{"id":385,"date":"2014-06-06T03:00:00","date_gmt":"2014-06-06T06:00:00","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/2014\/06\/06\/ministro-visita-passo-fundo-e-prefeito-pede-investimentos-na-cidade-8291\/"},"modified":"2014-06-06T03:00:00","modified_gmt":"2014-06-06T06:00:00","slug":"ministro-visita-passo-fundo-e-prefeito-pede-investimentos-na-cidade-8291","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/2014\/06\/06\/ministro-visita-passo-fundo-e-prefeito-pede-investimentos-na-cidade-8291\/","title":{"rendered":"Ministro visita Passo Fundo e Prefeito pede investimentos na cidade"},"content":{"rendered":"<div align=\"justify\">A cidade de Passo Fundo recebeu nessa sexta-feira (6), a visita do Ministro da Agricultura, Pecu\u00e1ria e Abastecimento, Neri Gheller.  <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm; font-weight: normal;\">Em encontro realizado na sede da Embrapa, o prefeito Luciano Azevedo solicitou ao ministro aten\u00e7\u00e3o ao projeto da Escola do Leite, que est\u00e1 em Bras\u00edlia sendo analisado. \u201cQueremos que examine com carinho este projeto que \u00e9 fundamental para nosso munic\u00edpio e regi\u00e3o\u201d, disse Luciano. O prefeito ainda fez o pedido para que o governo federal fa\u00e7a mais investimentos na unidade da Embrapa em Passo Fundo. Luciano destacou a import\u00e2ncia da institui\u00e7\u00e3o para o desenvolvimento regional.<\/p>\n<div align=\"justify\">  <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm; font-weight: normal;\">O Ministro Neri Gheller, disse em seu discurso, que \u00e9 a inten\u00e7\u00e3o \u00e9 fortalecer o trabalho da Unidade. \u201cQueremos evoluir na qualidade do trigo, por que temos um grande potencial, e aqui nesta unidade, as coisas est\u00e3o acontecendo gra\u00e7as ao trabalho da EMBRAPA\u201d, falou.<\/p>\n<div align=\"justify\">  <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\"><b>Escola do Leite<\/b><\/p>\n<div align=\"justify\">A Prefeitura de Passo Fundo busca investimentos para a cria\u00e7\u00e3o da Escola do Leite, com aten\u00e7\u00e3o desde a cadeia produtiva at\u00e9 a \u00e1rea industrial. \u201c70% do que \u00e9 produzido est\u00e1 na regi\u00e3o, estamos na vanguarda\u201d, disse o secret\u00e1rio Extraordin\u00e1rio de Capta\u00e7\u00e3o de Recursos e Projetos Especiais, Edison Nunes. A Escola do Leite ser\u00e1 uma estrutura com objetivo de fazer rela\u00e7\u00e3o entre a ci\u00eancia e tecnologia do produto, com cursos e semin\u00e1rios para os produtores. <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm; font-weight: normal;\"> <\/p>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\"> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ministro visita Passo Fundo e Prefeito pede investimentos na cidade<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ministro visita Passo Fundo e Prefeito pede investimentos na cidade - Secretaria do Gabinete<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/2014\/06\/06\/ministro-visita-passo-fundo-e-prefeito-pede-investimentos-na-cidade-8291\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ministro visita Passo Fundo e Prefeito pede investimentos na cidade - Secretaria do Gabinete\" \/>\n<meta property=\"og:description\" content=\"Ministro visita Passo Fundo e Prefeito pede investimentos na cidade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/2014\/06\/06\/ministro-visita-passo-fundo-e-prefeito-pede-investimentos-na-cidade-8291\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria do Gabinete\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-06T06:00:00+00:00\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/2014\/06\/06\/ministro-visita-passo-fundo-e-prefeito-pede-investimentos-na-cidade-8291\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/2014\/06\/06\/ministro-visita-passo-fundo-e-prefeito-pede-investimentos-na-cidade-8291\/\",\"name\":\"Ministro visita Passo Fundo e Prefeito pede investimentos na cidade - Secretaria do Gabinete\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/#website\"},\"datePublished\":\"2014-06-06T06:00:00+00:00\",\"dateModified\":\"2014-06-06T06:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/2014\/06\/06\/ministro-visita-passo-fundo-e-prefeito-pede-investimentos-na-cidade-8291\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/\",\"name\":\"Secretaria do Gabinete\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ministro visita Passo Fundo e Prefeito pede investimentos na cidade - Secretaria do Gabinete","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/2014\/06\/06\/ministro-visita-passo-fundo-e-prefeito-pede-investimentos-na-cidade-8291\/","og_locale":"pt_BR","og_type":"article","og_title":"Ministro visita Passo Fundo e Prefeito pede investimentos na cidade - Secretaria do Gabinete","og_description":"Ministro visita Passo Fundo e Prefeito pede investimentos na cidade","og_url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/2014\/06\/06\/ministro-visita-passo-fundo-e-prefeito-pede-investimentos-na-cidade-8291\/","og_site_name":"Secretaria do Gabinete","article_published_time":"2014-06-06T06:00:00+00:00","author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/2014\/06\/06\/ministro-visita-passo-fundo-e-prefeito-pede-investimentos-na-cidade-8291\/","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/2014\/06\/06\/ministro-visita-passo-fundo-e-prefeito-pede-investimentos-na-cidade-8291\/","name":"Ministro visita Passo Fundo e Prefeito pede investimentos na cidade - Secretaria do Gabinete","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/#website"},"datePublished":"2014-06-06T06:00:00+00:00","dateModified":"2014-06-06T06:00:00+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/2014\/06\/06\/ministro-visita-passo-fundo-e-prefeito-pede-investimentos-na-cidade-8291\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/","name":"Secretaria do Gabinete","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/wp-json\/wp\/v2\/posts\/385"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/wp-json\/wp\/v2\/comments?post=385"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/wp-json\/wp\/v2\/posts\/385\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/wp-json\/wp\/v2\/media?parent=385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/wp-json\/wp\/v2\/categories?post=385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-do-gabinete\/wp-json\/wp\/v2\/tags?post=385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}