{"id":3227,"date":"2022-07-21T16:37:35","date_gmt":"2022-07-21T19:37:35","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/?p=3227"},"modified":"2022-07-22T08:53:31","modified_gmt":"2022-07-22T11:53:31","slug":"passo-fundo-inicia-a-vacinacao-de-criancas-de-3-a-4-anos-contra-a-covid-19","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/07\/21\/passo-fundo-inicia-a-vacinacao-de-criancas-de-3-a-4-anos-contra-a-covid-19\/","title":{"rendered":"Passo Fundo inicia a vacina\u00e7\u00e3o de crian\u00e7as de 3 a 4 anos contra a Covid-19"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>Nesta quinta-feira (21), Passo Fundo iniciou a vacina\u00e7\u00e3o contra a Covid-19 das crian\u00e7as de 3 a 4 anos. De segunda a sexta-feira, os pais ou respons\u00e1veis poder\u00e3o buscar uma das 17 unidades de sa\u00fade vacinadoras.<\/p>\n\n\n\n<p>A amplia\u00e7\u00e3o da faixa et\u00e1ria observa a Nota T\u00e9cnica 213\/2022 do Minist\u00e9rio da Sa\u00fade, que recomenda a vacina\u00e7\u00e3o deste p\u00fablico com a Coronavac ao considerar a seguran\u00e7a e efic\u00e1cia do imunizante. A pasta tamb\u00e9m indica que os estados e os munic\u00edpios organizem a vacina\u00e7\u00e3o de acordo com as doses dispon\u00edveis.<\/p>\n\n\n\n<p>Em Passo Fundo, conforme a coordenadora de Vigil\u00e2ncia em Sa\u00fade, Marisa Zanatta, as aplica\u00e7\u00f5es ser\u00e3o feitas em todas as crian\u00e7as com mais de 3 anos enquanto houver doses dispon\u00edveis nas unidades. \u201cA orienta\u00e7\u00e3o do Minist\u00e9rio da Sa\u00fade \u00e9 que os estados e munic\u00edpios priorizem o p\u00fablico imunocomprometido, mas temos estoque significativo para vacinar as crian\u00e7as desta faixa et\u00e1ria, trazendo mais prote\u00e7\u00e3o para as que frequentam ber\u00e7\u00e1rios, escolas e demais espa\u00e7os\u201d, afirma, informando que o munic\u00edpio possui cerca de 5,3 mil crian\u00e7as de 3 a 4 anos.<\/p>\n\n\n\n<p>Outra mudan\u00e7a na vacina\u00e7\u00e3o \u00e9 que as crian\u00e7as n\u00e3o precisam ter mais o intervalo de 15 dias entre vacinas. &#8220;Assim como a popula\u00e7\u00e3o adulta, elas podem receber o imunizante contra a Covid-19 simultaneamente aos de rotina&#8221;, destaca Marisa.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Confira como fica a vacina\u00e7\u00e3o:<\/strong><\/p>\n\n\n\n<p><strong>P\u00fablicos<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>1\u00aa dose para crian\u00e7as de 3 a 11 anos (enquanto houver doses)<\/li><li>1\u00aa dose para pessoas acima de 12 anos, gestantes e pu\u00e9rperas<\/li><li>2\u00aa dose de Coronavac para todas as crian\u00e7as que precisam completar o esquema vacinal (intervalo \u00e9 de 28 dias)<\/li><li>2\u00aa dose de Coronavac para todas as pessoas que precisam completar o esquema vacinal (intervalo \u00e9 de 28 dias)<\/li><li>2\u00aa dose de Pfizer para as pessoas com 18 anos ou mais que precisam completar o esquema vacinal (intervalo \u00e9 de oito semanas)<\/li><li>2\u00aa dose de Pfizer para adolescentes que precisam completar o esquema vacinal (intervalo \u00e9 de oito semanas) (*enquanto houver doses)<\/li><li>2\u00aa dose de AstraZeneca para todas as pessoas que precisam completar o esquema vacinal (intervalo \u00e9 de oito semanas)<\/li><li>3\u00aa dose (refor\u00e7o) para todas as pessoas com 18 anos ou mais que receberam a segunda dose h\u00e1, no m\u00ednimo, quatro meses<\/li><li>3\u00aa dose (refor\u00e7o para os adolescentes de 12 a 17 anos que receberam a segunda dose h\u00e1, no m\u00ednimo, quatro meses<\/li><li>2\u00aa dose de refor\u00e7o para pessoas com 40 anos ou mais que fizeram o primeiro refor\u00e7o h\u00e1 quatro meses ou mais<\/li><li>2\u00aa dose de refor\u00e7o para profissionais e estudantes da \u00e1rea da sa\u00fade com mais de 18 anos que fizeram o primeiro refor\u00e7o h\u00e1 quatro meses ou mais<\/li><\/ul>\n\n\n\n<p>Cais Vila Lu\u00edza, Cais H\u00edpica, Cais Boqueir\u00e3o, Ambulat\u00f3rio de Especialidades, ESF Nen\u00ea Graeff, ESF Zachia, Ambulat\u00f3rio S\u00e3o Jos\u00e9, ESF Don\u00e1ria\/Santa Marta, ESF S\u00e3o Luiz Gonzaga, ESF Adirbal Corralo, ESF Planaltina, ESF S\u00e3o Crist\u00f3v\u00e3o, ESF Adolfo Groth, ESF Jaboticabal, UBS Vila Nova, UBS Parque Farroupilha e Central de Vacinas.<\/p>\n\n\n\n<p>ESF, UBS e ambulat\u00f3rios: das 8h \u00e0s 11h30 e das 13h \u00e0s 16h<br>Cais e Central de Vacinas: das 8h \u00e0s 16h<\/p>\n\n\n\n<p><strong>Exclusivo para quem fez a vacina Janssen<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Refor\u00e7o para todas as pessoas com 18 anos ou mais que fizeram a vacina Janssen no esquema prim\u00e1rio (dose \u00fanica) h\u00e1, no m\u00ednimo, dois meses<\/li><li>2\u00aa dose de refor\u00e7o para pessoas com 18 anos a 39 anos (n\u00e3o gestantes e pu\u00e9rperas) que fizeram a vacina Janssen no esquema prim\u00e1rio (dose \u00fanica), independente do imunizante utilizado no primeiro refor\u00e7o<\/li><li>3\u00aa dose de refor\u00e7o para pessoas com 40 anos ou mais (n\u00e3o gestantes e pu\u00e9rperas) que fizeram a vacina Janssen no esquema prim\u00e1rio (dose \u00fanica), independente do imunizante utilizado nos refor\u00e7os anteriores.<\/li><\/ul>\n\n\n\n<p>Cais Vila Lu\u00edza, Cais H\u00edpica, Cais Boqueir\u00e3o, Ambulat\u00f3rio de Especialidades, ESF Nen\u00ea Graeff, ESF Zachia, Ambulat\u00f3rio S\u00e3o Jos\u00e9, ESF Don\u00e1ria\/Santa Marta, ESF S\u00e3o Luiz Gonzaga, ESF Adirbal Corralo, ESF Planaltina, ESF S\u00e3o Crist\u00f3v\u00e3o, ESF Adolfo Groth, ESF Jaboticabal, UBS Vila Nova, UBS Parque Farroupilha e Central de Vacinas.<\/p>\n\n\n\n<p>ESF, UBS e ambulat\u00f3rios: das 8h \u00e0s 11h30 e das 13h \u00e0s 16h<br>Cais e Central de Vacinas: das 8h \u00e0s 16h<\/p>\n\n\n\n<p><strong>Outros p\u00fablicos<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Dose adicional para adolescentes de 12 a 17 anos imunocomprometidos (intervalo m\u00ednimo de oito semanas da segunda dose)<\/li><li>3\u00aa dose para imunossuprimidos<\/li><\/ul>\n\n\n\n<p>Somente na Central de Vacinas, das 8h \u00e0s 16h<br>*Enquanto houver doses<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>2\u00aa dose de Pfizer para todas as crian\u00e7as que precisam completar o esquema vacinal (intervalo \u00e9 de oito semanas)<\/li><\/ul>\n\n\n\n<p>Na Central de Vacinas, mediante agendamento<br>Telefone para agendamento: 54 3046-0153<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aplica\u00e7\u00f5es s\u00e3o feitas em 17 unidades de sa\u00fade. N\u00e3o \u00e9 necess\u00e1rio ter intervalo entre o imunizante contra a Covid-19 e os de rotina<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[],"class_list":["post-3227","post","type-post","status-publish","format-standard","hentry","category-vacinacao-covid-19"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Passo Fundo inicia a vacina\u00e7\u00e3o de crian\u00e7as de 3 a 4 anos contra a Covid-19 - Secretaria de Sa\u00fade<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/07\/21\/passo-fundo-inicia-a-vacinacao-de-criancas-de-3-a-4-anos-contra-a-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Passo Fundo inicia a vacina\u00e7\u00e3o de crian\u00e7as de 3 a 4 anos contra a Covid-19 - Secretaria de Sa\u00fade\" \/>\n<meta property=\"og:description\" content=\"Aplica\u00e7\u00f5es s\u00e3o feitas em 17 unidades de sa\u00fade. N\u00e3o \u00e9 necess\u00e1rio ter intervalo entre o imunizante contra a Covid-19 e os de rotina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/07\/21\/passo-fundo-inicia-a-vacinacao-de-criancas-de-3-a-4-anos-contra-a-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Sa\u00fade\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-21T19:37:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-22T11:53:31+00:00\" \/>\n<meta name=\"author\" content=\"andressazorzetto07\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"andressazorzetto07\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/07\/21\/passo-fundo-inicia-a-vacinacao-de-criancas-de-3-a-4-anos-contra-a-covid-19\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/07\/21\/passo-fundo-inicia-a-vacinacao-de-criancas-de-3-a-4-anos-contra-a-covid-19\/\",\"name\":\"Passo Fundo inicia a vacina\u00e7\u00e3o de crian\u00e7as de 3 a 4 anos contra a Covid-19 - Secretaria de Sa\u00fade\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#website\"},\"datePublished\":\"2022-07-21T19:37:35+00:00\",\"dateModified\":\"2022-07-22T11:53:31+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#\/schema\/person\/30ee1d1bd74da1469b01fcf086e43351\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/07\/21\/passo-fundo-inicia-a-vacinacao-de-criancas-de-3-a-4-anos-contra-a-covid-19\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/07\/21\/passo-fundo-inicia-a-vacinacao-de-criancas-de-3-a-4-anos-contra-a-covid-19\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/07\/21\/passo-fundo-inicia-a-vacinacao-de-criancas-de-3-a-4-anos-contra-a-covid-19\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Passo Fundo inicia a vacina\u00e7\u00e3o de crian\u00e7as de 3 a 4 anos contra a Covid-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/\",\"name\":\"Secretaria de Sa\u00fade\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#\/schema\/person\/30ee1d1bd74da1469b01fcf086e43351\",\"name\":\"andressazorzetto07\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/14c5458ed79dc81da99a13b9ff5f9f19?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/14c5458ed79dc81da99a13b9ff5f9f19?s=96&d=mm&r=g\",\"caption\":\"andressazorzetto07\"},\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/author\/andressazorzetto07\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Passo Fundo inicia a vacina\u00e7\u00e3o de crian\u00e7as de 3 a 4 anos contra a Covid-19 - Secretaria de Sa\u00fade","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/07\/21\/passo-fundo-inicia-a-vacinacao-de-criancas-de-3-a-4-anos-contra-a-covid-19\/","og_locale":"pt_BR","og_type":"article","og_title":"Passo Fundo inicia a vacina\u00e7\u00e3o de crian\u00e7as de 3 a 4 anos contra a Covid-19 - Secretaria de Sa\u00fade","og_description":"Aplica\u00e7\u00f5es s\u00e3o feitas em 17 unidades de sa\u00fade. N\u00e3o \u00e9 necess\u00e1rio ter intervalo entre o imunizante contra a Covid-19 e os de rotina","og_url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/07\/21\/passo-fundo-inicia-a-vacinacao-de-criancas-de-3-a-4-anos-contra-a-covid-19\/","og_site_name":"Secretaria de Sa\u00fade","article_published_time":"2022-07-21T19:37:35+00:00","article_modified_time":"2022-07-22T11:53:31+00:00","author":"andressazorzetto07","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"andressazorzetto07","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/07\/21\/passo-fundo-inicia-a-vacinacao-de-criancas-de-3-a-4-anos-contra-a-covid-19\/","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/07\/21\/passo-fundo-inicia-a-vacinacao-de-criancas-de-3-a-4-anos-contra-a-covid-19\/","name":"Passo Fundo inicia a vacina\u00e7\u00e3o de crian\u00e7as de 3 a 4 anos contra a Covid-19 - Secretaria de Sa\u00fade","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#website"},"datePublished":"2022-07-21T19:37:35+00:00","dateModified":"2022-07-22T11:53:31+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#\/schema\/person\/30ee1d1bd74da1469b01fcf086e43351"},"breadcrumb":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/07\/21\/passo-fundo-inicia-a-vacinacao-de-criancas-de-3-a-4-anos-contra-a-covid-19\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/07\/21\/passo-fundo-inicia-a-vacinacao-de-criancas-de-3-a-4-anos-contra-a-covid-19\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/07\/21\/passo-fundo-inicia-a-vacinacao-de-criancas-de-3-a-4-anos-contra-a-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/"},{"@type":"ListItem","position":2,"name":"Passo Fundo inicia a vacina\u00e7\u00e3o de crian\u00e7as de 3 a 4 anos contra a Covid-19"}]},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/","name":"Secretaria de Sa\u00fade","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#\/schema\/person\/30ee1d1bd74da1469b01fcf086e43351","name":"andressazorzetto07","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/14c5458ed79dc81da99a13b9ff5f9f19?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14c5458ed79dc81da99a13b9ff5f9f19?s=96&d=mm&r=g","caption":"andressazorzetto07"},"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/author\/andressazorzetto07\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/posts\/3227"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/comments?post=3227"}],"version-history":[{"count":3,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/posts\/3227\/revisions"}],"predecessor-version":[{"id":3231,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/posts\/3227\/revisions\/3231"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/media?parent=3227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/categories?post=3227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/tags?post=3227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}