{"id":3157,"date":"2022-05-16T16:44:38","date_gmt":"2022-05-16T19:44:38","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/?p=3157"},"modified":"2022-05-16T16:44:38","modified_gmt":"2022-05-16T19:44:38","slug":"olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/","title":{"rendered":"Olhar de Crian\u00e7a: Prefeitura promove consultas, exames oftalmol\u00f3gicos e \u00f3culos gratuitos a crian\u00e7as"},"content":{"rendered":"\n<p><br>Ver bem para aprender melhor: foi pensando nisso que a Prefeitura de Passo Fundo criou o programa Olhar de Crian\u00e7a. A iniciativa promove a acuidade visual para os alunos das escolas municipais de educa\u00e7\u00e3o por meio de avalia\u00e7\u00f5es, testes e, se necess\u00e1rio, o fornecimento de \u00f3culos sem nenhum custo \u00e0s fam\u00edlias.<\/p>\n\n\n\n<p>No \u00faltimo s\u00e1bado (14), crian\u00e7as da EMEI Maria Elizabeth, que abrange a regi\u00e3o do Bairro S\u00e3o Crist\u00f3v\u00e3o, passaram por uma consulta no Hospital de Olhos, conveniado com o Munic\u00edpio para os procedimentos. Conforme a secret\u00e1ria de Sa\u00fade, Cristine Pilati, todas essas crian\u00e7as j\u00e1 passaram por um teste de vis\u00e3o na pr\u00f3pria escola, que evidenciou dificuldades, e vieram para a consulta a fim de realizar exames mais espec\u00edficos. \u201cEm 2021, o teste de acuidade visual foi aplicado em 135 crian\u00e7as da EMEI Maria Elizabeth. Desse total, 41 t\u00eam indica\u00e7\u00e3o para a consulta oftalmol\u00f3gica. Organizamos um cronograma de atendimentos com o Hospital de Olhos e come\u00e7amos a levar essas crian\u00e7as e os seus respons\u00e1veis para a consulta. Al\u00e9m de promover as consultas, a Prefeitura d\u00e1 o transporte a essas fam\u00edlias para facilitar os servi\u00e7os\u201d, pontua.<\/p>\n\n\n\n<p>O programa funciona em tr\u00eas diferentes etapas: na primeira, as crian\u00e7as fazem um teste de vis\u00e3o nas escolas; caso seja detectado algum problema, um novo teste \u00e9 feito no Hospital de Olhos; as crian\u00e7as com indica\u00e7\u00e3o de \u00f3culos recebem um encaminhamento para escolha da arma\u00e7\u00e3o e, posteriormente, os \u00f3culos s\u00e3o entregues nas institui\u00e7\u00f5es.<\/p>\n\n\n\n<p>As avalia\u00e7\u00f5es acontecem com os alunos na faixa dos tr\u00eas aos seis anos de idade. Al\u00e9m de um primeiro atendimento, aqueles que precisam de tratamento seguem em acompanhamento por mais tempo. No ano passado, foram realizados 1,5 mil testes, com a indica\u00e7\u00e3o de que 500 crian\u00e7as sejam atendidas no Hospital de Olhos. O fluxo de consultas est\u00e1 sendo estruturado pela Prefeitura e pela institui\u00e7\u00e3o e ser\u00e1 informado pelas escolas aos respons\u00e1veis.<\/p>\n\n\n\n<p>O Guilherme, de seis anos, \u00e9 um dos alunos da EMEI Maria Elizabeth que foram at\u00e9 o Hospital de Olhos no s\u00e1bado. Ele recebeu o teste de acuidade visual da escola, o qual evidenciou a necessidade do uso de \u00f3culos. A m\u00e3e, Suzana Colussi, comenta que a iniciativa foi muito importante para a fam\u00edlia. \u201c\u00c0s vezes, os pais percebem. \u00c0s vezes, n\u00e3o, que foi o nosso caso. Com a pandemia, o Guilherme quase n\u00e3o foi para a escolinha. Ele nunca chegou e disse que n\u00e3o estava enxergando bem. Para n\u00f3s, foi uma surpresa\u201d, conta.<\/p>\n\n\n\n<p>Utilizando \u00f3culos desde fevereiro, Guilherme se acostumou rapidamente a realizar todas as suas atividades do dia com ele. \u201cEle mesmo sente que faz a diferen\u00e7a. Ele se acostumou muito bem e procura usar o \u00f3culos. S\u00f3 tira para brincar, para correr\u201d, relata a m\u00e3e.<\/p>\n\n\n\n<p><strong>Sons do Mundo<br><\/strong>Foi com a mesma perspectiva do Olhar de Crian\u00e7a que a Prefeitura criou, em abril deste ano, o programa Sons do Mundo, que busca identificar crian\u00e7as com defici\u00eancias auditivas na rede municipal e assegurar que recebam o acompanhamento necess\u00e1rio. O p\u00fablico-alvo s\u00e3o as crian\u00e7as de 3 a 8 anos que estudam na rede municipal.<\/p>\n\n\n\n<p>O prefeito Pedro Almeida enfatizou que problemas auditivos e visuais est\u00e3o entre os motivos que podem dificultar o processo de aprendizagem dos alunos. Ele lembrou que o Munic\u00edpio j\u00e1 possui o programa Olhar de Crian\u00e7a, que fornece gratuitamente \u00f3culos para as crian\u00e7as que precisam, ap\u00f3s triagens nas escolas e consultas oftalmol\u00f3gicas. \u201cEstamos dando mais um passo para enfrentar esses fatores que podem prejudicar o desempenho dos alunos em sala de aula. Temos certeza de que o programa Sons do Mundo far\u00e1 a diferen\u00e7a na vida de muitas crian\u00e7as\u201d, afirmou Pedro.<br>Conforme explica a secret\u00e1ria de Sa\u00fade, Cristine Pilati, \u201co programa Sons do Mundo tem o objetivo de preencher a lacuna que possa existir entre crian\u00e7as que realizaram o Teste da Orelhinha quando nasceram e crian\u00e7as que est\u00e3o em idade escolar e que, por algum motivo, possam ter desenvolvido d\u00e9ficit auditivo\u201d.<\/p>\n\n\n\n<p>Os alunos ser\u00e3o triados nas escolas por uma fonoaudi\u00f3loga, com avalia\u00e7\u00e3o cl\u00ednica, otoscopia e aplica\u00e7\u00e3o do teste de emiss\u00f5es otoac\u00fasticas. Em caso de detec\u00e7\u00e3o de altera\u00e7\u00f5es, a crian\u00e7a ser\u00e1 encaminhada para atendimento especializado e realiza\u00e7\u00e3o de audiometria convencional. O programa est\u00e1 recebendo os \u00faltimos ajustes para que entre em funcionamento.<\/p>\n\n\n\n<p><strong>Fotos: Michel Sanderi<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ver bem para aprender melhor: foi pensando nisso que a Prefeitura de Passo Fundo criou o programa Olhar de Crian\u00e7a. A iniciativa promove a acuidade visual para os alunos das escolas municipais [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":3158,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22,23],"tags":[],"class_list":["post-3157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-olhar-de-crianca","category-sons-do-mundo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Olhar de Crian\u00e7a: Prefeitura promove consultas, exames oftalmol\u00f3gicos e \u00f3culos gratuitos a crian\u00e7as - Secretaria de Sa\u00fade<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Olhar de Crian\u00e7a: Prefeitura promove consultas, exames oftalmol\u00f3gicos e \u00f3culos gratuitos a crian\u00e7as - Secretaria de Sa\u00fade\" \/>\n<meta property=\"og:description\" content=\"Ver bem para aprender melhor: foi pensando nisso que a Prefeitura de Passo Fundo criou o programa Olhar de Crian\u00e7a. A iniciativa promove a acuidade visual para os alunos das escolas municipais [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Sa\u00fade\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-16T19:44:38+00:00\" \/>\n<meta name=\"author\" content=\"andressazorzetto07\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"andressazorzetto07\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/\",\"name\":\"Olhar de Crian\u00e7a: Prefeitura promove consultas, exames oftalmol\u00f3gicos e \u00f3culos gratuitos a crian\u00e7as - Secretaria de Sa\u00fade\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-content\/uploads\/sites\/50\/2022\/05\/olhar-de-crianca.jpg\",\"datePublished\":\"2022-05-16T19:44:38+00:00\",\"dateModified\":\"2022-05-16T19:44:38+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#\/schema\/person\/30ee1d1bd74da1469b01fcf086e43351\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-content\/uploads\/sites\/50\/2022\/05\/olhar-de-crianca.jpg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-content\/uploads\/sites\/50\/2022\/05\/olhar-de-crianca.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Olhar de Crian\u00e7a: Prefeitura promove consultas, exames oftalmol\u00f3gicos e \u00f3culos gratuitos a crian\u00e7as\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/\",\"name\":\"Secretaria de Sa\u00fade\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#\/schema\/person\/30ee1d1bd74da1469b01fcf086e43351\",\"name\":\"andressazorzetto07\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/14c5458ed79dc81da99a13b9ff5f9f19?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/14c5458ed79dc81da99a13b9ff5f9f19?s=96&d=mm&r=g\",\"caption\":\"andressazorzetto07\"},\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/author\/andressazorzetto07\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Olhar de Crian\u00e7a: Prefeitura promove consultas, exames oftalmol\u00f3gicos e \u00f3culos gratuitos a crian\u00e7as - Secretaria de Sa\u00fade","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/","og_locale":"pt_BR","og_type":"article","og_title":"Olhar de Crian\u00e7a: Prefeitura promove consultas, exames oftalmol\u00f3gicos e \u00f3culos gratuitos a crian\u00e7as - Secretaria de Sa\u00fade","og_description":"Ver bem para aprender melhor: foi pensando nisso que a Prefeitura de Passo Fundo criou o programa Olhar de Crian\u00e7a. A iniciativa promove a acuidade visual para os alunos das escolas municipais [&hellip;]","og_url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/","og_site_name":"Secretaria de Sa\u00fade","article_published_time":"2022-05-16T19:44:38+00:00","author":"andressazorzetto07","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"andressazorzetto07","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/","name":"Olhar de Crian\u00e7a: Prefeitura promove consultas, exames oftalmol\u00f3gicos e \u00f3culos gratuitos a crian\u00e7as - Secretaria de Sa\u00fade","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-content\/uploads\/sites\/50\/2022\/05\/olhar-de-crianca.jpg","datePublished":"2022-05-16T19:44:38+00:00","dateModified":"2022-05-16T19:44:38+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#\/schema\/person\/30ee1d1bd74da1469b01fcf086e43351"},"breadcrumb":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-content\/uploads\/sites\/50\/2022\/05\/olhar-de-crianca.jpg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-content\/uploads\/sites\/50\/2022\/05\/olhar-de-crianca.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/2022\/05\/16\/olhar-de-crianca-prefeitura-promove-consultas-exames-oftalmologicos-e-oculos-gratuitos-a-criancas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/"},{"@type":"ListItem","position":2,"name":"Olhar de Crian\u00e7a: Prefeitura promove consultas, exames oftalmol\u00f3gicos e \u00f3culos gratuitos a crian\u00e7as"}]},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/","name":"Secretaria de Sa\u00fade","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#\/schema\/person\/30ee1d1bd74da1469b01fcf086e43351","name":"andressazorzetto07","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/14c5458ed79dc81da99a13b9ff5f9f19?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14c5458ed79dc81da99a13b9ff5f9f19?s=96&d=mm&r=g","caption":"andressazorzetto07"},"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/author\/andressazorzetto07\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/posts\/3157"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/comments?post=3157"}],"version-history":[{"count":1,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/posts\/3157\/revisions"}],"predecessor-version":[{"id":3159,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/posts\/3157\/revisions\/3159"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/media\/3158"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/media?parent=3157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/categories?post=3157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-saude\/wp-json\/wp\/v2\/tags?post=3157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}