{"id":2009,"date":"2023-05-23T10:05:14","date_gmt":"2023-05-23T13:05:14","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/?post_type=servicos&#038;p=2009"},"modified":"2025-06-25T10:04:48","modified_gmt":"2025-06-25T13:04:48","slug":"recebimento-infraestrutura","status":"publish","type":"servicos","link":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/servicos\/recebimento-infraestrutura\/","title":{"rendered":"Termo de verifica\u00e7\u00e3o e do recebimento dos servi\u00e7os e obras (infraestrutura)"},"content":{"rendered":"\n<div class=\"wp-block-columns has-grey-background-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Os termos de verifica\u00e7\u00e3o e recebimento de infraestrutura para loteamentos ou condom\u00ednios  ser\u00e1 feito atrav\u00e9s de decreto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O decreto do Termo de Verifica\u00e7\u00e3o dos servi\u00e7os e obras de infraestrutura do condom\u00ednio urban\u00edstico ser\u00e1 precedido de requerimento eletr\u00f4nico e ser\u00e1 expedido somente ap\u00f3s a emiss\u00e3o dos Termos de Verifica\u00e7\u00e3o de cada servi\u00e7o e obra de infraestrutura, conferida pelos \u00f3rg\u00e3os municipais competentes e ap\u00f3s a apresenta\u00e7\u00e3o dos Termos de Aceita\u00e7\u00e3o emitidos pelas concession\u00e1rias dos servi\u00e7os concedidos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Legisla\u00e7\u00e3o: <a href=\"https:\/\/leismunicipais.com.br\/a1\/codigo-de-obras-passo-fundo-rs\">Lei complementar 399 de 07\/11\/2016 (C\u00f3digo de Obras)<\/a>; <a href=\"https:\/\/leismunicipais.com.br\/a1\/parcelamento-do-solo-passo-fundo-rs\">Art. 50 e 113 da lei complementar n\u00ba 230 de 07\/10\/2009<\/a>; <a href=\"https:\/\/leismunicipais.com.br\/a1\/rs\/p\/passo-fundo\/lei-ordinaria\/2019\/539\/5388\/lei-ordinaria-n-5388-2019-dispoe-sobre-a-utilizacao-de-meios-eletronicos-para-a-tramitacao-dos-processos-administrativos-e-internos-no-mbito-da-administracao-publica-municipal-direta-autarquica-e-fundacional?q=5388%2F2019\">Lei Ordin\u00e1ria 5.388, de 09 de janeiro de 2019.<\/a><\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>Etapas para a realiza\u00e7\u00e3o deste servi\u00e7o<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Para acessar o servi\u00e7o eletr\u00f4nico, o requerente ou respons\u00e1vel t\u00e9cnico dever\u00e1 ter uma senha (credencial), certificado digital habilitado ou acesso ao GOV.BR. Caso n\u00e3o tenha, poder\u00e1 clicar em \u201cCriar Credencial\u201d na tela de autentica\u00e7\u00e3o ou&nbsp;<a href=\"https:\/\/grp.pmpf.rs.gov.br\/grp\/acessoexterno\/programaAcessoExterno.faces?codigo=670014\" target=\"_blank\" rel=\"noreferrer noopener\">clique aqui<\/a> para realizar o cadastro. Ap\u00f3s o cadastro, o requerente receber\u00e1 a credencial no seu e-mail.<\/li>\n\n\n\n<li>Para que um respons\u00e1vel t\u00e9cnico fa\u00e7a a solicita\u00e7\u00e3o em nome do requerente, dever\u00e1, antes da abertura do processo, realizar o cadastro da procura\u00e7\u00e3o, em que o requerente outorga poderes para abertura de processos em seu nome, via procura\u00e7\u00e3o eletr\u00f4nica, <a href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-administracao\/servicos\/cadastrar-procuracao-eletronica\/\">acesse aqui.<\/a><\/li>\n\n\n\n<li>O in\u00edcio do processo dar-se-\u00e1 a pedido da parte interessada, de forma online, pelo site de servi\u00e7os da prefeitura mediante cadastro de usu\u00e1rio, chave de acesso ou certificado digital.\n<ul class=\"wp-block-list\">\n<li><strong>Como solicitar<\/strong>: Clicar no bot\u00e3o <strong>&#8220;Acesso ao sistema&#8221;<\/strong>&nbsp;e informar sua senha, ap\u00f3s, selecionar o assunto RECEBIMENTO DE INFRAESTRUTURA e anexar os documentos conforme solicitado.<\/li>\n\n\n\n<li><strong><mark style=\"background-color:#fcb900\" class=\"has-inline-color has-red-color\">O requerente do processo deve ser o propriet\u00e1rio da obra.<\/mark><\/strong><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Na instaura\u00e7\u00e3o do processo, o requerente receber\u00e1 em seu e-mail o n\u00famero do protocolo para acompanhamento do processo.\n<ul class=\"wp-block-list\">\n<li><strong>Como acompanhar<\/strong>:  Clicar no bot\u00e3o <strong>&#8220;Acompanhar solicita\u00e7\u00e3o&#8221;<\/strong>&nbsp;e informar sua senha. No programa Meus Processos, informar o exerc\u00edcio do processo e clicar no bot\u00e3o recuperar. Clicar sobre o processo desejado e verificar as informa\u00e7\u00f5es da aba hist\u00f3rico de tramita\u00e7\u00f5es. Os documentos e\/ou licen\u00e7as emitidas poder\u00e3o ser visualizados na aba anexos, se assinados.<\/li>\n<\/ul>\n<\/li>\n<\/ol>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong><strong>Documentos Necess\u00e1rios<\/strong><\/strong><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<ol class=\"wp-block-list\">\n<li>*Termo de aceita\u00e7\u00e3o da concession\u00e1ria de \u00e1gua e esgoto<\/li>\n\n\n\n<li>*Termo de aceita\u00e7\u00e3o da concession\u00e1ria de energia el\u00e9trica<\/li>\n\n\n\n<li>Licen\u00e7a ambiental<\/li>\n\n\n\n<li>Termo de recebimento relativo ao RIV, se for o caso<\/li>\n<\/ol>\n\n\n\n<p class=\"has-grey-background-color has-background wp-block-paragraph\">Os documentos marcados com * s\u00e3o obrigat\u00f3rios para a abertura do processo. Em caso de d\u00favidas, envie um e-mail para smo@pmpf.rs.gov.br.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n<\/div><\/div>\n","protected":false},"featured_media":0,"template":"","canal":[2],"quem":[3,9],"servico_tags":[31,17,6],"class_list":["post-2009","servicos","type-servicos","status-publish","hentry","canal-online","quem-cidadao","quem-empresa","servico_tags-aprovacao-e-licenciamento-de-obras","servico_tags-autorizacoes-e-licencas","servico_tags-obra-facil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Termo de verifica\u00e7\u00e3o e do recebimento dos servi\u00e7os e obras (infraestrutura) - Secretaria de Obras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/servicos\/recebimento-infraestrutura\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Termo de verifica\u00e7\u00e3o e do recebimento dos servi\u00e7os e obras (infraestrutura) - Secretaria de Obras\" \/>\n<meta property=\"og:description\" content=\"Os termos de verifica\u00e7\u00e3o e recebimento de infraestrutura para loteamentos ou condom\u00ednios ser\u00e1 feito atrav\u00e9s de decreto. O decreto do Termo de Verifica\u00e7\u00e3o dos servi\u00e7os e obras de infraestrutura do condom\u00ednio urban\u00edstico [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/servicos\/recebimento-infraestrutura\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Obras\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-25T13:04:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pmpf.rs.gov.br\\\/secretaria-de-obras\\\/servicos\\\/recebimento-infraestrutura\\\/\",\"url\":\"https:\\\/\\\/www.pmpf.rs.gov.br\\\/secretaria-de-obras\\\/servicos\\\/recebimento-infraestrutura\\\/\",\"name\":\"Termo de verifica\u00e7\u00e3o e do recebimento dos servi\u00e7os e obras (infraestrutura) - Secretaria de Obras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pmpf.rs.gov.br\\\/secretaria-de-obras\\\/#website\"},\"datePublished\":\"2023-05-23T13:05:14+00:00\",\"dateModified\":\"2025-06-25T13:04:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pmpf.rs.gov.br\\\/secretaria-de-obras\\\/servicos\\\/recebimento-infraestrutura\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pmpf.rs.gov.br\\\/secretaria-de-obras\\\/servicos\\\/recebimento-infraestrutura\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pmpf.rs.gov.br\\\/secretaria-de-obras\\\/servicos\\\/recebimento-infraestrutura\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.pmpf.rs.gov.br\\\/secretaria-de-obras\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servi\u00e7os\",\"item\":\"https:\\\/\\\/www.pmpf.rs.gov.br\\\/secretaria-de-obras\\\/servicos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Termo de verifica\u00e7\u00e3o e do recebimento dos servi\u00e7os e obras (infraestrutura)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pmpf.rs.gov.br\\\/secretaria-de-obras\\\/#website\",\"url\":\"https:\\\/\\\/www.pmpf.rs.gov.br\\\/secretaria-de-obras\\\/\",\"name\":\"Secretaria de Obras\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pmpf.rs.gov.br\\\/secretaria-de-obras\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Termo de verifica\u00e7\u00e3o e do recebimento dos servi\u00e7os e obras (infraestrutura) - Secretaria de Obras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/servicos\/recebimento-infraestrutura\/","og_locale":"pt_BR","og_type":"article","og_title":"Termo de verifica\u00e7\u00e3o e do recebimento dos servi\u00e7os e obras (infraestrutura) - Secretaria de Obras","og_description":"Os termos de verifica\u00e7\u00e3o e recebimento de infraestrutura para loteamentos ou condom\u00ednios ser\u00e1 feito atrav\u00e9s de decreto. O decreto do Termo de Verifica\u00e7\u00e3o dos servi\u00e7os e obras de infraestrutura do condom\u00ednio urban\u00edstico [&hellip;]","og_url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/servicos\/recebimento-infraestrutura\/","og_site_name":"Secretaria de Obras","article_modified_time":"2025-06-25T13:04:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/servicos\/recebimento-infraestrutura\/","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/servicos\/recebimento-infraestrutura\/","name":"Termo de verifica\u00e7\u00e3o e do recebimento dos servi\u00e7os e obras (infraestrutura) - Secretaria de Obras","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#website"},"datePublished":"2023-05-23T13:05:14+00:00","dateModified":"2025-06-25T13:04:48+00:00","breadcrumb":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/servicos\/recebimento-infraestrutura\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/servicos\/recebimento-infraestrutura\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/servicos\/recebimento-infraestrutura\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/"},{"@type":"ListItem","position":2,"name":"Servi\u00e7os","item":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/servicos\/"},{"@type":"ListItem","position":3,"name":"Termo de verifica\u00e7\u00e3o e do recebimento dos servi\u00e7os e obras (infraestrutura)"}]},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/","name":"Secretaria de Obras","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/servicos\/2009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/servicos"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/types\/servicos"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/media?parent=2009"}],"wp:term":[{"taxonomy":"canal","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/canal?post=2009"},{"taxonomy":"quem","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/quem?post=2009"},{"taxonomy":"servico_tags","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/servico_tags?post=2009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}