{"id":2931,"date":"2026-05-13T15:47:16","date_gmt":"2026-05-13T18:47:16","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/?p=2931"},"modified":"2026-05-13T15:47:22","modified_gmt":"2026-05-13T18:47:22","slug":"prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/","title":{"rendered":"Prefeitura: Vila Uni\u00e3o vai ganhar 7 quadras de asfalto na Rua Lava P\u00e9s"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>A comunidade da Vila Uni\u00e3o come\u00e7a a ver mais uma antiga reivindica\u00e7\u00e3o sair do papel. A Prefeitura de Passo Fundo iniciar\u00e1 nessa quarta-feira(13), os trabalhos de prepara\u00e7\u00e3o da Rua Lava P\u00e9s para receber nova pavimenta\u00e7\u00e3o asf\u00e1ltica em sete quadras da via, no trecho entre as ruas Alferes Rodrigues e Livramento, no Boqueir\u00e3o.<\/p>\n\n\n\n<p>As melhorias fazem parte das a\u00e7\u00f5es do programa Bairro a Bairro, que ter\u00e1 uma tarde festiva de entrega das obras e servi\u00e7os no pr\u00f3ximo dia 23, reunindo moradores e lideran\u00e7as da comunidade.<\/p>\n\n\n\n<p>Nessa semana, as equipes de asfalto da SMO, finalizaram a obra de asfalto na rua Tenente Mendes no bairro Santa Maria II. A melhoria asf\u00e1ltica faz parte das a\u00e7\u00f5es do programa \u201cMinha Rua com Asfalto\u201d, que alcan\u00e7a 40% de execu\u00e7\u00e3o das obras de pavimenta\u00e7\u00e3o em diferentes regi\u00f5es do munic\u00edpio.<\/p>\n\n\n\n<p>De acordo com o secret\u00e1rio municipal de Obras, Rubens Astolfi, a etapa de melhorias no sistema de esgoto j\u00e1 foi realizada pela Corsan na semana passada, permitindo agora o avan\u00e7o da pavimenta\u00e7\u00e3o. \u201cTamb\u00e9m fizemos manuten\u00e7\u00e3o nas bocas de lobo e agora devemos iniciar a aplica\u00e7\u00e3o do asfalto at\u00e9 o final da semana. Todo o trabalho est\u00e1 sendo executado por equipes pr\u00f3prias do munic\u00edpio, garantindo mais agilidade e qualidade\u201d, destacou o secret\u00e1rio.<\/p>\n\n\n\n<p>Al\u00e9m do novo asfalto, equipes da SMO seguem atuando na Vila Uni\u00e3o com servi\u00e7os de limpeza e manuten\u00e7\u00e3o de bocas de lobo, revis\u00e3o de canaliza\u00e7\u00f5es e opera\u00e7\u00e3o tapa-buracos em outras ruas do bairro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Moradores j\u00e1 acompanham prepara\u00e7\u00e3o da via para receber o in\u00edcio da pavimenta\u00e7\u00e3o<\/p>\n","protected":false},"author":24,"featured_media":2932,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prefeitura: Vila Uni\u00e3o vai ganhar 7 quadras de asfalto na Rua Lava P\u00e9s - Secretaria de Obras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeitura: Vila Uni\u00e3o vai ganhar 7 quadras de asfalto na Rua Lava P\u00e9s - Secretaria de Obras\" \/>\n<meta property=\"og:description\" content=\"Moradores j\u00e1 acompanham prepara\u00e7\u00e3o da via para receber o in\u00edcio da pavimenta\u00e7\u00e3o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Obras\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-13T18:47:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T18:47:22+00:00\" \/>\n<meta name=\"author\" content=\"lilicrivello\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lilicrivello\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/\",\"name\":\"Prefeitura: Vila Uni\u00e3o vai ganhar 7 quadras de asfalto na Rua Lava P\u00e9s - Secretaria de Obras\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-content\/uploads\/sites\/49\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.35.15.jpeg\",\"datePublished\":\"2026-05-13T18:47:16+00:00\",\"dateModified\":\"2026-05-13T18:47:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#\/schema\/person\/6e93b0ab2174b69f691ac4f278ba2d0a\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-content\/uploads\/sites\/49\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.35.15.jpeg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-content\/uploads\/sites\/49\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.35.15.jpeg\",\"width\":1600,\"height\":1067},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prefeitura: Vila Uni\u00e3o vai ganhar 7 quadras de asfalto na Rua Lava P\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/\",\"name\":\"Secretaria de Obras\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#\/schema\/person\/6e93b0ab2174b69f691ac4f278ba2d0a\",\"name\":\"lilicrivello\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0b546b667388f8edb7b67d70a57b5e46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0b546b667388f8edb7b67d70a57b5e46?s=96&d=mm&r=g\",\"caption\":\"lilicrivello\"},\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/author\/lilicrivello\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeitura: Vila Uni\u00e3o vai ganhar 7 quadras de asfalto na Rua Lava P\u00e9s - Secretaria de Obras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeitura: Vila Uni\u00e3o vai ganhar 7 quadras de asfalto na Rua Lava P\u00e9s - Secretaria de Obras","og_description":"Moradores j\u00e1 acompanham prepara\u00e7\u00e3o da via para receber o in\u00edcio da pavimenta\u00e7\u00e3o","og_url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/","og_site_name":"Secretaria de Obras","article_published_time":"2026-05-13T18:47:16+00:00","article_modified_time":"2026-05-13T18:47:22+00:00","author":"lilicrivello","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"lilicrivello","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/","name":"Prefeitura: Vila Uni\u00e3o vai ganhar 7 quadras de asfalto na Rua Lava P\u00e9s - Secretaria de Obras","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-content\/uploads\/sites\/49\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.35.15.jpeg","datePublished":"2026-05-13T18:47:16+00:00","dateModified":"2026-05-13T18:47:22+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#\/schema\/person\/6e93b0ab2174b69f691ac4f278ba2d0a"},"breadcrumb":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-content\/uploads\/sites\/49\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.35.15.jpeg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-content\/uploads\/sites\/49\/2026\/05\/WhatsApp-Image-2026-05-13-at-11.35.15.jpeg","width":1600,"height":1067},{"@type":"BreadcrumbList","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2026\/05\/13\/prefeitura-vila-uniao-vai-ganhar-7-quadras-de-asfalto-na-rua-lava-pes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/"},{"@type":"ListItem","position":2,"name":"Prefeitura: Vila Uni\u00e3o vai ganhar 7 quadras de asfalto na Rua Lava P\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/","name":"Secretaria de Obras","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#\/schema\/person\/6e93b0ab2174b69f691ac4f278ba2d0a","name":"lilicrivello","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0b546b667388f8edb7b67d70a57b5e46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b546b667388f8edb7b67d70a57b5e46?s=96&d=mm&r=g","caption":"lilicrivello"},"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/author\/lilicrivello\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/posts\/2931"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/comments?post=2931"}],"version-history":[{"count":1,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/posts\/2931\/revisions"}],"predecessor-version":[{"id":2933,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/posts\/2931\/revisions\/2933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/media\/2932"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/media?parent=2931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/categories?post=2931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/tags?post=2931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}