{"id":2148,"date":"2024-01-17T09:01:35","date_gmt":"2024-01-17T12:01:35","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/?p=2148"},"modified":"2024-01-17T09:01:37","modified_gmt":"2024-01-17T12:01:37","slug":"avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/","title":{"rendered":"Avan\u00e7am as obras de revitaliza\u00e7\u00e3o das avenidas Presidente Vargas e Scarpellini Ghezzi"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>A revitaliza\u00e7\u00e3o das avenidas Presidente Vargas e Scarpellini Ghezzi est\u00e1 transformando o Bairro S\u00e3o Crist\u00f3v\u00e3o e qualificar\u00e1 a mobilidade urbana entre este quadrante da cidade e a regi\u00e3o do Bairro Boqueir\u00e3o. Na manh\u00e3 desta ter\u00e7a-feira (16), o prefeito Pedro Almeida, junto com o secret\u00e1rio de Obras, Rubens Astolfi, esteve nos locais que recebem as interven\u00e7\u00f5es para conferir os avan\u00e7os.<\/p>\n\n\n\n<p>\u201cS\u00e3o duas grandes e importantes obras para Passo Fundo, que v\u00e3o melhorar a mobilidade urbana e a qualidade de vida das pessoas. Este lado da cidade est\u00e1 ganhando uma nova perspectiva, que permite melhorar o fluxo de ve\u00edculos e tamb\u00e9m ampliar a ocupa\u00e7\u00e3o dos espa\u00e7os p\u00fablicos e a utiliza\u00e7\u00e3o de outros modais de transporte\u201d, enfatizou o prefeito.<\/p>\n\n\n\n<p>Avenida Presidente Vargas<br>A revitaliza\u00e7\u00e3o da Avenida Presidente Vargas abranger\u00e1 um trecho total de cinco quil\u00f4metros com drenagem, novo asfalto, ciclovia, ilumina\u00e7\u00e3o em LED e paisagismo e foi dividida em etapas.<br>A primeira fase, do trevo do Ricci \u00e0 Rua Valentin Grazziotin, est\u00e1 sendo conclu\u00edda e passar\u00e1, nos pr\u00f3ximos dias, pela sinaliza\u00e7\u00e3o. Al\u00e9m disso, a Prefeitura dar\u00e1 in\u00edcio, nesta quarta-feira (17), \u00e0 segunda fase de interven\u00e7\u00f5es, que ir\u00e1 at\u00e9 a Rua Martins Cavalcante.<\/p>\n\n\n\n<p>Conforme o secret\u00e1rio de Obras, a primeira medida ser\u00e1 a remo\u00e7\u00e3o do antigo canteiro. \u00c9 importante que os motoristas fiquem atentos ao tr\u00e2nsito e aos poss\u00edveis desvios que ser\u00e3o sinalizados. \u201cBuscamos o m\u00ednimo impacto para o tr\u00e2nsito, com a manuten\u00e7\u00e3o normal do fluxo. Mas, por se tratar de uma grande obra, algumas altera\u00e7\u00f5es s\u00e3o feitas. Em breve, todos poder\u00e3o aproveitar a avenida com uma nova infraestrutura\u201d, pontuou.<\/p>\n\n\n\n<p>O prefeito considerou que as melhorias j\u00e1 est\u00e3o impactando positivamente no dia a dia da popula\u00e7\u00e3o. \u201cMesmo com as obras em andamento, muitas pessoas j\u00e1 est\u00e3o utilizando o canteiro central e a ciclovia da Presidente Vargas para a pr\u00e1tica de atividades f\u00edsicas, especialmente, nos fins de tarde\u201d, afirmou.<\/p>\n\n\n\n<p>Scarpellini Ghezzi<br>A revitaliza\u00e7\u00e3o da Avenida Scarpellini Ghezzi acontece em uma extens\u00e3o de dois quil\u00f4metros, entre a Avenida Presidente Vargas e a Rua Jo\u00e3o Biazus com nova pavimenta\u00e7\u00e3o, refor\u00e7o na drenagem, ilumina\u00e7\u00e3o em LED e ciclovia. Uma novidade \u00e9 a coloca\u00e7\u00e3o de paver na regi\u00e3o do Bosque Lucas Ara\u00fajo, tendo em vista as peculiaridades ambientais do espa\u00e7o.<\/p>\n\n\n\n<p>Na mesma licita\u00e7\u00e3o, foram inseridas as ruas Guilherme Kurtz, S\u00e3o Pedro, Coronel Miranda e Mascarenhas, totalizando cinco quil\u00f4metros de obras e contemplando, assim, todo o anel vi\u00e1rio da regi\u00e3o.<\/p>\n\n\n\n<p>De acordo com Astolfi, cerca de 70% das interven\u00e7\u00f5es previstas j\u00e1 foram conclu\u00eddas. \u201cNeste momento, as equipes atuam em duas frentes de servi\u00e7o: uma na coloca\u00e7\u00e3o de meio-fio e paver entre as ruas Daltro Filho e Geny da Cunha; e outra na camada asf\u00e1ltica da Rua Guilherme Kurtz. As interven\u00e7\u00f5es seguintes ser\u00e3o a liga\u00e7\u00e3o da ilumina\u00e7\u00e3o em LED e a sinaliza\u00e7\u00e3o\u201d, enfatizou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura deu in\u00edcio a mais uma etapa de interven\u00e7\u00f5es na Avenida Presidente Vargas. Enquanto isso, as obras da Avenida Scarpellini Ghezzi j\u00e1 foram 70% executadas<\/p>\n","protected":false},"author":6,"featured_media":2149,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Avan\u00e7am as obras de revitaliza\u00e7\u00e3o das avenidas Presidente Vargas e Scarpellini Ghezzi - Secretaria de Obras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avan\u00e7am as obras de revitaliza\u00e7\u00e3o das avenidas Presidente Vargas e Scarpellini Ghezzi - Secretaria de Obras\" \/>\n<meta property=\"og:description\" content=\"A Prefeitura deu in\u00edcio a mais uma etapa de interven\u00e7\u00f5es na Avenida Presidente Vargas. Enquanto isso, as obras da Avenida Scarpellini Ghezzi j\u00e1 foram 70% executadas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Obras\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-17T12:01:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-17T12:01:37+00:00\" \/>\n<meta name=\"author\" content=\"andressazorzetto07\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"andressazorzetto07\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/\",\"name\":\"Avan\u00e7am as obras de revitaliza\u00e7\u00e3o das avenidas Presidente Vargas e Scarpellini Ghezzi - Secretaria de Obras\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-content\/uploads\/sites\/49\/2024\/01\/MSF05346-scaled.jpg\",\"datePublished\":\"2024-01-17T12:01:35+00:00\",\"dateModified\":\"2024-01-17T12:01:37+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#\/schema\/person\/30ee1d1bd74da1469b01fcf086e43351\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-content\/uploads\/sites\/49\/2024\/01\/MSF05346-scaled.jpg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-content\/uploads\/sites\/49\/2024\/01\/MSF05346-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avan\u00e7am as obras de revitaliza\u00e7\u00e3o das avenidas Presidente Vargas e Scarpellini Ghezzi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/\",\"name\":\"Secretaria de Obras\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#\/schema\/person\/30ee1d1bd74da1469b01fcf086e43351\",\"name\":\"andressazorzetto07\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/14c5458ed79dc81da99a13b9ff5f9f19?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/14c5458ed79dc81da99a13b9ff5f9f19?s=96&d=mm&r=g\",\"caption\":\"andressazorzetto07\"},\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/author\/andressazorzetto07\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avan\u00e7am as obras de revitaliza\u00e7\u00e3o das avenidas Presidente Vargas e Scarpellini Ghezzi - Secretaria de Obras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/","og_locale":"pt_BR","og_type":"article","og_title":"Avan\u00e7am as obras de revitaliza\u00e7\u00e3o das avenidas Presidente Vargas e Scarpellini Ghezzi - Secretaria de Obras","og_description":"A Prefeitura deu in\u00edcio a mais uma etapa de interven\u00e7\u00f5es na Avenida Presidente Vargas. Enquanto isso, as obras da Avenida Scarpellini Ghezzi j\u00e1 foram 70% executadas","og_url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/","og_site_name":"Secretaria de Obras","article_published_time":"2024-01-17T12:01:35+00:00","article_modified_time":"2024-01-17T12:01:37+00:00","author":"andressazorzetto07","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"andressazorzetto07","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/","name":"Avan\u00e7am as obras de revitaliza\u00e7\u00e3o das avenidas Presidente Vargas e Scarpellini Ghezzi - Secretaria de Obras","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-content\/uploads\/sites\/49\/2024\/01\/MSF05346-scaled.jpg","datePublished":"2024-01-17T12:01:35+00:00","dateModified":"2024-01-17T12:01:37+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#\/schema\/person\/30ee1d1bd74da1469b01fcf086e43351"},"breadcrumb":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-content\/uploads\/sites\/49\/2024\/01\/MSF05346-scaled.jpg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-content\/uploads\/sites\/49\/2024\/01\/MSF05346-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/2024\/01\/17\/avancam-as-obras-de-revitalizacao-das-avenidas-presidente-vargas-e-scarpellini-ghezzi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/"},{"@type":"ListItem","position":2,"name":"Avan\u00e7am as obras de revitaliza\u00e7\u00e3o das avenidas Presidente Vargas e Scarpellini Ghezzi"}]},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/","name":"Secretaria de Obras","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#\/schema\/person\/30ee1d1bd74da1469b01fcf086e43351","name":"andressazorzetto07","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/14c5458ed79dc81da99a13b9ff5f9f19?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14c5458ed79dc81da99a13b9ff5f9f19?s=96&d=mm&r=g","caption":"andressazorzetto07"},"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/author\/andressazorzetto07\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/posts\/2148"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/comments?post=2148"}],"version-history":[{"count":1,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/posts\/2148\/revisions"}],"predecessor-version":[{"id":2150,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/posts\/2148\/revisions\/2150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/media\/2149"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/media?parent=2148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/categories?post=2148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-obras\/wp-json\/wp\/v2\/tags?post=2148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}