{"id":951,"date":"2019-05-08T17:52:05","date_gmt":"2019-05-08T20:52:05","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/"},"modified":"2019-05-08T17:52:05","modified_gmt":"2019-05-08T20:52:05","slug":"e-o-bicho-realiza-mais-de-3-mil-castracoes-13556","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/","title":{"rendered":"\u00c9 o Bicho realiza mais de 3 mil castra\u00e7\u00f5es"},"content":{"rendered":"<p>O Programa \u00c9 o Bicho, implantado pela Prefeitura de Passo Fundo, \u00e9 dedicado ao bem-estar dos animais de rua do munic\u00edpio, especialmente, c\u00e3es e gatos. Desde sua cria\u00e7\u00e3o em 2014, mais de 3 mil castra\u00e7\u00f5es cir\u00fargicas de animais foram realizadas em diversos bairros da cidade.<\/p>\n<p>Conforme o secret\u00e1rio de Meio Ambiente, Rubens Astolfi, o programa tamb\u00e9m conhecido como Castram\u00f3vel, traz benef\u00edcios futuros, ao evitar que os animais de rua se proliferem e minimizar um problema que \u00e9 cr\u00f4nico nos centros urbanos. \u201cChegamos a uma marca importante das nossas a\u00e7\u00f5es feitas na inten\u00e7\u00e3o de diminuir o n\u00famero de animais abandonados em nosso munic\u00edpio. Foram 3 mil castra\u00e7\u00f5es que, consequentemente, evitaram o nascimento de mais de 36 mil animais no per\u00edodo, considerando apenas um ciclo de um ano\u201d, afirma Rubens.<\/p>\n<p>Nesta semana, o programa atende as comunidades do Loteamento Umb\u00fa e finaliza o recolhimento de f\u00eameas de c\u00e3es e gatos no Loteamento Manoel Corralo, que foram cadastradas no programa Bairro a Bairro.<\/p>\n<p>Funcionamento do programa<br \/>Evitar a procria\u00e7\u00e3o descontrolada e o abandono de animais, atrav\u00e9s do procedimento de castra\u00e7\u00e3o cir\u00fargica e cuidados em geral. Atrav\u00e9s de uma unidade m\u00f3vel, o programa leva c\u00e3es e gatos at\u00e9 cl\u00ednicas veterin\u00e1rias conveniadas para realizar o procedimento de castra\u00e7\u00e3o cir\u00fargica.<\/p>\n<p>O programa beneficiar\u00e1 os usu\u00e1rios inscritos no Cadastro \u00danico (Cad\u00danico) \u2013 com renda mensal de at\u00e9 meio sal\u00e1rio-m\u00ednimo por pessoa ou renda mensal total de at\u00e9 tr\u00eas sal\u00e1rios \u2013 e as organiza\u00e7\u00f5es protetoras dos animais. O \u00c9 o Bicho tamb\u00e9m ser\u00e1 realizado por regi\u00f5es da cidade e para a castra\u00e7\u00e3o cir\u00fargica de f\u00eameas.<\/p>\n<p>Para mais informa\u00e7\u00f5es sobre o programa \u00c9 o Bicho o cidad\u00e3o pode entrar em contato pelo telefone (54) 3312-9201.<\/p>\n<p><b>(Fotos: Divulga\u00e7\u00e3o)<br \/><\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para mais informa\u00e7\u00f5es sobre o programa o cidad\u00e3o pode entrar em contato pelo telefone (54) 3312-9201<\/p>\n","protected":false},"author":1,"featured_media":952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9 o Bicho realiza mais de 3 mil castra\u00e7\u00f5es - Secretaria de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9 o Bicho realiza mais de 3 mil castra\u00e7\u00f5es - Secretaria de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"Para mais informa\u00e7\u00f5es sobre o programa o cidad\u00e3o pode entrar em contato pelo telefone (54) 3312-9201\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-08T20:52:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2019-05-08_145509_385109-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/\",\"name\":\"\u00c9 o Bicho realiza mais de 3 mil castra\u00e7\u00f5es - Secretaria de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2019-05-08_145509_385109-scaled.jpg\",\"datePublished\":\"2019-05-08T20:52:05+00:00\",\"dateModified\":\"2019-05-08T20:52:05+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2019-05-08_145509_385109-scaled.jpg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2019-05-08_145509_385109-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/\",\"name\":\"Secretaria de Meio Ambiente\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9 o Bicho realiza mais de 3 mil castra\u00e7\u00f5es - Secretaria de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/","og_locale":"pt_BR","og_type":"article","og_title":"\u00c9 o Bicho realiza mais de 3 mil castra\u00e7\u00f5es - Secretaria de Meio Ambiente","og_description":"Para mais informa\u00e7\u00f5es sobre o programa o cidad\u00e3o pode entrar em contato pelo telefone (54) 3312-9201","og_url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/","og_site_name":"Secretaria de Meio Ambiente","article_published_time":"2019-05-08T20:52:05+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2019-05-08_145509_385109-scaled.jpg","type":"image\/jpeg"}],"author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/","name":"\u00c9 o Bicho realiza mais de 3 mil castra\u00e7\u00f5es - Secretaria de Meio Ambiente","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2019-05-08_145509_385109-scaled.jpg","datePublished":"2019-05-08T20:52:05+00:00","dateModified":"2019-05-08T20:52:05+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/05\/08\/e-o-bicho-realiza-mais-de-3-mil-castracoes-13556\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2019-05-08_145509_385109-scaled.jpg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2019-05-08_145509_385109-scaled.jpg","width":2560,"height":1920},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/","name":"Secretaria de Meio Ambiente","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts\/951"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/comments?post=951"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts\/951\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/media\/952"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/media?parent=951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/categories?post=951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/tags?post=951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}