{"id":946,"date":"2019-08-29T18:02:32","date_gmt":"2019-08-29T21:02:32","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/"},"modified":"2019-08-29T18:02:32","modified_gmt":"2019-08-29T21:02:32","slug":"e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/","title":{"rendered":"\u00c9 o Bicho realiza a\u00e7\u00e3o de castra\u00e7\u00e3o na Planaltina"},"content":{"rendered":"<p>O programa \u00c9 o Bicho, da Prefeitura de Passo Fundo, que busca reduzir a procria\u00e7\u00e3o descontrolada e o abandono de animais (c\u00e3es e gatos) na cidade, esteve nas \u00faltimas duas semanas realizando a\u00e7\u00f5es no bairro Planaltina. Neste per\u00edodo, foram encaminhados 55 animais para castra\u00e7\u00e3o.<\/p>\n<p>Pelo programa, de forma gratuita, os animais s\u00e3o levados at\u00e9 cl\u00ednicas veterin\u00e1rias conveniadas para realizar o procedimento de castra\u00e7\u00e3o cir\u00fargica. A escolha das cl\u00ednicas foi feita a partir de licita\u00e7\u00e3o e o investimento do programa foi feito com recursos do munic\u00edpio.<\/p>\n<p>O programa beneficia a comunidade inscrita no Cadastro \u00danico (Cad\u00danico) \u2013 com renda mensal de at\u00e9 meio sal\u00e1rio-m\u00ednimo por pessoa ou renda mensal total de at\u00e9 tr\u00eas sal\u00e1rios, al\u00e9m das organiza\u00e7\u00f5es protetoras dos animais.<\/p>\n<p><b>(Fotos: Divulga\u00e7\u00e3o)<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O programa beneficia a comunidade inscrita no Cadastro \u00danico (Cad\u00danico)<\/p>\n","protected":false},"author":1,"featured_media":947,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9 o Bicho realiza a\u00e7\u00e3o de castra\u00e7\u00e3o na Planaltina - Secretaria de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9 o Bicho realiza a\u00e7\u00e3o de castra\u00e7\u00e3o na Planaltina - Secretaria de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"O programa beneficia a comunidade inscrita no Cadastro \u00danico (Cad\u00danico)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-29T21:02:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2019-08-29_150349_385109.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"780\" \/>\n\t<meta property=\"og:image:height\" content=\"1040\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/\",\"name\":\"\u00c9 o Bicho realiza a\u00e7\u00e3o de castra\u00e7\u00e3o na Planaltina - Secretaria de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2019-08-29_150349_385109.jpg\",\"datePublished\":\"2019-08-29T21:02:32+00:00\",\"dateModified\":\"2019-08-29T21:02:32+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2019-08-29_150349_385109.jpg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2019-08-29_150349_385109.jpg\",\"width\":780,\"height\":1040},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/\",\"name\":\"Secretaria de Meio Ambiente\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c9 o Bicho realiza a\u00e7\u00e3o de castra\u00e7\u00e3o na Planaltina - Secretaria de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/","og_locale":"pt_BR","og_type":"article","og_title":"\u00c9 o Bicho realiza a\u00e7\u00e3o de castra\u00e7\u00e3o na Planaltina - Secretaria de Meio Ambiente","og_description":"O programa beneficia a comunidade inscrita no Cadastro \u00danico (Cad\u00danico)","og_url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/","og_site_name":"Secretaria de Meio Ambiente","article_published_time":"2019-08-29T21:02:32+00:00","og_image":[{"width":780,"height":1040,"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2019-08-29_150349_385109.jpg","type":"image\/jpeg"}],"author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/","name":"\u00c9 o Bicho realiza a\u00e7\u00e3o de castra\u00e7\u00e3o na Planaltina - Secretaria de Meio Ambiente","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2019-08-29_150349_385109.jpg","datePublished":"2019-08-29T21:02:32+00:00","dateModified":"2019-08-29T21:02:32+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2019\/08\/29\/e-o-bicho-realiza-acao-de-castracao-na-planaltina-13828\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2019-08-29_150349_385109.jpg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2019-08-29_150349_385109.jpg","width":780,"height":1040},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/","name":"Secretaria de Meio Ambiente","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts\/946"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/comments?post=946"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts\/946\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/media\/947"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/media?parent=946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/categories?post=946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/tags?post=946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}