{"id":871,"date":"2018-04-05T19:02:01","date_gmt":"2018-04-05T22:02:01","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/"},"modified":"2018-04-05T19:02:01","modified_gmt":"2018-04-05T22:02:01","slug":"coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/","title":{"rendered":"Coleta Seletiva Solid\u00e1ria chega \u00e0 vila Rodrigues"},"content":{"rendered":"<p>Nesta semana os moradores da Vila Rodrigues come\u00e7aram a receber alguns panfletos explicativos sobre separa\u00e7\u00e3o do lixo. Isso porque a regi\u00e3o vai come\u00e7ar a participar das a\u00e7\u00f5es do projeto Coleta Seletiva Solid\u00e1ria: Res\u00edduos Recicl\u00e1veis, desenvolvido pela Prefeitura de Passo Fundo atrav\u00e9s da Secretaria de Meio Ambiente. Dentro deste projeto, a coleta seletiva \u00e9 realizada diretamente pelas cooperativas de recicladores, que t\u00eam dia e hor\u00e1rio diferenciados para fazer este recolhimento.<\/p>\n<p>A distribui\u00e7\u00e3o dos panfletos faz parte do trabalho de educa\u00e7\u00e3o ambiental realizado no bairro com o objetivo de orientar os moradores sobre como separar adequadamente o lixo. Esta atividade contou com a colabora\u00e7\u00e3o dos alunos do Col\u00e9gio Tiradentes, que percorreram todas as ruas orientando a popula\u00e7\u00e3o e que neste domingo, dia 8 de abril, das 15h \u00e0s 16h, estar\u00e3o na pra\u00e7a Capit\u00e3o Jovino (em frente a igreja Santa Terezinha) para esclarecer d\u00favidas dos moradores. Com isso, a partir de segunda-feira, dia 9 de abril, a Coama come\u00e7a a fazer o recolhimento todas as segundas e quintas-feiras, \u00e0s 8h.<\/p>\n<p>O trabalho na vila Rodrigues \u00e9 um pouco diferenciado, pois conta tamb\u00e9m com o projeto Meu Bairro Mais Sustent\u00e1vel, promovido pela Una Construtora, e que tamb\u00e9m conta com o apoio da Prefeitura de Passo Fundo, al\u00e9m de ter apoio da Igreja Santa Teresinha, Imed, Col\u00e9gio Notre Dame Menino Jesus, Col\u00e9gio Tiradentes, Comercial Zaffari, Coama, Socrebe, Ifibe e Projeto TransformA\u00e7\u00e3o. O Meu Bairro Mais Sustent\u00e1vel, dentre outras a\u00e7\u00f5es, promove a conscientiza\u00e7\u00e3o sobre a correta separa\u00e7\u00e3o e destina\u00e7\u00e3o de res\u00eddios domiciliares na comunidade, especialmente nos empreendimentos da construtora.<\/p>\n<p>Conforme Cristiano Basso, da Una Construtora, o objetivo da empresa com o projeto \u00e9, al\u00e9m de auxiliar na melhoria do servi\u00e7o de coleta seletiva, beneficiar as cooperativas que trabalham com este material. \u201cEstamos fazendo ainda um trabalho de orienta\u00e7\u00e3o dos moradores para conserva\u00e7\u00e3o das cal\u00e7adas, especialmente na limpeza. A ideia \u00e9 transformar o bairro num exemplo n\u00e3o s\u00f3 se um bairro sustent\u00e1vel conceitualmente, mas tamb\u00e9m de conscientiza\u00e7\u00e3o\u201d, afirma.<\/p>\n<p>Este trabalho visa conscientizar e sensibilizar a comunidade de Passo Fundo em separar os seus res\u00edduos e destina-los adequadamente. \u201cA coleta seletiva dos res\u00edduos promove benef\u00edcios que v\u00e3o al\u00e9m dos j\u00e1 previstos para a esfera do meio ambiente. Promovem benef\u00edcios tanto no meio ambiente, como econ\u00f4micos e benef\u00edcios sociais\u201d, salienta o secret\u00e1rio de Meio Ambiente, Rubens Astolfi.<\/p>\n<p><b>Muito al\u00e9m da coleta<\/b><br \/>Para chegar ao objetivo de tornar o bairro um modelo no quesito de sustentabilidade, ser\u00e3o instaladas 35 lixeiras\/papeleiras nos bairros p\u00fablicos, especialmente em torno da pra\u00e7a. A\u00e7\u00e3o esta que ser\u00e1 desempenhada pela Una Construtora. A ideia \u00e9 que al\u00e9m de cuidar do lixo produzido nas resid\u00eancias, as ruas tenham o local adequado para conserva\u00e7\u00e3o dos materiais descartados, tanto por quem mora nas redondezas como quem visita o bairro.<\/p>\n<p><b>Pelos bairros<\/b><br \/>Al\u00e9m da vial Rodrigues, outros bairros de Passo Fundo em breve come\u00e7ar\u00e3o a ter a coleta seletiva realizada diretamente pelas cooperativas. De acordo com a Secretaria de Meio Ambiente, na pr\u00f3xima semana os bairros Menino Deus, Cohab Sechi e Santo Afonso ter\u00e3o o in\u00edcio do trabalho de educa\u00e7\u00e3o ambiental. Nesta regi\u00e3o, a parceria da secretaria \u00e9 com a Fasurgs, Associa\u00e7\u00e3o dos Moradores da Cohab Sechi e Instituto Redentorista Menino Deus. A coleta nesta regi\u00e3o ficar\u00e1 com a Cootraempo, que passar\u00e1 nos bairros a partir do dia 16 de abril, nas segundas e sextas-feiras no turno da manh\u00e3.<\/p>\n<p><b>Coleta de res\u00edduos org\u00e2nicos continua igual<\/b><br \/>O in\u00edcio dessas a\u00e7\u00f5es de coleta seletiva n\u00e3o ir\u00e1 interferir na coleta de res\u00edduos org\u00e2nicos realizados pela empresa Via Norte. N\u00e3o haver\u00e1 altera\u00e7\u00e3o de hor\u00e1rio ou dias da semana.<\/p>\n<p><b>(Foto: Divulga\u00e7\u00e3o)<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dentro deste projeto, a coleta seletiva \u00e9 realizada diretamente pelas cooperativas de recicladores<\/p>\n","protected":false},"author":1,"featured_media":872,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coleta Seletiva Solid\u00e1ria chega \u00e0 vila Rodrigues - Secretaria de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coleta Seletiva Solid\u00e1ria chega \u00e0 vila Rodrigues - Secretaria de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"Dentro deste projeto, a coleta seletiva \u00e9 realizada diretamente pelas cooperativas de recicladores\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-05T22:02:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2018-04-05_160327_385109-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/\",\"name\":\"Coleta Seletiva Solid\u00e1ria chega \u00e0 vila Rodrigues - Secretaria de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2018-04-05_160327_385109-scaled.jpg\",\"datePublished\":\"2018-04-05T22:02:01+00:00\",\"dateModified\":\"2018-04-05T22:02:01+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2018-04-05_160327_385109-scaled.jpg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2018-04-05_160327_385109-scaled.jpg\",\"width\":2560,\"height\":1704},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/\",\"name\":\"Secretaria de Meio Ambiente\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coleta Seletiva Solid\u00e1ria chega \u00e0 vila Rodrigues - Secretaria de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/","og_locale":"pt_BR","og_type":"article","og_title":"Coleta Seletiva Solid\u00e1ria chega \u00e0 vila Rodrigues - Secretaria de Meio Ambiente","og_description":"Dentro deste projeto, a coleta seletiva \u00e9 realizada diretamente pelas cooperativas de recicladores","og_url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/","og_site_name":"Secretaria de Meio Ambiente","article_published_time":"2018-04-05T22:02:01+00:00","og_image":[{"width":2560,"height":1704,"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2018-04-05_160327_385109-scaled.jpg","type":"image\/jpeg"}],"author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/","name":"Coleta Seletiva Solid\u00e1ria chega \u00e0 vila Rodrigues - Secretaria de Meio Ambiente","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2018-04-05_160327_385109-scaled.jpg","datePublished":"2018-04-05T22:02:01+00:00","dateModified":"2018-04-05T22:02:01+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/04\/05\/coleta-seletiva-solidaria-chega-a-vila-rodrigues-12563\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2018-04-05_160327_385109-scaled.jpg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2018-04-05_160327_385109-scaled.jpg","width":2560,"height":1704},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/","name":"Secretaria de Meio Ambiente","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts\/871"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/comments?post=871"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts\/871\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/media\/872"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/media?parent=871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/categories?post=871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/tags?post=871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}