{"id":866,"date":"2018-03-01T17:51:22","date_gmt":"2018-03-01T20:51:22","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/03\/01\/autorizado-novo-pavilhao-da-usina-de-reciclagem-12483\/"},"modified":"2018-03-01T17:51:22","modified_gmt":"2018-03-01T20:51:22","slug":"autorizado-novo-pavilhao-da-usina-de-reciclagem-12483","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/03\/01\/autorizado-novo-pavilhao-da-usina-de-reciclagem-12483\/","title":{"rendered":"Autorizado novo pavilh\u00e3o da Usina de Reciclagem"},"content":{"rendered":"<p>A Prefeitura de Passo Fundo confirmou nessa semana mais um investimento para buscar a reciclagem de res\u00edduos s\u00f3lidos e a gera\u00e7\u00e3o de emprego e renda. O prefeito Luciano Azevedo autorizou a licita\u00e7\u00e3o de um novo pavilh\u00e3o para a Usina de Reciclagem.<\/p>\n<p>\u201cCom essa amplia\u00e7\u00e3o instalaremos mais duas esteiras de reciclagem, que ser\u00e3o compradas separadamente. Esse compromisso foi assumido com os recicladores l\u00e1 em julho se 2017, quando pela primeira vez a Prefeitura contratou uma cooperativa de recicladores, a Recibela. Com esse investimento a capacidade de reciclagem ir\u00e1 triplicar\u201d, disse o secret\u00e1rio de Meio Ambiente, Rubens Astolfi. Atualmente, a Recibela est\u00e1 trabalhando em dois turnos, totalizando 60 pessoas.<\/p>\n<p>Os recursos s\u00e3o de aproximadamente R$ 587 mil, sendo provenientes do Fundo Municipal de Gest\u00e3o Compartilhada.<\/p>\n<p><b>Cada um fazendo a sua parte<\/b><br \/>Todo o lixo recolhido em Passo Fundo \u00e9 levado at\u00e9 a Central de Triagem e Transbordo. Chegando l\u00e1, o material recolhido pela coleta seletiva vai diretamente para a separa\u00e7\u00e3o. Na esteira as sacolas ou sacos de lixo s\u00e3o abertos para o material recicl\u00e1vel ser separado pelos cooperados.<\/p>\n<p>Justamente por essa log\u00edstica, \u00e9 fundamental que as fam\u00edlias fa\u00e7am a separa\u00e7\u00e3o do lixo seco e org\u00e2nico em suas casas, como explica Rubens: \u201ca separa\u00e7\u00e3o dos res\u00edduos nas resid\u00eancias facilita o trabalho de reciclagem realizado por todas as cooperativas, em especial a Recibela, por isso a import\u00e2ncia da separa\u00e7\u00e3o em res\u00edduo org\u00e2nico e seco independente de possuir coleta seletiva no bairro\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os recursos s\u00e3o de aproximadamente R$ 587 mil, oriundos do Fundo Municipal de Gest\u00e3o Compartilhada<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Autorizado novo pavilh\u00e3o da Usina de Reciclagem - Secretaria de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/03\/01\/autorizado-novo-pavilhao-da-usina-de-reciclagem-12483\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Autorizado novo pavilh\u00e3o da Usina de Reciclagem - Secretaria de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"Os recursos s\u00e3o de aproximadamente R$ 587 mil, oriundos do Fundo Municipal de Gest\u00e3o Compartilhada\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/03\/01\/autorizado-novo-pavilhao-da-usina-de-reciclagem-12483\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-01T20:51:22+00:00\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/03\/01\/autorizado-novo-pavilhao-da-usina-de-reciclagem-12483\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/03\/01\/autorizado-novo-pavilhao-da-usina-de-reciclagem-12483\/\",\"name\":\"Autorizado novo pavilh\u00e3o da Usina de Reciclagem - Secretaria de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website\"},\"datePublished\":\"2018-03-01T20:51:22+00:00\",\"dateModified\":\"2018-03-01T20:51:22+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/03\/01\/autorizado-novo-pavilhao-da-usina-de-reciclagem-12483\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/\",\"name\":\"Secretaria de Meio Ambiente\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Autorizado novo pavilh\u00e3o da Usina de Reciclagem - Secretaria de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/03\/01\/autorizado-novo-pavilhao-da-usina-de-reciclagem-12483\/","og_locale":"pt_BR","og_type":"article","og_title":"Autorizado novo pavilh\u00e3o da Usina de Reciclagem - Secretaria de Meio Ambiente","og_description":"Os recursos s\u00e3o de aproximadamente R$ 587 mil, oriundos do Fundo Municipal de Gest\u00e3o Compartilhada","og_url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/03\/01\/autorizado-novo-pavilhao-da-usina-de-reciclagem-12483\/","og_site_name":"Secretaria de Meio Ambiente","article_published_time":"2018-03-01T20:51:22+00:00","author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/03\/01\/autorizado-novo-pavilhao-da-usina-de-reciclagem-12483\/","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/03\/01\/autorizado-novo-pavilhao-da-usina-de-reciclagem-12483\/","name":"Autorizado novo pavilh\u00e3o da Usina de Reciclagem - Secretaria de Meio Ambiente","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website"},"datePublished":"2018-03-01T20:51:22+00:00","dateModified":"2018-03-01T20:51:22+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2018\/03\/01\/autorizado-novo-pavilhao-da-usina-de-reciclagem-12483\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/","name":"Secretaria de Meio Ambiente","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts\/866"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/comments?post=866"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts\/866\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/media?parent=866"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/categories?post=866"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/tags?post=866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}