{"id":339,"date":"2021-12-14T21:21:20","date_gmt":"2021-12-15T00:21:20","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/"},"modified":"2021-12-14T21:21:20","modified_gmt":"2021-12-15T00:21:20","slug":"mais-recursos-para-a-causa-animal-15196","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/","title":{"rendered":"Mais recursos para a causa animal"},"content":{"rendered":"<p style=\"margin-bottom: 0cm;\">A ter\u00e7a-feira (14) foi pautada por importantes an\u00fancios para o munic\u00edpio. O prefeito, Pedro Almeida, recebeu a secret\u00e1ria de Igualdade, Cidadania, Direitos Humanos e Assist\u00eancia Social, Regina Becker, e, juntos, efetivaram dois conv\u00eanios que trar\u00e3o avan\u00e7os para duas \u00e1reas: a prote\u00e7\u00e3o animal e a assist\u00eancia social.<\/p>\n<p style=\"margin-bottom: 0cm;\">A partir do programa <a href=\"https:\/\/rduirapuru.com.br\/?s=%C3%89+o+Bicho&#038;post_type=post\" target=\"_blank\" rel=\"noopener\">\u00c9 o Bicho<\/a>, a Prefeitura de Passo Fundo j\u00e1 castrou 6,7 mil animais, entre c\u00e3es e gatos. A iniciativa, que atualmente conta com R$ 50 mil mensais em recursos pr\u00f3prios do Munic\u00edpio, mediante a assinatura do conv\u00eanio, recebeu um aporte de R$ 68 mil do governo estadual.<\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\">O prefeito comemorou a iniciativa, assegurando que a Prefeitura aplicar\u00e1 uma contrapartida de R$ 13,6 mil a esse valor. \u201cAs castra\u00e7\u00f5es s\u00e3o um dever coletivo, que precisam ser estimuladas pelos governos. Elas encerram ciclos de procria\u00e7\u00e3o descontrolada e evitam poss\u00edveis maus-tratos e abandono. A partir do \u00c9 o Bicho, o Munic\u00edpio realiza h\u00e1 sete anos procedimentos gratuitos a animais de pessoas que n\u00e3o possuem condi\u00e7\u00f5es e dos resgatados por protetoras independentes. Ficamos muito felizes com o apoio do governo estadual, porque esse \u00e9 um passo importante para que a causa animal receba suporte n\u00e3o s\u00f3 em Passo Fundo, mas em tantas outras cidades\u201d, considerou.<\/p>\n<p style=\"margin-bottom: 0cm;\">Regina avaliou que os recursos aplicados no bem-estar animal, al\u00e9m de levarem o cuidado aos animais, trazem benef\u00edcios para a sa\u00fade p\u00fablica. \u201cCuidar da sa\u00fade animal \u00e9 tamb\u00e9m cuidar da sa\u00fade p\u00fablica. Por isso, pol\u00edticas p\u00fablicas como \u00c9 o Bicho s\u00e3o fundamentais\u201d, ponderou.<\/p>\n<p style=\"margin-bottom: 0cm;\">O investimento do Governo do Estado faz parte do programa Melhores Amigos \u2013 Bicho Sente como Gente, implementado por meio da Secretaria da Igualdade, Cidadania, Direitos Humanos e Assist\u00eancia Social (SICDHAS). A iniciativa tem como objetivo estabelecer pol\u00edticas p\u00fablicas de controle populacional e sensibiliza\u00e7\u00e3o da sociedade, estimulando os munic\u00edpios a criarem a\u00e7\u00f5es voltadas \u00e0 causa animal.<\/p>\n<p style=\"margin-bottom: 0cm;\">O programa possui dois eixos: campanhas de educa\u00e7\u00e3o da popula\u00e7\u00e3o contra os maus-tratos aos animais e projetos de castra\u00e7\u00f5es de c\u00e3es e gatos. Neste primeiro momento, foram beneficiados 32 munic\u00edpios, recortados a partir do fator de maior popula\u00e7\u00e3o, o que incluiu Passo Fundo.<\/p>\n<p style=\"margin-bottom: 0cm;\">A secret\u00e1ria municipal de Meio Ambiente, Gabriela Engers, destacou que os recursos ampliar\u00e3o ainda mais o n\u00famero de castra\u00e7\u00f5es a animais resgatados por protetores independentes e de pessoas inscritas no Cad\u00danico. \u201cO objetivo \u00e9 realizarmos de 400 a 420 castra\u00e7\u00f5es somente com esses recursos, al\u00e9m da microchipagem dos animais\u201d, afirmou.<\/p>\n<p style=\"margin-bottom: 0cm;\">Presente na assinatura do conv\u00eanio, o vereador e presidente do legislativo, Rafael Colussi, que tem como bandeira a causa animal, participou da articula\u00e7\u00e3o dos recursos. Ele falou sobre a luta para garantir avan\u00e7os. \u201cEssa administra\u00e7\u00e3o tem dado resultado ao cidad\u00e3o. E a C\u00e2mara est\u00e1 ao lado de todas as boas iniciativas, como \u00e9 o caso dos recursos da prote\u00e7\u00e3o animal\u201d, enfatizou.<\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\">  <\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\"><b>PopRua RS<\/b>  <\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\">Outro conv\u00eanio assinado nesta ter\u00e7a-feira (14), tamb\u00e9m entre o prefeito, Pedro Almeida, e a secret\u00e1ria de Igualdade, Cidadania, Direitos Humanos e Assist\u00eancia Social, Regina Becker, diz respeito a um repasse de R$ 170 mil para a \u00e1rea da assist\u00eancia social. Os recursos integram o programa PopRua RS e dever\u00e3o ser utilizados para proporcionar atendimento institucional a pessoas em situa\u00e7\u00e3o de rua.<\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\">Conforme a secret\u00e1ria-adjunta de Cidadania e Assist\u00eancia Social, Elenir Chapuis, esse recurso vem para potencializar os servi\u00e7os j\u00e1 executados pela Prefeitura no acolhimento a essa popula\u00e7\u00e3o. \u201cO conv\u00eanio vai proporcionar melhorias ao acolhimento no Centro POP, Casa de Passagem e Abordagem Social, que s\u00e3o os tr\u00eas servi\u00e7os existentes em Passo Fundo e que s\u00e3o refer\u00eancia em todo o Estado, porque prestam um acolhimento reconhecido pela qualidade do que \u00e9 oferecido pela Prefeitura. Para Passo Fundo isto \u00e9 muito relevante porque concretiza todo o olhar e o trabalho que j\u00e1 \u00e9 desenvolvido aqui no munic\u00edpio\u201d, reiterou.<\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\">A PopRuaRS \u00e9 resultado da parceria entre Estado, terceiro setor e empresas que contribu\u00edram com recursos destinados ao Pr\u00f3-Social. Segundo Regina, a pandemia trouxe a necessidade de estrat\u00e9gias de interven\u00e7\u00e3o junto \u00e0s popula\u00e7\u00f5es mais vulner\u00e1veis. \u201cO Estado reconhece os esfor\u00e7os da Administra\u00e7\u00e3o nos programas da assist\u00eancia social. O recurso fortalecer\u00e1 toda a estrutura montada pela Prefeitura, podendo ampliar os servi\u00e7os, al\u00e9m de oferecer ainda mais condi\u00e7\u00f5es para a Prefeitura garantir este acolhimento\u201d, mencionou.  <\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\">O conv\u00eanio assinado com Passo Fundo \u00e9 o primeiro a ser efetivado na segunda etapa do programa. Foram selecionados munic\u00edpios que possuem n\u00famero consider\u00e1vel de pessoas em situa\u00e7\u00e3o de vulnerabilidade e risco social decorrentes da situa\u00e7\u00e3o de rua e do desabrigo por abandono, migra\u00e7\u00e3o e aus\u00eancia de resid\u00eancia e, ainda, em tr\u00e2nsito sem condi\u00e7\u00f5es de autossustento, inseridas no Cad\u00danico da assist\u00eancia social.<\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\"><\/p>\n<p style=\"margin-bottom: 0cm; line-height: 100%;\"><b>Fotos: Diogo Zanatta<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Munic\u00edpio e Estado assinam conv\u00eanios para a causa animal e a assist\u00eancia social<\/p>\n","protected":false},"author":1,"featured_media":340,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mais recursos para a causa animal - Secretaria de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mais recursos para a causa animal - Secretaria de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"Munic\u00edpio e Estado assinam conv\u00eanios para a causa animal e a assist\u00eancia social\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-15T00:21:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2021-12-14_182508_402193.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/\",\"name\":\"Mais recursos para a causa animal - Secretaria de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2021-12-14_182508_402193.jpg\",\"datePublished\":\"2021-12-15T00:21:20+00:00\",\"dateModified\":\"2021-12-15T00:21:20+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2021-12-14_182508_402193.jpg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2021-12-14_182508_402193.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/\",\"name\":\"Secretaria de Meio Ambiente\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mais recursos para a causa animal - Secretaria de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/","og_locale":"pt_BR","og_type":"article","og_title":"Mais recursos para a causa animal - Secretaria de Meio Ambiente","og_description":"Munic\u00edpio e Estado assinam conv\u00eanios para a causa animal e a assist\u00eancia social","og_url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/","og_site_name":"Secretaria de Meio Ambiente","article_published_time":"2021-12-15T00:21:20+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2021-12-14_182508_402193.jpg","type":"image\/jpeg"}],"author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/","name":"Mais recursos para a causa animal - Secretaria de Meio Ambiente","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2021-12-14_182508_402193.jpg","datePublished":"2021-12-15T00:21:20+00:00","dateModified":"2021-12-15T00:21:20+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2021\/12\/14\/mais-recursos-para-a-causa-animal-15196\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2021-12-14_182508_402193.jpg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-content\/uploads\/sites\/48\/2021\/12\/I2021-12-14_182508_402193.jpg","width":1280,"height":853},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/","name":"Secretaria de Meio Ambiente","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts\/339"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/comments?post=339"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts\/339\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/media\/340"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/media?parent=339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/categories?post=339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/tags?post=339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}