{"id":1854,"date":"2026-07-15T15:59:10","date_gmt":"2026-07-15T18:59:10","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/?p=1854"},"modified":"2026-07-15T15:59:13","modified_gmt":"2026-07-15T18:59:13","slug":"nota-de-utilidade-publica","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2026\/07\/15\/nota-de-utilidade-publica\/","title":{"rendered":"Nota de Utilidade P\u00fablica"},"content":{"rendered":"\n<p>A Secretaria Municipal de Meio Ambiente &#8211; SMAM informa que o Ecoponto de Res\u00edduos Volumosos localizado na Rua Eduardo de Brito, esquina com a Rua Jacinto Vila Nova, no bairro Vila Annes, estar\u00e1 fechado para manuten\u00e7\u00e3o a partir desta quarta-feira(15) para a realiza\u00e7\u00e3o de servi\u00e7os de limpeza, manuten\u00e7\u00e3o e organiza\u00e7\u00e3o do espa\u00e7o.<\/p>\n\n\n\n<p>A medida tem como objetivo garantir melhores condi\u00e7\u00f5es de atendimento, seguran\u00e7a e conserva\u00e7\u00e3o da estrutura, para que possamos continuar prestando um servi\u00e7o de qualidade \u00e0 comunidade.<\/p>\n\n\n\n<p>Agradecemos a compreens\u00e3o de todos e informaremos oportunamente a data de reabertura do Ecoponto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria Municipal de Meio Ambiente &#8211; SMAM informa que o Ecoponto de Res\u00edduos Volumosos localizado na Rua Eduardo de Brito, esquina com a Rua Jacinto Vila Nova, no bairro Vila Annes, [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nota de Utilidade P\u00fablica - Secretaria de Meio Ambiente<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2026\/07\/15\/nota-de-utilidade-publica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nota de Utilidade P\u00fablica - Secretaria de Meio Ambiente\" \/>\n<meta property=\"og:description\" content=\"A Secretaria Municipal de Meio Ambiente &#8211; SMAM informa que o Ecoponto de Res\u00edduos Volumosos localizado na Rua Eduardo de Brito, esquina com a Rua Jacinto Vila Nova, no bairro Vila Annes, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2026\/07\/15\/nota-de-utilidade-publica\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Meio Ambiente\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T18:59:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T18:59:13+00:00\" \/>\n<meta name=\"author\" content=\"lilicrivello\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"lilicrivello\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2026\/07\/15\/nota-de-utilidade-publica\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2026\/07\/15\/nota-de-utilidade-publica\/\",\"name\":\"Nota de Utilidade P\u00fablica - Secretaria de Meio Ambiente\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website\"},\"datePublished\":\"2026-07-15T18:59:10+00:00\",\"dateModified\":\"2026-07-15T18:59:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/6e93b0ab2174b69f691ac4f278ba2d0a\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2026\/07\/15\/nota-de-utilidade-publica\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/\",\"name\":\"Secretaria de Meio Ambiente\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/6e93b0ab2174b69f691ac4f278ba2d0a\",\"name\":\"lilicrivello\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0b546b667388f8edb7b67d70a57b5e46?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0b546b667388f8edb7b67d70a57b5e46?s=96&d=mm&r=g\",\"caption\":\"lilicrivello\"},\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/author\/lilicrivello\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nota de Utilidade P\u00fablica - Secretaria de Meio Ambiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2026\/07\/15\/nota-de-utilidade-publica\/","og_locale":"pt_BR","og_type":"article","og_title":"Nota de Utilidade P\u00fablica - Secretaria de Meio Ambiente","og_description":"A Secretaria Municipal de Meio Ambiente &#8211; SMAM informa que o Ecoponto de Res\u00edduos Volumosos localizado na Rua Eduardo de Brito, esquina com a Rua Jacinto Vila Nova, no bairro Vila Annes, [&hellip;]","og_url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2026\/07\/15\/nota-de-utilidade-publica\/","og_site_name":"Secretaria de Meio Ambiente","article_published_time":"2026-07-15T18:59:10+00:00","article_modified_time":"2026-07-15T18:59:13+00:00","author":"lilicrivello","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"lilicrivello","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2026\/07\/15\/nota-de-utilidade-publica\/","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2026\/07\/15\/nota-de-utilidade-publica\/","name":"Nota de Utilidade P\u00fablica - Secretaria de Meio Ambiente","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website"},"datePublished":"2026-07-15T18:59:10+00:00","dateModified":"2026-07-15T18:59:13+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/6e93b0ab2174b69f691ac4f278ba2d0a"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/2026\/07\/15\/nota-de-utilidade-publica\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/","name":"Secretaria de Meio Ambiente","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/6e93b0ab2174b69f691ac4f278ba2d0a","name":"lilicrivello","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0b546b667388f8edb7b67d70a57b5e46?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b546b667388f8edb7b67d70a57b5e46?s=96&d=mm&r=g","caption":"lilicrivello"},"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/author\/lilicrivello\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts\/1854"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/comments?post=1854"}],"version-history":[{"count":1,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts\/1854\/revisions"}],"predecessor-version":[{"id":1855,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/posts\/1854\/revisions\/1855"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/media?parent=1854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/categories?post=1854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-meio-ambiente\/wp-json\/wp\/v2\/tags?post=1854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}