{"id":381,"date":"2017-05-10T19:52:17","date_gmt":"2017-05-10T22:52:17","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/"},"modified":"2017-05-10T19:52:17","modified_gmt":"2017-05-10T22:52:17","slug":"mais-de-600-familias-terao-melhorias-nas-casas-11536","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/","title":{"rendered":"Mais de 600 fam\u00edlias ter\u00e3o melhorias nas casas"},"content":{"rendered":"<p>A Prefeitura de Passo Fundo, atrav\u00e9s da Secretaria de Habita\u00e7\u00e3o, foi selecionada para o Programa Cart\u00e3o Reforma, do Governo Federal. Pelo programa, o munic\u00edpio fica habilitado a receber os benef\u00edcios destinados a qualificar a moradia de fam\u00edlias de baixa renda que queiram reformar, ampliar ou concluir suas resid\u00eancias. Com a previs\u00e3o de receber 608 Cart\u00f5es Reforma, Passo Fundo est\u00e1 entre os seis munic\u00edpios contemplados do Rio Grande do Sul. Em todo o Brasil, 87 cidades foram escolhidas.<\/p>\n<p>Por meio da concess\u00e3o de subs\u00eddio para compra de materiais de constru\u00e7\u00e3o e assist\u00eancia t\u00e9cnica de profissionais da \u00e1rea de constru\u00e7\u00e3o civil, as fam\u00edlias precisar\u00e3o custear apenas a m\u00e3o de obra do servi\u00e7o. O benef\u00edcio \u00e9 totalmente subsidiado, como explica o secret\u00e1rio de Habita\u00e7\u00e3o, Paulo Caletti. \u201cO programa n\u00e3o \u00e9 um financiamento, \u00e9 um subs\u00eddio, por isso, as pessoas que ser\u00e3o contempladas n\u00e3o precisar\u00e3o devolver o dinheiro\u201d, explicou ele. Os limites de cada cart\u00e3o devem variar entre R$ 2.500 e R$ 7.500, contabilizando mais de R$ 3 milh\u00f5es para o munic\u00edpio.<\/p>\n<p>Entre os objetivos est\u00e1 a redu\u00e7\u00e3o de d\u00e9ficit habitacional qualitativo que atinge pelo menos 8 milh\u00f5es de domic\u00edlios brasileiros em condi\u00e7\u00f5es inadequadas (Censo 2010). O programa visa reduzir a car\u00eancia de esgotamento sanit\u00e1rio, aus\u00eancia de banheiro exclusivo, cobertura inadequada e adensamento excessivo. Por isso, entre os servi\u00e7os est\u00e3o: solu\u00e7\u00e3o de esgoto, constru\u00e7\u00e3o do 1\u00b0 banheiro; constru\u00e7\u00e3o de um quarto; reforma do telhado; conclus\u00e3o de unidade habitacional.<\/p>\n<p>Ainda, a iniciativa pretende elevar a qualidade de vida por meio da qualifica\u00e7\u00e3o de moradias, proporcionando condi\u00e7\u00f5es desej\u00e1veis de habita\u00e7\u00e3o \u00e0s fam\u00edlias de baixa renda sem a necessidade de constru\u00e7\u00e3o de novas unidades habitacionais.<\/p>\n<p><b>Pr\u00f3ximos passos<\/b><br \/>A partir da habilita\u00e7\u00e3o do munic\u00edpio, o secret\u00e1rio Paulo Caletti e sua equipe ir\u00e3o \u00e0 Bras\u00edlia para realizar um curso de capacita\u00e7\u00e3o do Programa Cart\u00e3o Reforma. O treinamento \u00e9 necess\u00e1rio para implementar o funcionamento do programa na cidade. De acordo com Caletti, resumidamente, ser\u00e1 necess\u00e1rio eleger uma ou mais \u00e1reas para mapeamento; mapear as fam\u00edlias que se encaixam nos requisitos; fazer projetos aplic\u00e1veis conforme a necessidade de cada fam\u00edlia; e encaminhar os projetos ao Minist\u00e9rio das Cidades. \u201cAp\u00f3s a aprova\u00e7\u00e3o dos projetos \u00e9 que os cart\u00f5es ser\u00e3o liberados\u201d, ressaltou.<\/p>\n<p><b>Quem pode participar do programa<\/b><br \/>&#8211; Ter renda familiar bruta de at\u00e9 R$ 2.811,00;<br \/>&#8211; Possuir um \u00fanico im\u00f3vel, em todo o territ\u00f3rio nacional;<br \/>&#8211; Ser maior de 18 anos ou emancipado;<br \/>&#8211; Ser propriet\u00e1rio, possuidor ou detentor de im\u00f3vel residencial em \u00e1reas regularizadas ou pass\u00edveis de regulariza\u00e7\u00e3o na forma da lei;<br \/>&#8211; Residir no im\u00f3vel a ser beneficiado;<br \/>&#8211; O im\u00f3vel deve estar localizado dentro das \u00e1reas cadastradas no programa. <\/p>\n<p><b>N\u00e3o podem participar do programa<\/b><br \/>&#8211; Fam\u00edlias residentes em im\u00f3veis alugados ou cedidos;<br \/>&#8211; Im\u00f3veis exclusivamente comerciais;<br \/>&#8211; Im\u00f3veis com precariedade extrema (taipa n\u00e3o revestida, madeira aproveitada, palha);<br \/>&#8211; Im\u00f3vel em conflito fundi\u00e1rio;<br \/>&#8211; Im\u00f3veis em \u00e1reas n\u00e3o pass\u00edveis de regulariza\u00e7\u00e3o, como \u00e1reas de risco.<\/p>\n<p><b>Mais informa\u00e7\u00f5es:<\/b><br \/>www.cartaoreforma.cidades.gov.br\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fam\u00edlias ter\u00e3o subs\u00eddios para comprar materiais e assist\u00eancia t\u00e9cnica<\/p>\n","protected":false},"author":1,"featured_media":382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-381","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mais de 600 fam\u00edlias ter\u00e3o melhorias nas casas - Secretaria de Habita\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mais de 600 fam\u00edlias ter\u00e3o melhorias nas casas - Secretaria de Habita\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Fam\u00edlias ter\u00e3o subs\u00eddios para comprar materiais e assist\u00eancia t\u00e9cnica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Habita\u00e7\u00e3o\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-10T22:52:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-content\/uploads\/sites\/47\/2021\/12\/I2017-05-10_170832_385109.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"465\" \/>\n\t<meta property=\"og:image:height\" content=\"224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/\",\"name\":\"Mais de 600 fam\u00edlias ter\u00e3o melhorias nas casas - Secretaria de Habita\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-content\/uploads\/sites\/47\/2021\/12\/I2017-05-10_170832_385109.jpg\",\"datePublished\":\"2017-05-10T22:52:17+00:00\",\"dateModified\":\"2017-05-10T22:52:17+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-content\/uploads\/sites\/47\/2021\/12\/I2017-05-10_170832_385109.jpg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-content\/uploads\/sites\/47\/2021\/12\/I2017-05-10_170832_385109.jpg\",\"width\":465,\"height\":224},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/\",\"name\":\"Secretaria de Habita\u00e7\u00e3o\",\"description\":\"Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mais de 600 fam\u00edlias ter\u00e3o melhorias nas casas - Secretaria de Habita\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/","og_locale":"pt_BR","og_type":"article","og_title":"Mais de 600 fam\u00edlias ter\u00e3o melhorias nas casas - Secretaria de Habita\u00e7\u00e3o","og_description":"Fam\u00edlias ter\u00e3o subs\u00eddios para comprar materiais e assist\u00eancia t\u00e9cnica","og_url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/","og_site_name":"Secretaria de Habita\u00e7\u00e3o","article_published_time":"2017-05-10T22:52:17+00:00","og_image":[{"width":465,"height":224,"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-content\/uploads\/sites\/47\/2021\/12\/I2017-05-10_170832_385109.jpg","type":"image\/jpeg"}],"author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/","name":"Mais de 600 fam\u00edlias ter\u00e3o melhorias nas casas - Secretaria de Habita\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-content\/uploads\/sites\/47\/2021\/12\/I2017-05-10_170832_385109.jpg","datePublished":"2017-05-10T22:52:17+00:00","dateModified":"2017-05-10T22:52:17+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/2017\/05\/10\/mais-de-600-familias-terao-melhorias-nas-casas-11536\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-content\/uploads\/sites\/47\/2021\/12\/I2017-05-10_170832_385109.jpg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-content\/uploads\/sites\/47\/2021\/12\/I2017-05-10_170832_385109.jpg","width":465,"height":224},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/","name":"Secretaria de Habita\u00e7\u00e3o","description":"Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-json\/wp\/v2\/posts\/381"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-json\/wp\/v2\/comments?post=381"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-json\/wp\/v2\/posts\/381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-json\/wp\/v2\/media\/382"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-json\/wp\/v2\/media?parent=381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-json\/wp\/v2\/categories?post=381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-habitacao\/wp-json\/wp\/v2\/tags?post=381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}