{"id":2167,"date":"2023-07-28T10:51:25","date_gmt":"2023-07-28T13:51:25","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/?p=2167"},"modified":"2023-07-31T10:11:13","modified_gmt":"2023-07-31T13:11:13","slug":"cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/","title":{"rendered":"Caf\u00e9 com Emprego: 800 vagas \u00a0ser\u00e3o ofertadas na 7\u00aa edi\u00e7\u00e3o"},"content":{"rendered":"\n<p><br><br>Para comemorar os 166 anos de Passo Fundo, a Prefeitura promove, na ter\u00e7a-feira (01), a 7\u00aa edi\u00e7\u00e3o do Caf\u00e9 com Emprego. A atividade ser\u00e1 realizada no Clube Comercial, das 8h \u00e0s 14h, e, conforme o prefeito, Pedro Almeida, cerca de 800 vagas de emprego estar\u00e3o dispon\u00edveis ao p\u00fablico. \u201cO Caf\u00e9 com Emprego tem se mostrado uma pol\u00edtica acertada, porque possibilita que os trabalhadores encontrem centenas de oportunidades de trabalho reunidas em um \u00fanico local. \u00c9 mais facilidade para entregar curr\u00edculos, analisar o cen\u00e1rio e tamb\u00e9m participar de di\u00e1logos com os recrutadores das empresas\u201d, comentou ele.<\/p>\n\n\n\n<p>De acordo com o prefeito, o Caf\u00e9 com Emprego, que integra as a\u00e7\u00f5es do programa Acelera Passo Fundo, j\u00e1 inseriu no mercado formal de trabalho aproximadamente 800 pessoas, em diferentes setores produtivos e econ\u00f4micos. \u201cDesde a primeira edi\u00e7\u00e3o, realizada em 2021, observamos um cen\u00e1rio positivo para a gera\u00e7\u00e3o de emprego e o aumento da oportunidade de inser\u00e7\u00e3o das pessoas nas empresas locais. Isso nos estimulou a seguir promovendo e ampliando o projeto, al\u00e9m de nos levar a desenvolver outras iniciativas, como a Escola das Profiss\u00f5es, que qualifica e capacita profissionalmente os passo-fundenses para as demandas do mercado\u201d, declarou Pedro.<\/p>\n\n\n\n<p>Sob responsabilidade da Secretaria de Desenvolvimento Econ\u00f4mico (SDE), a 7\u00aa edi\u00e7\u00e3o do Caf\u00e9 com Emprego, destacou o secret\u00e1rio da SDE, Diorges Oliveira, ter\u00e1 a participa\u00e7\u00e3o de 26 empresas dos segmentos do com\u00e9rcio, servi\u00e7os, ind\u00fastria e tecnologia. \u201cNesta edi\u00e7\u00e3o especial que comemora o anivers\u00e1rio do Munic\u00edpio teremos um espa\u00e7o dedicado para que as pessoas possam se inscrever em mais de 40 cursos de capacita\u00e7\u00e3o profissional\u201d, informou, acrescentando que as vagas de trabalho tamb\u00e9m envolvem oportunidades para Menor Aprendiz, Jovem Aprendiz, est\u00e1gios de ensino m\u00e9dio e superior e para PCD\u2019s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atividade ocorre na ter\u00e7a-feira (01), no Clube Comercial, das 8h \u00e0s 14h, dentro das programa\u00e7\u00f5es alusivas ao anivers\u00e1rio de 166 anos de Passo Fundo<\/p>\n","protected":false},"author":6,"featured_media":2168,"comment_status":"closed","ping_status":"closed","sticky":true,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2167","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Caf\u00e9 com Emprego: 800 vagas \u00a0ser\u00e3o ofertadas na 7\u00aa edi\u00e7\u00e3o - Secretaria de Desenvolvimento Econ\u00f4mico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caf\u00e9 com Emprego: 800 vagas \u00a0ser\u00e3o ofertadas na 7\u00aa edi\u00e7\u00e3o - Secretaria de Desenvolvimento Econ\u00f4mico\" \/>\n<meta property=\"og:description\" content=\"Atividade ocorre na ter\u00e7a-feira (01), no Clube Comercial, das 8h \u00e0s 14h, dentro das programa\u00e7\u00f5es alusivas ao anivers\u00e1rio de 166 anos de Passo Fundo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Desenvolvimento Econ\u00f4mico\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-28T13:51:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-31T13:11:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-content\/uploads\/sites\/27\/2023\/07\/cafe-com-emprego-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"andressazorzetto07\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"andressazorzetto07\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/\",\"name\":\"Caf\u00e9 com Emprego: 800 vagas \u00a0ser\u00e3o ofertadas na 7\u00aa edi\u00e7\u00e3o - Secretaria de Desenvolvimento Econ\u00f4mico\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-content\/uploads\/sites\/27\/2023\/07\/cafe-com-emprego-scaled.jpg\",\"datePublished\":\"2023-07-28T13:51:25+00:00\",\"dateModified\":\"2023-07-31T13:11:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/#\/schema\/person\/30ee1d1bd74da1469b01fcf086e43351\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-content\/uploads\/sites\/27\/2023\/07\/cafe-com-emprego-scaled.jpg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-content\/uploads\/sites\/27\/2023\/07\/cafe-com-emprego-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/\",\"name\":\"Secretaria de Desenvolvimento Econ\u00f4mico\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/#\/schema\/person\/30ee1d1bd74da1469b01fcf086e43351\",\"name\":\"andressazorzetto07\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/14c5458ed79dc81da99a13b9ff5f9f19?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/14c5458ed79dc81da99a13b9ff5f9f19?s=96&d=mm&r=g\",\"caption\":\"andressazorzetto07\"},\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/author\/andressazorzetto07\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caf\u00e9 com Emprego: 800 vagas \u00a0ser\u00e3o ofertadas na 7\u00aa edi\u00e7\u00e3o - Secretaria de Desenvolvimento Econ\u00f4mico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/","og_locale":"pt_BR","og_type":"article","og_title":"Caf\u00e9 com Emprego: 800 vagas \u00a0ser\u00e3o ofertadas na 7\u00aa edi\u00e7\u00e3o - Secretaria de Desenvolvimento Econ\u00f4mico","og_description":"Atividade ocorre na ter\u00e7a-feira (01), no Clube Comercial, das 8h \u00e0s 14h, dentro das programa\u00e7\u00f5es alusivas ao anivers\u00e1rio de 166 anos de Passo Fundo","og_url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/","og_site_name":"Secretaria de Desenvolvimento Econ\u00f4mico","article_published_time":"2023-07-28T13:51:25+00:00","article_modified_time":"2023-07-31T13:11:13+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-content\/uploads\/sites\/27\/2023\/07\/cafe-com-emprego-scaled.jpg","type":"image\/jpeg"}],"author":"andressazorzetto07","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"andressazorzetto07","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/","name":"Caf\u00e9 com Emprego: 800 vagas \u00a0ser\u00e3o ofertadas na 7\u00aa edi\u00e7\u00e3o - Secretaria de Desenvolvimento Econ\u00f4mico","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-content\/uploads\/sites\/27\/2023\/07\/cafe-com-emprego-scaled.jpg","datePublished":"2023-07-28T13:51:25+00:00","dateModified":"2023-07-31T13:11:13+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/#\/schema\/person\/30ee1d1bd74da1469b01fcf086e43351"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/2023\/07\/28\/cafe-com-emprego-800-vagas-serao-ofertadas-na-7a-edicao\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-content\/uploads\/sites\/27\/2023\/07\/cafe-com-emprego-scaled.jpg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-content\/uploads\/sites\/27\/2023\/07\/cafe-com-emprego-scaled.jpg","width":2560,"height":1707},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/","name":"Secretaria de Desenvolvimento Econ\u00f4mico","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/#\/schema\/person\/30ee1d1bd74da1469b01fcf086e43351","name":"andressazorzetto07","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/14c5458ed79dc81da99a13b9ff5f9f19?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/14c5458ed79dc81da99a13b9ff5f9f19?s=96&d=mm&r=g","caption":"andressazorzetto07"},"url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/author\/andressazorzetto07\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-json\/wp\/v2\/posts\/2167"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-json\/wp\/v2\/comments?post=2167"}],"version-history":[{"count":1,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-json\/wp\/v2\/posts\/2167\/revisions"}],"predecessor-version":[{"id":2169,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-json\/wp\/v2\/posts\/2167\/revisions\/2169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-json\/wp\/v2\/media\/2168"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-json\/wp\/v2\/media?parent=2167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-json\/wp\/v2\/categories?post=2167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-desenvolvimento-economico\/wp-json\/wp\/v2\/tags?post=2167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}