{"id":1304,"date":"2022-01-19T15:09:31","date_gmt":"2022-01-19T18:09:31","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/?post_type=downloads&#038;p=1304"},"modified":"2022-01-19T15:09:31","modified_gmt":"2022-01-19T18:09:31","slug":"documentos-da-rede-socioassistencial-privada-do-suas","status":"publish","type":"downloads","link":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/documentos-da-rede-socioassistencial-privada-do-suas\/","title":{"rendered":"Documentos da Rede Socioassistencial Privada do SUAS"},"content":{"rendered":"\n<ul class=\"wp-block-list\"><li><a href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/wp-content\/uploads\/sites\/24\/2021\/11\/suas_entidades_cartilha.pdf\">Cartilha<\/a><\/li><li><a href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/wp-content\/uploads\/sites\/24\/2021\/11\/suas_entidades_relacao.pdf\">Entidades da Rede Socioassistencial<\/a><\/li><\/ul>\n","protected":false},"template":"","class_list":["post-1304","downloads","type-downloads","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Documentos da Rede Socioassistencial Privada do SUAS - Secretaria de Cidadania e Assist\u00eancia Social<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/documentos-da-rede-socioassistencial-privada-do-suas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Documentos da Rede Socioassistencial Privada do SUAS - Secretaria de Cidadania e Assist\u00eancia Social\" \/>\n<meta property=\"og:description\" content=\"Cartilha Entidades da Rede Socioassistencial\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/documentos-da-rede-socioassistencial-privada-do-suas\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Cidadania e Assist\u00eancia Social\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/documentos-da-rede-socioassistencial-privada-do-suas\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/documentos-da-rede-socioassistencial-privada-do-suas\/\",\"name\":\"Documentos da Rede Socioassistencial Privada do SUAS - Secretaria de Cidadania e Assist\u00eancia Social\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/#website\"},\"datePublished\":\"2022-01-19T18:09:31+00:00\",\"dateModified\":\"2022-01-19T18:09:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/documentos-da-rede-socioassistencial-privada-do-suas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/documentos-da-rede-socioassistencial-privada-do-suas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/documentos-da-rede-socioassistencial-privada-do-suas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Downloads\",\"item\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Documentos da Rede Socioassistencial Privada do SUAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/\",\"name\":\"Secretaria de Cidadania e Assist\u00eancia Social\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Documentos da Rede Socioassistencial Privada do SUAS - Secretaria de Cidadania e Assist\u00eancia Social","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/documentos-da-rede-socioassistencial-privada-do-suas\/","og_locale":"pt_BR","og_type":"article","og_title":"Documentos da Rede Socioassistencial Privada do SUAS - Secretaria de Cidadania e Assist\u00eancia Social","og_description":"Cartilha Entidades da Rede Socioassistencial","og_url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/documentos-da-rede-socioassistencial-privada-do-suas\/","og_site_name":"Secretaria de Cidadania e Assist\u00eancia Social","twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/documentos-da-rede-socioassistencial-privada-do-suas\/","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/documentos-da-rede-socioassistencial-privada-do-suas\/","name":"Documentos da Rede Socioassistencial Privada do SUAS - Secretaria de Cidadania e Assist\u00eancia Social","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/#website"},"datePublished":"2022-01-19T18:09:31+00:00","dateModified":"2022-01-19T18:09:31+00:00","breadcrumb":{"@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/documentos-da-rede-socioassistencial-privada-do-suas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/documentos-da-rede-socioassistencial-privada-do-suas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/documentos-da-rede-socioassistencial-privada-do-suas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Downloads","item":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/downloads\/"},{"@type":"ListItem","position":2,"name":"Documentos da Rede Socioassistencial Privada do SUAS"}]},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/","name":"Secretaria de Cidadania e Assist\u00eancia Social","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/wp-json\/wp\/v2\/downloads\/1304"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/wp-json\/wp\/v2\/downloads"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/wp-json\/wp\/v2\/types\/downloads"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cidadania-e-assistencia-social\/wp-json\/wp\/v2\/media?parent=1304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}