{"id":129,"date":"2014-06-30T03:00:00","date_gmt":"2014-06-30T06:00:00","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/financas\/2014\/06\/30\/comissao-para-adequar-sistema-contabil-da-prefeitura-e-nomeada-8359\/"},"modified":"2014-06-30T03:00:00","modified_gmt":"2014-06-30T06:00:00","slug":"comissao-para-adequar-sistema-contabil-da-prefeitura-e-nomeada-8359","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/financas\/2014\/06\/30\/comissao-para-adequar-sistema-contabil-da-prefeitura-e-nomeada-8359\/","title":{"rendered":"Comiss\u00e3o para adequar sistema cont\u00e1bil da Prefeitura \u00e9 nomeada"},"content":{"rendered":"<p align=\"justify\" style=\"margin-bottom: 0cm;\">A comiss\u00e3o respons\u00e1vel por atualizar os processos cont\u00e1beis do munic\u00edpio, na realiza\u00e7\u00e3o do Invent\u00e1rio Patrimonial da Prefeitura de Passo Fundo, foi nomeada pelo prefeito Luciano Azevedo na \u00faltima semana.   <\/p>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\">A a\u00e7\u00e3o \u00e9 determinada para adequar o Sistema Cont\u00e1bil da Prefeitura \u00e0s Normas Internacionais de Contabilidade Aplicadas ao Setor P\u00fablico, al\u00e9m de atender a legisla\u00e7\u00e3o pertinente acerca dos sistemas de contabilidade e controle patrimonial.  <\/p>\n<div align=\"justify\">  <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\">A comiss\u00e3o de 10 pessoas, ligadas \u00e0s secretarias de Finan\u00e7as, Administra\u00e7\u00e3o, Planejamento, Educa\u00e7\u00e3o e Cidadania e Assist\u00eancia Social, ser\u00e1 coordenada pelo presidente Jorge Fernandes de Mattos, da Secretaria de Finan\u00e7as.  <\/p>\n<div align=\"justify\">  <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\">Com a estrutura da equipe, ser\u00e1 feito um cronograma atividades para realiza\u00e7\u00e3o de procedimentos t\u00e9cnicos, a\u00e7\u00f5es operacionais, mensura\u00e7\u00e3o e avalia\u00e7\u00e3o de resultados e atualiza\u00e7\u00e3o Sistema de Informa\u00e7\u00e3o do Patrim\u00f4nio, integrado ao Sistema de Informa\u00e7\u00e3o de Contabilidade. Ainda, um manual de procedimentos internos de movimenta\u00e7\u00e3o de materiais e de procedimentos de  bens patrimoniais est\u00e1 previsto para regularizar os processos.  <\/p>\n<div align=\"justify\">  <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\">O invent\u00e1rio possibilitar\u00e1 a avalia\u00e7\u00e3o de bens patrimoniais e de todos bens e materiais de consumo sob o controle do almoxarifado e das secretarias, al\u00e9m de realizar a mensura\u00e7\u00e3o financeira de bens inventariados, por reavalia\u00e7\u00e3o.<\/p>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\"> <\/p>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\"> <\/p>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\"> <\/p>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\"> <\/p>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\"> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comiss\u00e3o para adequar sistema cont\u00e1bil da Prefeitura \u00e9 nomeada<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comiss\u00e3o para adequar sistema cont\u00e1bil da Prefeitura \u00e9 nomeada - Finan\u00e7as<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/financas\/2014\/06\/30\/comissao-para-adequar-sistema-contabil-da-prefeitura-e-nomeada-8359\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comiss\u00e3o para adequar sistema cont\u00e1bil da Prefeitura \u00e9 nomeada - Finan\u00e7as\" \/>\n<meta property=\"og:description\" content=\"Comiss\u00e3o para adequar sistema cont\u00e1bil da Prefeitura \u00e9 nomeada\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/financas\/2014\/06\/30\/comissao-para-adequar-sistema-contabil-da-prefeitura-e-nomeada-8359\/\" \/>\n<meta property=\"og:site_name\" content=\"Finan\u00e7as\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-30T06:00:00+00:00\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/financas\/2014\/06\/30\/comissao-para-adequar-sistema-contabil-da-prefeitura-e-nomeada-8359\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/financas\/2014\/06\/30\/comissao-para-adequar-sistema-contabil-da-prefeitura-e-nomeada-8359\/\",\"name\":\"Comiss\u00e3o para adequar sistema cont\u00e1bil da Prefeitura \u00e9 nomeada - Finan\u00e7as\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/financas\/#website\"},\"datePublished\":\"2014-06-30T06:00:00+00:00\",\"dateModified\":\"2014-06-30T06:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/financas\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/financas\/2014\/06\/30\/comissao-para-adequar-sistema-contabil-da-prefeitura-e-nomeada-8359\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/financas\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/financas\/\",\"name\":\"Finan\u00e7as\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/financas\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/financas\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/financas\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/financas\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comiss\u00e3o para adequar sistema cont\u00e1bil da Prefeitura \u00e9 nomeada - Finan\u00e7as","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/financas\/2014\/06\/30\/comissao-para-adequar-sistema-contabil-da-prefeitura-e-nomeada-8359\/","og_locale":"pt_BR","og_type":"article","og_title":"Comiss\u00e3o para adequar sistema cont\u00e1bil da Prefeitura \u00e9 nomeada - Finan\u00e7as","og_description":"Comiss\u00e3o para adequar sistema cont\u00e1bil da Prefeitura \u00e9 nomeada","og_url":"https:\/\/www.pmpf.rs.gov.br\/financas\/2014\/06\/30\/comissao-para-adequar-sistema-contabil-da-prefeitura-e-nomeada-8359\/","og_site_name":"Finan\u00e7as","article_published_time":"2014-06-30T06:00:00+00:00","author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/financas\/2014\/06\/30\/comissao-para-adequar-sistema-contabil-da-prefeitura-e-nomeada-8359\/","url":"https:\/\/www.pmpf.rs.gov.br\/financas\/2014\/06\/30\/comissao-para-adequar-sistema-contabil-da-prefeitura-e-nomeada-8359\/","name":"Comiss\u00e3o para adequar sistema cont\u00e1bil da Prefeitura \u00e9 nomeada - Finan\u00e7as","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/financas\/#website"},"datePublished":"2014-06-30T06:00:00+00:00","dateModified":"2014-06-30T06:00:00+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/financas\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/financas\/2014\/06\/30\/comissao-para-adequar-sistema-contabil-da-prefeitura-e-nomeada-8359\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/financas\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/financas\/","name":"Finan\u00e7as","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/financas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/financas\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/financas\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/financas\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/financas\/wp-json\/wp\/v2\/posts\/129"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/financas\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/financas\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/financas\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/financas\/wp-json\/wp\/v2\/comments?post=129"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/financas\/wp-json\/wp\/v2\/posts\/129\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/financas\/wp-json\/wp\/v2\/media?parent=129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/financas\/wp-json\/wp\/v2\/categories?post=129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/financas\/wp-json\/wp\/v2\/tags?post=129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}