{"id":418,"date":"2017-06-30T20:01:55","date_gmt":"2017-06-30T23:01:55","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-extraordinaria-de-esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/"},"modified":"2017-06-30T20:01:55","modified_gmt":"2017-06-30T23:01:55","slug":"mais-de-890-atletas-participam-da-corrida-11744","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/","title":{"rendered":"Mais de 890 atletas participam da corrida"},"content":{"rendered":"<p>Domingo (2) ser\u00e1 o dia da segunda etapa do Circuito Municipal de Corrida de Rua de Passo Fundo. Dessa vez, mais de 890 atletas se inscreveram para participar da prova, que come\u00e7a \u00e0s 9h, com sa\u00edda na Avenida Sete de Setembro, 161, em frente \u00e0 R\u00e1dio Uirapuru. A chegada tamb\u00e9m ser\u00e1 em frente a r\u00e1dio.<\/p>\n<p>A atividade, que \u00e9 promovida pela Secretaria de Esportes da Prefeitura de Passo Fundo, \u00e9 gratuita. Entretanto, \u00e9 solicitada uma contribui\u00e7\u00e3o social como contrapartida dos atletas. Nesta etapa, os competidores devem contribuir com dois quilos de ra\u00e7\u00e3o, sendo um de gato e um de cachorro. Todos os donativos arrecadados ser\u00e3o doados para entidades e colaboradores da causa animal na cidade.<\/p>\n<p>O percurso ser\u00e1 igual ao da primeira etapa. O Circuito Municipal de Corrida de Rua deste ano ser\u00e1 composto de quatro etapas que acontecer\u00e3o ao longo de 2017.<br \/><b><br \/>Entrega dos kits<\/b><br \/>O recebimento dos donativos ser\u00e1 realizado neste s\u00e1bado, 1\u00ba de julho, das 12h \u00e0s 16h, quando ser\u00e3o entregues os kits para a corrida, que cont\u00e9m os chips para os participantes. No domingo (2), das 7h30 \u00e0s 8h15 acontece a entrega para os corredores que v\u00eam de outras cidades. A retirada deve ser feita na Secretaria dos Esportes, que fica na Avenida Brasil, 792, fundos.<\/p>\n<p><b>Servi\u00e7o<\/b><br \/>Circuito Municipal de Corrida de Rua 2017<br \/>Segunda etapa \u2013 dia 2 de julho (domingo)<br \/>Entrega dos kits e donativos \u2013 1\u00ba de julho (s\u00e1bado), das 12h \u00e0s 16h para corredores de Passo Fundo e dia 02 de julho (domingo), das 7h30 \u00e0s 8h15 para participantes de fora da cidade, na Secretaria de Esportes (Avenida Brasil, 792, fundos)<\/p>\n<p><b>(Foto: Arquivo\/PMPF)<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Circuito Municipal de Corrida de Rua deste ano ser\u00e1 composto de quatro etapas<\/p>\n","protected":false},"author":1,"featured_media":419,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mais de 890 atletas participam da corrida - Secretaria de Esportes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mais de 890 atletas participam da corrida - Secretaria de Esportes\" \/>\n<meta property=\"og:description\" content=\"O Circuito Municipal de Corrida de Rua deste ano ser\u00e1 composto de quatro etapas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Esportes\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-30T23:01:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-30_170323_385109.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1632\" \/>\n\t<meta property=\"og:image:height\" content=\"916\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/\",\"name\":\"Mais de 890 atletas participam da corrida - Secretaria de Esportes\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-30_170323_385109.jpg\",\"datePublished\":\"2017-06-30T23:01:55+00:00\",\"dateModified\":\"2017-06-30T23:01:55+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-30_170323_385109.jpg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-30_170323_385109.jpg\",\"width\":1632,\"height\":916},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/\",\"name\":\"Secretaria de Esportes\",\"description\":\"Site Secretaria de Esporte da Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mais de 890 atletas participam da corrida - Secretaria de Esportes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/","og_locale":"pt_BR","og_type":"article","og_title":"Mais de 890 atletas participam da corrida - Secretaria de Esportes","og_description":"O Circuito Municipal de Corrida de Rua deste ano ser\u00e1 composto de quatro etapas","og_url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/","og_site_name":"Secretaria de Esportes","article_published_time":"2017-06-30T23:01:55+00:00","og_image":[{"width":1632,"height":916,"url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-30_170323_385109.jpg","type":"image\/jpeg"}],"author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/","url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/","name":"Mais de 890 atletas participam da corrida - Secretaria de Esportes","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-30_170323_385109.jpg","datePublished":"2017-06-30T23:01:55+00:00","dateModified":"2017-06-30T23:01:55+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/30\/mais-de-890-atletas-participam-da-corrida-11744\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-30_170323_385109.jpg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-30_170323_385109.jpg","width":1632,"height":916},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/","name":"Secretaria de Esportes","description":"Site Secretaria de Esporte da Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/esportes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/posts\/418"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/comments?post=418"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/posts\/418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/media\/419"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/media?parent=418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/categories?post=418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/tags?post=418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}