{"id":406,"date":"2017-06-16T19:44:36","date_gmt":"2017-06-16T22:44:36","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-extraordinaria-de-esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/"},"modified":"2017-06-16T19:44:36","modified_gmt":"2017-06-16T22:44:36","slug":"novos-jogos-do-amador-no-final-de-semana-11687","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/","title":{"rendered":"Novos jogos do Amador no final de semana"},"content":{"rendered":"<p>A 28\u00aa edi\u00e7\u00e3o do Campeonato Municipal de Futebol Amador, organizado pela Secretaria de Esportes da Prefeitura de Passo Fundo, tem rodada neste final semana. Ser\u00e3o quatro jogos entre os dias 17 e 18 de junho. No s\u00e1bado, se enfrentam Boca Junior e Juventus\/Borussia, e Ipiranga e Roma. No domingo ser\u00e1 a vez do Independente enfrentar o BW ATR\/AFC e do Uni\u00e3o enfrentar o Torres.<\/p>\n<p>O Campeonato Municipal de Futebol Amador deste ano conta com a participa\u00e7\u00e3o de 16 equipes, que disputar\u00e3o os jogos que ser\u00e3o realizados no Est\u00e1dio Vermelh\u00e3o da Serra e na Arena do Ga\u00facho. Uma das novidades para este ano \u00e9 que somente cinco atletas de fora do munic\u00edpio poder\u00e3o ser inscritos por equipe. Outra grande conquista, comemorada pelas equipes, \u00e9 a possibilidade de realizar os jogos nos est\u00e1dios que contam com infraestrutura para receber a todos. A realiza\u00e7\u00e3o dos jogos nestes locais era uma reivindica\u00e7\u00e3o antiga, segundo o secret\u00e1rio dos Esportes, Gilberto Bellaver. Conforme ele, um dos objetivos \u00e9 que as fam\u00edlias voltem a frequentar os est\u00e1dios e assistir os jogos.<\/p>\n<p><b>\u00daltimos jogos<\/b><br \/>No final de semana passado, pela Chave A, o Farroupilha venceu o Vila Real por 2 X 0, com gols de Daniel R e Maicon A. No outro jogo do s\u00e1bado (10), tamb\u00e9m pela Chave A, o 13 de Abril venceu o Bahia por 3X0. Todos os gols foram de Rogerson Prates.<\/p>\n<p>No domingo (11), pela Chave B, o Beco Santa Marta venceu o Pumas por 1 X 0, com gol de Lucas S. O outro jogo da Chave B foi Cruzeiro 1 X 0 Revela\u00e7\u00e3o UFA. O gol foi de Dionatan P.<\/p>\n<p><b>Subindo para a primeira divis\u00e3o<\/b><br \/>Os times que permaneceram na primeira divis\u00e3o, dentre eles campe\u00e3o do ano passado, o Vila Real, contam este ano com duas novas equipes participantes, o Beco Santa Marta e o Farroupilha, que foram o campe\u00e3o e vice, respectivamente, da segunda divis\u00e3o. Ao final do certame de 2017, duas equipes ser\u00e3o rebaixadas.<br \/><b><br \/>Pr\u00f3xima rodada<\/p>\n<p>Jogo 5 | Chave B | Dia 17 de junho (s\u00e1bado) | 13h30<\/b><br \/>Local: Est\u00e1dio Vermelh\u00e3o da Serra<br \/>Boca Junior X Juventus\/Borussia<\/p>\n<p><b>Jogo 6 | Chave B | Dia 17 de junho (s\u00e1bado) | 15h45<\/b><br \/>Local: Est\u00e1dio Vermelh\u00e3o da Serra<br \/>Ipiranga X Roma<br \/><b><br \/>Jogo 7 | Chave A | Dia 18 de junho (domingo) | 8h30<\/b><br \/>Local: Est\u00e1dio Vermelh\u00e3o da Serra<br \/>Independente X BW ATR\/AFC<\/p>\n<p><b>Jogo 8 | Chave A | Dia 18 de junho (domingo) | 10h30<\/b><br \/>Local: Est\u00e1dio Vermelh\u00e3o da Serra<br \/>Uni\u00e3o X Torres<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Campeonato Municipal de Futebol Amador deste ano conta com a participa\u00e7\u00e3o de 16 equipes<\/p>\n","protected":false},"author":1,"featured_media":407,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Novos jogos do Amador no final de semana - Secretaria de Esportes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novos jogos do Amador no final de semana - Secretaria de Esportes\" \/>\n<meta property=\"og:description\" content=\"O Campeonato Municipal de Futebol Amador deste ano conta com a participa\u00e7\u00e3o de 16 equipes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Esportes\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-16T22:44:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-16_164627_385109-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/\",\"name\":\"Novos jogos do Amador no final de semana - Secretaria de Esportes\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-16_164627_385109-scaled.jpg\",\"datePublished\":\"2017-06-16T22:44:36+00:00\",\"dateModified\":\"2017-06-16T22:44:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-16_164627_385109-scaled.jpg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-16_164627_385109-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/\",\"name\":\"Secretaria de Esportes\",\"description\":\"Site Secretaria de Esporte da Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novos jogos do Amador no final de semana - Secretaria de Esportes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/","og_locale":"pt_BR","og_type":"article","og_title":"Novos jogos do Amador no final de semana - Secretaria de Esportes","og_description":"O Campeonato Municipal de Futebol Amador deste ano conta com a participa\u00e7\u00e3o de 16 equipes","og_url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/","og_site_name":"Secretaria de Esportes","article_published_time":"2017-06-16T22:44:36+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-16_164627_385109-scaled.jpg","type":"image\/jpeg"}],"author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/","url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/","name":"Novos jogos do Amador no final de semana - Secretaria de Esportes","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-16_164627_385109-scaled.jpg","datePublished":"2017-06-16T22:44:36+00:00","dateModified":"2017-06-16T22:44:36+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/16\/novos-jogos-do-amador-no-final-de-semana-11687\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-16_164627_385109-scaled.jpg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-16_164627_385109-scaled.jpg","width":2560,"height":1707},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/","name":"Secretaria de Esportes","description":"Site Secretaria de Esporte da Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/esportes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/posts\/406"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/comments?post=406"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/posts\/406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/media\/407"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/media?parent=406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/categories?post=406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/tags?post=406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}