{"id":400,"date":"2017-06-06T19:45:16","date_gmt":"2017-06-06T22:45:16","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-extraordinaria-de-esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/"},"modified":"2017-06-06T19:45:16","modified_gmt":"2017-06-06T22:45:16","slug":"entidades-beneficiadas-com-donativos-da-corrida-11653","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/","title":{"rendered":"Entidades beneficiadas com donativos da corrida"},"content":{"rendered":"<p>Integrantes da Secretaria dos Esportes da Prefeitura de Passo Fundo visitaram na tarde desta ter\u00e7a-feira (6) institui\u00e7\u00f5es que atendem idosos na cidade para fazer a entrega dos donativos arrecadados na primeira etapa do Circuito Municipal de Corrida de Rua. Foram cerca de 750 pacotes de fraldas arrecadados, entre geri\u00e1tricas e infantis. Parte do que foi doado para o p\u00fablico adulto foi entregue no Lar da Vov\u00f3 e nos asilos da Funda\u00e7\u00e3o Lucas Ara\u00fajo, o S\u00e3o Jos\u00e9 e o Jo\u00e3o XXIII.<\/p>\n<p>Os donativos foram muito bem recebidos. \u201cCom este tipo de doa\u00e7\u00e3o, \u00e9 poss\u00edvel beneficiar um n\u00famero cada vez maior de pessoas\u201d, comentou Lorena Ribeiro, presidente do Lar da Vov\u00f3. De acordo com ela, qualquer doa\u00e7\u00e3o \u00e9 importante e essa veio a contemplar uma necessidade da institui\u00e7\u00e3o.<\/p>\n<p>Somente neste primeiro dia foram entregues mais de 450 pacotes de fraldas. \u201c\u00c9 sempre muito bom poder ajudar e ir nestes locais e ser t\u00e3o bem recebidos como fomos, d\u00e1 gosto de ajudar\u201d, disse o secret\u00e1rio Gilberto Bellaver. De acordo com ele, ainda ser\u00e3o entregues mais fraldas geri\u00e1tricas em outras institui\u00e7\u00f5es, al\u00e9m das infantis, que ir\u00e3o beneficiar as crian\u00e7as que frequentam as escolas de educa\u00e7\u00e3o infantil do munic\u00edpio.<\/p>\n<p>Nas pr\u00f3ximas etapas do Circuito Municipal de Corrida de Rua ser\u00e3o arrecadados outros donativos, sempre com o intuito de beneficiar institui\u00e7\u00f5es e entidades beneficentes mantidas em Passo Fundo.<\/p>\n<p>(Foto: Divulga\u00e7\u00e3o)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foram cerca de 750 pacotes de fraldas arrecadados, entre geri\u00e1tricas e infantis<\/p>\n","protected":false},"author":1,"featured_media":401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Entidades beneficiadas com donativos da corrida - Secretaria de Esportes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entidades beneficiadas com donativos da corrida - Secretaria de Esportes\" \/>\n<meta property=\"og:description\" content=\"Foram cerca de 750 pacotes de fraldas arrecadados, entre geri\u00e1tricas e infantis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Esportes\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-06T22:45:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-06_164709_385109.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1153\" \/>\n\t<meta property=\"og:image:height\" content=\"892\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/\",\"name\":\"Entidades beneficiadas com donativos da corrida - Secretaria de Esportes\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-06_164709_385109.jpg\",\"datePublished\":\"2017-06-06T22:45:16+00:00\",\"dateModified\":\"2017-06-06T22:45:16+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-06_164709_385109.jpg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-06_164709_385109.jpg\",\"width\":1153,\"height\":892},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/\",\"name\":\"Secretaria de Esportes\",\"description\":\"Site Secretaria de Esporte da Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/esportes\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entidades beneficiadas com donativos da corrida - Secretaria de Esportes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/","og_locale":"pt_BR","og_type":"article","og_title":"Entidades beneficiadas com donativos da corrida - Secretaria de Esportes","og_description":"Foram cerca de 750 pacotes de fraldas arrecadados, entre geri\u00e1tricas e infantis","og_url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/","og_site_name":"Secretaria de Esportes","article_published_time":"2017-06-06T22:45:16+00:00","og_image":[{"width":1153,"height":892,"url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-06_164709_385109.jpg","type":"image\/jpeg"}],"author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/","url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/","name":"Entidades beneficiadas com donativos da corrida - Secretaria de Esportes","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-06_164709_385109.jpg","datePublished":"2017-06-06T22:45:16+00:00","dateModified":"2017-06-06T22:45:16+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/2017\/06\/06\/entidades-beneficiadas-com-donativos-da-corrida-11653\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-06_164709_385109.jpg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-content\/uploads\/sites\/44\/2021\/12\/I2017-06-06_164709_385109.jpg","width":1153,"height":892},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/","name":"Secretaria de Esportes","description":"Site Secretaria de Esporte da Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/esportes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/esportes\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/esportes\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/posts\/400"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/comments?post=400"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/posts\/400\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/media\/401"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/media?parent=400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/categories?post=400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/esportes\/wp-json\/wp\/v2\/tags?post=400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}