{"id":9017,"date":"2023-02-09T10:50:35","date_gmt":"2023-02-09T13:50:35","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/educacao\/?p=9017"},"modified":"2023-02-09T10:50:36","modified_gmt":"2023-02-09T13:50:36","slug":"passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/","title":{"rendered":"<strong>Passo Fundo volta \u00e0s aulas: cerca de 18 mil alunos retornam \u00e0s escolas municipais na segunda-feira (13)<\/strong>"},"content":{"rendered":"\n<p>Na segunda-feira (13), as mais de 70 escolas da Rede Municipal de Educa\u00e7\u00e3o em Passo Fundo ter\u00e3o algum tipo de atividade especial para recepcionar os cerca de 18 mil alunos que retornam \u00e0s aulas nos ensinos Infantil e Fundamental depois do per\u00edodo de f\u00e9rias. Enquanto o ano letivo com os estudantes n\u00e3o inicia, os professores e servidores das institui\u00e7\u00f5es de ensino participam de cursos de forma\u00e7\u00e3o continuada, recebem orienta\u00e7\u00f5es da Secretaria Municipal de Educa\u00e7\u00e3o (SME) e organizam os espa\u00e7os para que, quando os corredores e salas de aula come\u00e7arem a ser ocupados, os projetos e o planejamento pedag\u00f3gico possam ser aplicados.<\/p>\n\n\n\n<p>A expectativa do secret\u00e1rio municipal de Educa\u00e7\u00e3o, Adriano Canabarro Teixeira, \u00e9 de que, em 2023, os programas que v\u00eam sendo trabalhados pelo Munic\u00edpio apresentem indicadores de avan\u00e7os, como as a\u00e7\u00f5es de combate \u00e0 desigualdade educacional, por exemplo, que est\u00e3o pautando diferentes iniciativas dentro da SME desde 2021, quando os alunos come\u00e7aram a retornar, de forma gradual e escalonada, as atividades presenciais nas escolas. \u201cAcreditamos muito nos reflexos positivos das a\u00e7\u00f5es que come\u00e7amos a trabalhar em 2021, quando as escolas voltaram a receber os alunos na modalidade presencial. Desde ent\u00e3o, passamos a trabalhar com a avalia\u00e7\u00e3o diagn\u00f3stica e com refor\u00e7os em projetos de combate \u00e0s desigualdades educacionais. Agora, em 2023, nossa expectativa \u00e9 fazermos avan\u00e7ar outras iniciativas que v\u00e3o ter impacto na forma\u00e7\u00e3o das nossas crian\u00e7as e adolescentes\u201d, avalia Teixeira.<\/p>\n\n\n\n<p>Para ele, os investimentos da gest\u00e3o Pedro Almeida na educa\u00e7\u00e3o e a compreens\u00e3o do governo municipal de que este \u00e9 um setor fundamental para o desenvolvimento de Passo Fundo, resultaram em uma melhoria da aprendizagem dos estudantes que ultrapassa os 16%. \u201cEsse indicador nos revela que as a\u00e7\u00f5es executadas at\u00e9 o momento est\u00e3o gerando efeitos positivos e a tend\u00eancia \u00e9 de que tenhamos percentuais ainda maiores a partir do esfor\u00e7o dos nossos professores e trabalhadores em educa\u00e7\u00e3o, somados aos constantes programas que recebem recursos e aten\u00e7\u00e3o especial da gest\u00e3o do prefeito Pedro\u201d, observa o secret\u00e1rio.<\/p>\n\n\n\n<p>Exemplificando a preocupa\u00e7\u00e3o do governo municipal com a melhoria do ensino em Passo Fundo, o secret\u00e1rio de Educa\u00e7\u00e3o cita um conjunto significativo de atividades envolvendo, por exemplo, a mudan\u00e7a na grade curricular das escolas; os investimentos de mais de R$ 12 milh\u00f5es em infraestrutura para uso pedag\u00f3gico, como notebooks, aperfei\u00e7oamento da rede de internet, tablets e televisores para salas de aula; e as obras de melhorias e reformas em diversas escolas da Rede. \u201cFocamos muito na melhoria das condi\u00e7\u00f5es estruturais das nossas escolas. O prefeito Pedro fez a entrega de tr\u00eas novas escolas, autorizou processos de reformas e amplia\u00e7\u00f5es e tamb\u00e9m garantiu recursos para que fossem qualificados o cabeamento de acesso \u00e0 internet, permitindo com isso que novos projetos pedag\u00f3gicos fossem implementados\u201d, enumera Teixeira.<\/p>\n\n\n\n<p>Entre as obras de reformas e melhorias nas escolas est\u00e1 o investimento de R$ 780 mil na EMEF Urbano Ribas que, de acordo com o secret\u00e1rio, recebeu nova pintura interna e externa, al\u00e9m da substitui\u00e7\u00e3o completa da cobertura do pr\u00e9dio mais velho da escola; troca da parte hidr\u00e1ulica e sanit\u00e1ria, revis\u00e3o el\u00e9trica e reforma do assoalho de todas as salas de aula e das \u00e1reas administrativas, do sagu\u00e3o, do refeit\u00f3rio e dos banheiros.<\/p>\n\n\n\n<p>O secret\u00e1rio cita ainda outros projetos que foram estruturados em 2022 e que ter\u00e3o sequ\u00eancia neste ano letivo, como o processo de gamifica\u00e7\u00e3o das escolas; projetos que conectam os alunos ao futuro, como o Cultura Digital, Pensamento cient\u00edfico e Cidadania Global; e os programas de acelera\u00e7\u00e3o da recupera\u00e7\u00e3o da aprendizagem, atrav\u00e9s de iniciativas como a Cyberliga, Projeto Apoiar e o mapeamento dos resultados das avalia\u00e7\u00f5es de larga escala.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Laborat\u00f3rios de Aprendizagem Criativa<\/strong><\/p>\n\n\n\n<p>Lan\u00e7ados em 2022, os Laborat\u00f3rios de Aprendizagem Criativa (LAC\u2019s) s\u00e3o estruturas da Prefeitura nas escolas de ensino fundamental que buscam estimular e capacitar os alunos para o uso de ferramentas tecnol\u00f3gicas e digitais. O primeiro deles foi instalado na EMEF Daniel Dipp, mas o prefeito, Pedro Almeida, j\u00e1 confirmou que cada EMEF receber\u00e1 uma unidade. Para o secret\u00e1rio de Educa\u00e7\u00e3o, esta a\u00e7\u00e3o vai ampliar a qualidade do ensino ofertado na Rede, valorizando e incentivando aspectos como o pensamento cient\u00edfico. \u201cEstes Laborat\u00f3rios s\u00e3o espa\u00e7os de criatividade e resolu\u00e7\u00e3o de problemas que dar\u00e3o suporte aos professores para propostas pedag\u00f3gicas inovadoras. Junto a este investimento, est\u00e1 prevista a forma\u00e7\u00e3o de professores para apropria\u00e7\u00e3o da infraestrutura em cada escola que receber\u00e1 uma das unidades do LAC\u201d, afirma Teixeira.<\/p>\n\n\n\n<p><strong>Forma\u00e7\u00e3o continuada dos professores<\/strong><\/p>\n\n\n\n<p>Na semana que antecede o retorno dos alunos \u00e0s aulas, os professores e servidores das escolas municipais passaram por processos de forma\u00e7\u00e3o continuada, com atividades de orienta\u00e7\u00e3o e tamb\u00e9m qualifica\u00e7\u00e3o pedag\u00f3gica. Uma delas ocorreu nesta quinta-feira (09), quando os mais de 1,5 mil professores foram recepcionados pelo secret\u00e1rio de Educa\u00e7\u00e3o e pelas equipes diretivas da pasta em um semin\u00e1rio de forma\u00e7\u00e3o.<\/p>\n\n\n\n<p>No in\u00edcio de fevereiro, o prefeito de Passo Fundo deu posse a mais 23 novos professores e tr\u00eas secret\u00e1rios de escolas, que atuar\u00e3o na Rede a partir deste ano letivo de 2023. Conforme Teixeira, a Prefeitura vem buscando ampliar o n\u00famero de educadores e profissionais que atuam nas escolas, garantindo o atendimento das demandas educacionais provocados com o crescimento da procura por vagas no ensino p\u00fablico municipal. \u201cO papel da educa\u00e7\u00e3o, em todas as esferas, \u00e9 essencial para que as crian\u00e7as e jovens se aventurem em um universo cheio de coisas novas. N\u00f3s acreditamos que ela \u00e9 a solu\u00e7\u00e3o para todos os problemas do mundo. A gest\u00e3o municipal tem a Educa\u00e7\u00e3o como um elemento basilar para a transforma\u00e7\u00e3o de Passo Fundo, que j\u00e1 tem uma rede que \u00e9 refer\u00eancia para o Brasil inteiro\u201d, disse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al\u00e9m dos investimentos em tecnologia, implementa\u00e7\u00e3o de projetos pedag\u00f3gicos visando combater as desigualdades educacionais e novos professores empossados, Prefeitura promoveu a\u00e7\u00f5es de melhorias e reformas nas escolas da Rede Municipal de Ensino<\/p>\n","protected":false},"author":14,"featured_media":9018,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33,14],"tags":[42,45,44],"class_list":["post-9017","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidades-educadoras","category-educacao","tag-cidades-educadoras","tag-investimentos-em-tecnologia","tag-volta-as-aulas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Passo Fundo volta \u00e0s aulas: cerca de 18 mil alunos retornam \u00e0s escolas municipais na segunda-feira (13) - Secretaria de Educa\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Passo Fundo volta \u00e0s aulas: cerca de 18 mil alunos retornam \u00e0s escolas municipais na segunda-feira (13) - Secretaria de Educa\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Al\u00e9m dos investimentos em tecnologia, implementa\u00e7\u00e3o de projetos pedag\u00f3gicos visando combater as desigualdades educacionais e novos professores empossados, Prefeitura promoveu a\u00e7\u00f5es de melhorias e reformas nas escolas da Rede Municipal de Ensino\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Educa\u00e7\u00e3o\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-09T13:50:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-09T13:50:36+00:00\" \/>\n<meta name=\"author\" content=\"crispuhll\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"crispuhll\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/\",\"name\":\"Passo Fundo volta \u00e0s aulas: cerca de 18 mil alunos retornam \u00e0s escolas municipais na segunda-feira (13) - Secretaria de Educa\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2023\/02\/4cebedbb-715c-42db-aa4c-f83a202acb17.jpg\",\"datePublished\":\"2023-02-09T13:50:35+00:00\",\"dateModified\":\"2023-02-09T13:50:36+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/d5e03c9407acc37371a3fc616069ca6b\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2023\/02\/4cebedbb-715c-42db-aa4c-f83a202acb17.jpg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2023\/02\/4cebedbb-715c-42db-aa4c-f83a202acb17.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/\",\"name\":\"Secretaria de Educa\u00e7\u00e3o\",\"description\":\"Secretaria de Educa\u00e7\u00e3o da cidade de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/d5e03c9407acc37371a3fc616069ca6b\",\"name\":\"crispuhll\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/345741ad9625b2854df5b938a77f8d85?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/345741ad9625b2854df5b938a77f8d85?s=96&d=mm&r=g\",\"caption\":\"crispuhll\"},\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/author\/crispuhll\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Passo Fundo volta \u00e0s aulas: cerca de 18 mil alunos retornam \u00e0s escolas municipais na segunda-feira (13) - Secretaria de Educa\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/","og_locale":"pt_BR","og_type":"article","og_title":"Passo Fundo volta \u00e0s aulas: cerca de 18 mil alunos retornam \u00e0s escolas municipais na segunda-feira (13) - Secretaria de Educa\u00e7\u00e3o","og_description":"Al\u00e9m dos investimentos em tecnologia, implementa\u00e7\u00e3o de projetos pedag\u00f3gicos visando combater as desigualdades educacionais e novos professores empossados, Prefeitura promoveu a\u00e7\u00f5es de melhorias e reformas nas escolas da Rede Municipal de Ensino","og_url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/","og_site_name":"Secretaria de Educa\u00e7\u00e3o","article_published_time":"2023-02-09T13:50:35+00:00","article_modified_time":"2023-02-09T13:50:36+00:00","author":"crispuhll","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"crispuhll","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/","url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/","name":"Passo Fundo volta \u00e0s aulas: cerca de 18 mil alunos retornam \u00e0s escolas municipais na segunda-feira (13) - Secretaria de Educa\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2023\/02\/4cebedbb-715c-42db-aa4c-f83a202acb17.jpg","datePublished":"2023-02-09T13:50:35+00:00","dateModified":"2023-02-09T13:50:36+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/d5e03c9407acc37371a3fc616069ca6b"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2023\/02\/09\/passo-fundo-volta-as-aulas-cerca-de-18-mil-alunos-retornam-as-escolas-municipais-na-segunda-feira-13\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2023\/02\/4cebedbb-715c-42db-aa4c-f83a202acb17.jpg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2023\/02\/4cebedbb-715c-42db-aa4c-f83a202acb17.jpg","width":1600,"height":900},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/","name":"Secretaria de Educa\u00e7\u00e3o","description":"Secretaria de Educa\u00e7\u00e3o da cidade de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/educacao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/d5e03c9407acc37371a3fc616069ca6b","name":"crispuhll","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/345741ad9625b2854df5b938a77f8d85?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/345741ad9625b2854df5b938a77f8d85?s=96&d=mm&r=g","caption":"crispuhll"},"url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/author\/crispuhll\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/9017"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/comments?post=9017"}],"version-history":[{"count":1,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/9017\/revisions"}],"predecessor-version":[{"id":9019,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/9017\/revisions\/9019"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/media\/9018"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/media?parent=9017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/categories?post=9017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/tags?post=9017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}