{"id":7443,"date":"2014-06-10T03:00:00","date_gmt":"2014-06-10T06:00:00","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/"},"modified":"2014-06-10T03:00:00","modified_gmt":"2014-06-10T06:00:00","slug":"prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/","title":{"rendered":"Prefeitura entrega duas escolas e abre 240 novas vagas na Educa\u00e7\u00e3o Infantil"},"content":{"rendered":"<p>Passo Fundo ganhou duas novas escolas de Educa\u00e7\u00e3o, no Loteamento Menino Deus, com a EMEI Menino Deus \u2013 Professor Bandana, e na Vila Mattos, com a EMEI Toquinho de Gente. Com as duas escolas, s\u00e3o abertas 240 novas vagas para garantir uma educa\u00e7\u00e3o de qualidade no munic\u00edpio.<\/p>\n<p>\u201c\u00c9 um passo importante entregar essas duas escolas e abrir mais 240 vagas para atender a demanda da comunidade\u201d, ressaltou o prefeito Luciano Azevedo ao entregar as escolas. Para a constru\u00e7\u00e3o da Escola Menino Deus, foram investidos mais de R$ 700 mil, entre recursos do Governo Federal e do munic\u00edpio.<\/p>\n<p>No total, a Prefeitura de Passo Fundo j\u00e1 criou mais de 900 vagas na rede municipal de ensino, com o objetivo de atender a necessidade dos pais e da comunidade escolar. Para a moradora do Menino Deus, Maria Helena Tonelero, a escola \u00e9 um sonho realizado. \u201c\u00c9 um dia maravilhoso. Eu vou voltar a trabalhar porque terei onde deixar meus dois filhos. \u00c9 um sonho que se realizou\u201d, disse.<\/p>\n<p>A diretora da EMEI Menino Deus, Jana\u00edna de Castro Nunes, est\u00e1 ansiosa para iniciar o trabalho. \u201c\u00c9 sempre bom ter mais vagas para atender as crian\u00e7as, que agora passam a frequentar a escola. Vamos fazer um \u00f3timo trabalho\u201d, observou. O pedido pela escola era aguardado h\u00e1 mais de oito anos pela comunidade. Na Villa Mattos, n\u00e3o \u00e9 diferente. A escola, instalada em um espa\u00e7o alugado pela Prefeitura, atender\u00e1 a necessidade dos moradores de toda regi\u00e3o. \u201cQueremos uma comunidade participativa e que ajude a construir um espa\u00e7o para as crian\u00e7as, que s\u00e3o nossas protagonistas e nosso bem maior\u201d, disse a diretora da EMEI Toquinho de Gente, Taniamar Helena Reschke.<\/p>\n<p>Inscri\u00e7\u00f5es<br \/>Para realizar as inscri\u00e7\u00f5es, os pais ou respons\u00e1veis precisam apresentar certid\u00e3o de nascimento da crian\u00e7a, documento de identidade do respons\u00e1vel e comprovante de endere\u00e7o atual, em nome do respons\u00e1vel pela crian\u00e7a. O prazo de inscri\u00e7\u00f5es tem in\u00edcio no dia 16 de junho (segunda-feira), em ambas as escolas. Acompanhe o cronograma:<\/p>\n<p>EMEI Menino Deus \u2013 Professor Bandana (Loteamento Menino Deus): as inscri\u00e7\u00f5es ser\u00e3o realizadas das 9h \u00e0s 11h30min e das 14h \u00e0s 16h30min.<br \/>16\/06 \u2013 Ber\u00e7\u00e1rio: crian\u00e7as de 6 meses a 2 anos.<br \/>18\/06 \u2013 Maternal I: crian\u00e7as de 2 a 3 anos.<br \/>20\/06 \u2013 Maternal II: crian\u00e7as de 3 a 4 anos.<br \/>23\/06 \u2013 Pr\u00e9 I: crian\u00e7as de 4 a 5 anos.<br \/>25\/06 \u2013 Pr\u00e9 II: crian\u00e7as de 5 a 6 anos.<\/p>\n<p>EMEI Toquinho de Gente (Vila Mattos): as inscri\u00e7\u00f5es ser\u00e3o realizadas das 13h \u00e0s 17h.<br \/>16\/06 e 17\/06 \u2013 Maternal II: crian\u00e7as de 3 a 4 anos.<br \/>18\/06 e 20\/06 \u2013 Pr\u00e9 I: crian\u00e7as 4 a 5 anos.<br \/>23\/06 e 24\/06 \u2013 Pr\u00e9 II: crian\u00e7as 5 a 6 anos.<\/p>\n<p>Mais informa\u00e7\u00f5es pelo telefone da Secretaria Municipal de Educa\u00e7\u00e3o (54) 3316-7182.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Passo Fundo ganhou duas novas escolas de Educa\u00e7\u00e3o, no Loteamento Menino Deus, com a EMEI Menino Deus \u2013 Professor Bandana, e na Vila Mattos, com a EMEI Toquinho de Gente<\/p>\n","protected":false},"author":1,"featured_media":2313,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prefeitura entrega duas escolas e abre 240 novas vagas na Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeitura entrega duas escolas e abre 240 novas vagas na Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Passo Fundo ganhou duas novas escolas de Educa\u00e7\u00e3o, no Loteamento Menino Deus, com a EMEI Menino Deus \u2013 Professor Bandana, e na Vila Mattos, com a EMEI Toquinho de Gente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Educa\u00e7\u00e3o\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-10T06:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-09-12_052620_c10877.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"233\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/\",\"name\":\"Prefeitura entrega duas escolas e abre 240 novas vagas na Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-09-12_052620_c10877.jpg\",\"datePublished\":\"2014-06-10T06:00:00+00:00\",\"dateModified\":\"2014-06-10T06:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-09-12_052620_c10877.jpg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-09-12_052620_c10877.jpg\",\"width\":350,\"height\":233},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/\",\"name\":\"Secretaria de Educa\u00e7\u00e3o\",\"description\":\"Secretaria de Educa\u00e7\u00e3o da cidade de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeitura entrega duas escolas e abre 240 novas vagas na Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeitura entrega duas escolas e abre 240 novas vagas na Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o","og_description":"Passo Fundo ganhou duas novas escolas de Educa\u00e7\u00e3o, no Loteamento Menino Deus, com a EMEI Menino Deus \u2013 Professor Bandana, e na Vila Mattos, com a EMEI Toquinho de Gente","og_url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/","og_site_name":"Secretaria de Educa\u00e7\u00e3o","article_published_time":"2014-06-10T06:00:00+00:00","og_image":[{"width":350,"height":233,"url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-09-12_052620_c10877.jpg","type":"image\/jpeg"}],"author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/","url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/","name":"Prefeitura entrega duas escolas e abre 240 novas vagas na Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-09-12_052620_c10877.jpg","datePublished":"2014-06-10T06:00:00+00:00","dateModified":"2014-06-10T06:00:00+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/06\/10\/prefeitura-entrega-duas-escolas-e-abre-240-novas-vagas-na-educacao-infantil-8211\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-09-12_052620_c10877.jpg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-09-12_052620_c10877.jpg","width":350,"height":233},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/","name":"Secretaria de Educa\u00e7\u00e3o","description":"Secretaria de Educa\u00e7\u00e3o da cidade de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/educacao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/7443"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/comments?post=7443"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/7443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/media\/2313"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/media?parent=7443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/categories?post=7443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/tags?post=7443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}