{"id":7212,"date":"2014-04-08T03:00:00","date_gmt":"2014-04-08T06:00:00","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/"},"modified":"2014-04-08T03:00:00","modified_gmt":"2014-04-08T06:00:00","slug":"escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/","title":{"rendered":"Escolas municipais recebem kits do Programa Mundo da Leitura"},"content":{"rendered":"<div align=\"justify\">A parceria firmada entre a Funda\u00e7\u00e3o Universidade de Passo Fundo (FUPF) e a Prefeitura de Passo Fundo tem o objetivo de incentivar o envolvimento de alunos e professores com conte\u00fados de diferentes \u00e1reas do conhecimento, por meio da linguagem televisiva. O trabalho relevante divulgado na comunidade fez surgir o projeto de extens\u00e3o Mundo da Leitura, modos de ler o contexto das escolas municipais, destinado \u00e0s pr\u00e1ticas de letramento e forma\u00e7\u00e3o do leitor, orientados com kits do Programa Mundo da Leitura na TV.    <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\" class=\"western\">Para dar continuidade \u00e0 a\u00e7\u00e3o, a entrega dos kits do programa foi realizada na tarde dessa ter\u00e7a-feira (7). Ao todo, 15 escolas municipais receberam o kit com 9 DVDs com 34 epis\u00f3dios e o Guia de Atividades III. O Programa Mundo da Leitura \u00e9 destaque do Canal Futura, sendo o programa que mais recebe cartas e e-mails dos telespectadores, mais de tr\u00eas mil ao m\u00eas. Para Passo Fundo, Capital Nacional da Literatura, a iniciativa \u00e9 motivo de satisfa\u00e7\u00e3o ao unir educa\u00e7\u00e3o, comunica\u00e7\u00e3o e cultura.  <\/p>\n<div align=\"justify\">  <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\" class=\"western\">A equipe do Mundo da Leitura e da UPFTV contam com a participa\u00e7\u00e3o e acompanhamento dos alunos do Curso de Letras da UPF e monitores do Centro Refer\u00eancia nas a\u00e7\u00f5es de leitura que ocorrem nos espa\u00e7os das escolas parceiras e nos ambientes do Mundo da Leitura, localizado no campus I da UPF. Os roteiros do programa s\u00e3o feitos pelo professor e doutor Paulo Becker.  <\/p>\n<div align=\"justify\">  <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\" class=\"western\">Para a coordenadora das Jornadas Liter\u00e1rias e do Mundo da Leitura, Tania R\u00f6sing, vivenciar a uni\u00e3o da educa\u00e7\u00e3o e da cultura foi o desafio para criar o programa. \u201c\u00c9 uma oportunidade para os professores usarem outra linguagem em sala de aula e serem divulgadores deste material fant\u00e1stico. Agradecemos a Prefeitura e sua equipe e aos professores e diretores por serem nosso parceiros.  Pedimos que voc\u00eas dinamizem, usem este material, pois com cr\u00edticas e trabalho estaremos crescendo\u201d, disse.  <\/p>\n<div align=\"justify\">  <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\" class=\"western\">O secret\u00e1rio municipal de Educa\u00e7\u00e3o, professor Edemilson Brand\u00e3o, ressalta a qualidade do conte\u00fado produzido pelo programa. \u201cAcreditamos muito neste projeto e no efeito que isso provoca. A proposta do Mundo da Leitura mostra a dedica\u00e7\u00e3o e empenho na produ\u00e7\u00e3o deste material entregue \u00e0s escolas. Pedimos aos professores que abracem a ideia e aproveitem muito esta oportunidade\u201d, disse.  <\/p>\n<div align=\"justify\">  <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\" class=\"western\">O vice-prefeito Juliano Roso tamb\u00e9m destaca a singularidade do Mundo da Leitura e sugere a participa\u00e7\u00e3o mais efetiva dos alunos no que se refere ao contato com o programa. \u201cO Mundo da Leitura \u00e9 altamente respeitado, um orgulho para n\u00f3s. Vamos organizar um calend\u00e1rio de visita\u00e7\u00e3o  das escolas com o \u00f4nibus Conhecendo Passo Fundo. \u00c9 importante que nossos alunos possam interagir e conhecer melhor esta iniciativa\u201d, finalizou.  <\/p>\n<div align=\"justify\">  <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\" class=\"western\">O conv\u00eanio para levar o programa para a sala de aula foi firmado ainda em 2004, entre a Funda\u00e7\u00e3o Universidade de Passo Fundo (FUPF), por meio do Centro de Refer\u00eancia e Multimeios\/UPFTV, e a Prefeitura de Passo Fundo, atrav\u00e9s da Secretaria de Educa\u00e7\u00e3o.  <\/p>\n<div align=\"justify\">  <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm;\" class=\"western\"><b>Um mundo <\/b> <\/p>\n<div align=\"justify\">O Mundo da Leitura \u00e9 um programa de TV produzido pela Universidade de Passo Fundo e exibido nacionalmente no Canal Futura. As aventuras de Gali-Leu e sua turma s\u00e3o elaboradas por uma equipe interdisciplinar que envolve os cursos de Letras, Artes e Comunica\u00e7\u00e3o, Educa\u00e7\u00e3o, Ci\u00eancias Exatas e a UPFTV.      <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ao todo, 15 escolas municipais receberam o kit com 9 DVDs com 34 epis\u00f3dios e o Guia de Atividades III<\/p>\n","protected":false},"author":1,"featured_media":1977,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Escolas municipais recebem kits do Programa Mundo da Leitura - Secretaria de Educa\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escolas municipais recebem kits do Programa Mundo da Leitura - Secretaria de Educa\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Ao todo, 15 escolas municipais receberam o kit com 9 DVDs com 34 epis\u00f3dios e o Guia de Atividades III\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Educa\u00e7\u00e3o\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-08T06:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-05-20_041903_c10762.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"264\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/\",\"name\":\"Escolas municipais recebem kits do Programa Mundo da Leitura - Secretaria de Educa\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-05-20_041903_c10762.jpg\",\"datePublished\":\"2014-04-08T06:00:00+00:00\",\"dateModified\":\"2014-04-08T06:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-05-20_041903_c10762.jpg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-05-20_041903_c10762.jpg\",\"width\":350,\"height\":264},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/\",\"name\":\"Secretaria de Educa\u00e7\u00e3o\",\"description\":\"Secretaria de Educa\u00e7\u00e3o da cidade de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escolas municipais recebem kits do Programa Mundo da Leitura - Secretaria de Educa\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/","og_locale":"pt_BR","og_type":"article","og_title":"Escolas municipais recebem kits do Programa Mundo da Leitura - Secretaria de Educa\u00e7\u00e3o","og_description":"Ao todo, 15 escolas municipais receberam o kit com 9 DVDs com 34 epis\u00f3dios e o Guia de Atividades III","og_url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/","og_site_name":"Secretaria de Educa\u00e7\u00e3o","article_published_time":"2014-04-08T06:00:00+00:00","og_image":[{"width":350,"height":264,"url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-05-20_041903_c10762.jpg","type":"image\/jpeg"}],"author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/","url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/","name":"Escolas municipais recebem kits do Programa Mundo da Leitura - Secretaria de Educa\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-05-20_041903_c10762.jpg","datePublished":"2014-04-08T06:00:00+00:00","dateModified":"2014-04-08T06:00:00+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/08\/escolas-municipais-recebem-kits-do-programa-mundo-da-leitura-8074\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-05-20_041903_c10762.jpg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-05-20_041903_c10762.jpg","width":350,"height":264},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/","name":"Secretaria de Educa\u00e7\u00e3o","description":"Secretaria de Educa\u00e7\u00e3o da cidade de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/educacao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/7212"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/comments?post=7212"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/7212\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/media\/1977"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/media?parent=7212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/categories?post=7212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/tags?post=7212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}