{"id":6256,"date":"2014-04-09T03:00:00","date_gmt":"2014-04-09T06:00:00","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/09\/prefeitura-chama-professores-para-educacao-infantil-8146\/"},"modified":"2014-04-09T03:00:00","modified_gmt":"2014-04-09T06:00:00","slug":"prefeitura-chama-professores-para-educacao-infantil-8146","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/09\/prefeitura-chama-professores-para-educacao-infantil-8146\/","title":{"rendered":"Prefeitura chama professores para Educa\u00e7\u00e3o Infantil"},"content":{"rendered":"<p class=\"western\" align=\"CENTER\" style=\"text-align: left; margin-bottom: 0cm;\"><span style=\" \">O prefeito Luciano Azevedo autorizou para esta quinta-feira (10), a publica\u00e7\u00e3o de edital de convoca\u00e7\u00e3o para os professores aprovados no Concurso do Magist\u00e9rio. Ser\u00e3o chamados 18 professores que devem preencher vagas na Educa\u00e7\u00e3o Infantil da rede municipal de ensino.<\/span><\/p>\n<p class=\"western\" align=\"JUSTIFY\" style=\"margin-bottom: 0cm;\"><span style=\" \">A Secretaria Municipal de Educa\u00e7\u00e3o &#8211; SME, realizou levantamento t\u00e9cnico para identificar as demandas existentes nas 27 escolas de Educa\u00e7\u00e3o Infantil (EMEIS). Como resultado, foi constatado a necessidade de nomear professores para cargos vagos, devido a aposentadorias e licen\u00e7as.<\/span><\/p>\n<p class=\"western\" align=\"JUSTIFY\" style=\"margin-bottom: 0cm;\"><span style=\" \">O <\/span><span style=\" \">secret\u00e1rio de Educa\u00e7\u00e3o, Edemilson Brand\u00e3o, destaca que com a amplia\u00e7\u00e3o das escolas que est\u00e3o sendo constru\u00eddas na cidade, existir\u00e1 a necessidade urgente de novos professores. \u201c<\/span><span style=\" \">Conforme vamos inaugurando as escolas, novas necessidades s\u00e3o apresentadas. Por isso, o prefeito Luciano determinar\u00e1 nova chamada de professores concursados, <\/span><span style=\" \">para garantir a qualidade do ensino \u00e0s nossas crian\u00e7as<\/span><span style=\" \">\u201d.<\/span><\/p>\n<p class=\"western\" align=\"JUSTIFY\" style=\"margin-bottom: 0cm;\"><span style=\" \">Ap\u00f3s a publica\u00e7\u00e3o do edital, os concursados dever\u00e3o proceder com os tr\u00e2mites legais junto ao <\/span><span style=\" \">setor de recursos humanos da Prefeitura e da Secretaria de Educa\u00e7\u00e3o &#8211; <\/span><span style=\" \">SME<\/span><span style=\" \">. N<\/span><span style=\" \">o prazo aproximado de 30 dias, os novos <\/span><span style=\" \">professores nomeados <\/span><span style=\" \">j\u00e1 <\/span><span style=\" \">desenvolver\u00e3o<\/span><span style=\" \"> as tarefas na rede municipal de ensino.<\/span><\/p>\n<p class=\"western\" align=\"JUSTIFY\" style=\"margin-bottom: 0cm;\"><span style=\" \">Com a nova chamada de professores concursados para Educa\u00e7\u00e3o Infantil, a administra\u00e7\u00e3o j\u00e1 totaliza 72 professores nomeados para atender a rede de ensino municipal.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prefeitura chama professores para Educa\u00e7\u00e3o Infantil<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prefeitura chama professores para Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/09\/prefeitura-chama-professores-para-educacao-infantil-8146\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeitura chama professores para Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Prefeitura chama professores para Educa\u00e7\u00e3o Infantil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/09\/prefeitura-chama-professores-para-educacao-infantil-8146\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Educa\u00e7\u00e3o\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-09T06:00:00+00:00\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/09\/prefeitura-chama-professores-para-educacao-infantil-8146\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/09\/prefeitura-chama-professores-para-educacao-infantil-8146\/\",\"name\":\"Prefeitura chama professores para Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website\"},\"datePublished\":\"2014-04-09T06:00:00+00:00\",\"dateModified\":\"2014-04-09T06:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/09\/prefeitura-chama-professores-para-educacao-infantil-8146\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/\",\"name\":\"Secretaria de Educa\u00e7\u00e3o\",\"description\":\"Secretaria de Educa\u00e7\u00e3o da cidade de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeitura chama professores para Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/09\/prefeitura-chama-professores-para-educacao-infantil-8146\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeitura chama professores para Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o","og_description":"Prefeitura chama professores para Educa\u00e7\u00e3o Infantil","og_url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/09\/prefeitura-chama-professores-para-educacao-infantil-8146\/","og_site_name":"Secretaria de Educa\u00e7\u00e3o","article_published_time":"2014-04-09T06:00:00+00:00","author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/09\/prefeitura-chama-professores-para-educacao-infantil-8146\/","url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/09\/prefeitura-chama-professores-para-educacao-infantil-8146\/","name":"Prefeitura chama professores para Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website"},"datePublished":"2014-04-09T06:00:00+00:00","dateModified":"2014-04-09T06:00:00+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/04\/09\/prefeitura-chama-professores-para-educacao-infantil-8146\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/","name":"Secretaria de Educa\u00e7\u00e3o","description":"Secretaria de Educa\u00e7\u00e3o da cidade de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/educacao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/6256"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/comments?post=6256"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/6256\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/media?parent=6256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/categories?post=6256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/tags?post=6256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}