{"id":6247,"date":"2014-05-21T03:00:00","date_gmt":"2014-05-21T06:00:00","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/"},"modified":"2014-05-21T03:00:00","modified_gmt":"2014-05-21T06:00:00","slug":"projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/","title":{"rendered":"Projeto Baby Ballet leva a dan\u00e7a para escola municipal de Educa\u00e7\u00e3o Infantil"},"content":{"rendered":"<p align=\"justify\" style=\"margin-bottom: 0cm; line-height: 100%;\" class=\"western\"> Uma forma de express\u00e3o e constru\u00e7\u00e3o da identidade atrav\u00e9s do bal\u00e9. \u00c9 assim que o projeto Baby Ballet, desenvolvido na Escola Municipal de Educa\u00e7\u00e3o Infantil Padre Pergentino Dalmagro, no Parque Farroupilha, se destaca entre as atividades preferidas dos alunos. Idealizado pela professora Alice Martins, que estuda a dan\u00e7a desde a inf\u00e2ncia, o projeto j\u00e1 completou tr\u00eas anos e conta com o apoio integral da Prefeitura de Passo Fundo   <\/p>\n<div align=\"justify\"> <\/div>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm; line-height: 100%;\" class=\"western\"> Segundo Alice, as atividades t\u00eam como principal objetivo o bem estar dos alunos. \u201cEm primeiro lugar, a crian\u00e7a deve se sentir bem ao realizar a atividade, para a partir da\u00ed, se expressar de maneira criativa atrav\u00e9s da dan\u00e7a\u201d, salientou.  <\/p>\n<div align=\"justify\"> <\/div>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm; line-height: 100%;\" class=\"western\"> Durante as aulas, s\u00e3o trabalhados os primeiros passos do bal\u00e9, al\u00e9m das terminologias, no\u00e7\u00f5es de postura, express\u00e3o corporal, coordena\u00e7\u00e3o motora, criatividade, interpreta\u00e7\u00e3o e socializa\u00e7\u00e3o.  O projeto atende cerca de 30 meninas na escola, com idade entre tr\u00eas e seis anos.  <\/p>\n<div align=\"justify\"> <\/div>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm; line-height: 100%;\" class=\"western\"> Para a professora Soeli Santos, diretora da EMEI Padre Pergentino Dalmagro, as aulas de bal\u00e9 t\u00eam auxiliado na autoestima das crian\u00e7as e at\u00e9 mesmo na dos pais. \u201cPodemos perceber a evolu\u00e7\u00e3o das crian\u00e7as e cada vez mais os pais est\u00e3o interessados na participa\u00e7\u00e3o dos filhos no projeto\u201d, disse Soeli.<\/p>\n<div align=\"justify\"> <\/div>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm; line-height: 100%;\" class=\"western\"> As alunas j\u00e1 participaram de eventos como a Passodan\u00e7a e do Semin\u00e1rio Municipal de Educa\u00e7\u00e3o Infantil de Passo Fundo. O projeto que atende 250 crian\u00e7as ao todo, tamb\u00e9m \u00e9 desenvolvido em outras escolas p\u00fablicas e particulares.  <\/p>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm; line-height: 100%;\" class=\"western\"> <\/p>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm; line-height: 100%;\" class=\"western\"> <\/p>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"margin-bottom: 0cm; line-height: 100%;\" class=\"western\"> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O projeto desenvolvido na Escola Padre Pergentino Dalmagro atende a uma turma de 30 meninas com aulas de bal\u00e9<\/p>\n","protected":false},"author":1,"featured_media":628,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Projeto Baby Ballet leva a dan\u00e7a para escola municipal de Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projeto Baby Ballet leva a dan\u00e7a para escola municipal de Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"O projeto desenvolvido na Escola Padre Pergentino Dalmagro atende a uma turma de 30 meninas com aulas de bal\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Educa\u00e7\u00e3o\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-21T06:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-09-12_052620_c10843.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"263\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/\",\"name\":\"Projeto Baby Ballet leva a dan\u00e7a para escola municipal de Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-09-12_052620_c10843.jpg\",\"datePublished\":\"2014-05-21T06:00:00+00:00\",\"dateModified\":\"2014-05-21T06:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-09-12_052620_c10843.jpg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-09-12_052620_c10843.jpg\",\"width\":350,\"height\":263},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/\",\"name\":\"Secretaria de Educa\u00e7\u00e3o\",\"description\":\"Secretaria de Educa\u00e7\u00e3o da cidade de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projeto Baby Ballet leva a dan\u00e7a para escola municipal de Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/","og_locale":"pt_BR","og_type":"article","og_title":"Projeto Baby Ballet leva a dan\u00e7a para escola municipal de Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o","og_description":"O projeto desenvolvido na Escola Padre Pergentino Dalmagro atende a uma turma de 30 meninas com aulas de bal\u00e9","og_url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/","og_site_name":"Secretaria de Educa\u00e7\u00e3o","article_published_time":"2014-05-21T06:00:00+00:00","og_image":[{"width":350,"height":263,"url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-09-12_052620_c10843.jpg","type":"image\/jpeg"}],"author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/","url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/","name":"Projeto Baby Ballet leva a dan\u00e7a para escola municipal de Educa\u00e7\u00e3o Infantil - Secretaria de Educa\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-09-12_052620_c10843.jpg","datePublished":"2014-05-21T06:00:00+00:00","dateModified":"2014-05-21T06:00:00+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/2014\/05\/21\/projeto-baby-ballet-leva-a-danca-para-escola-municipal-de-educacao-infantil-8229\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-09-12_052620_c10843.jpg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-content\/uploads\/sites\/43\/2021\/12\/I2014-09-12_052620_c10843.jpg","width":350,"height":263},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/","name":"Secretaria de Educa\u00e7\u00e3o","description":"Secretaria de Educa\u00e7\u00e3o da cidade de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/educacao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/6247"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/comments?post=6247"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts\/6247\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/media\/628"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/media?parent=6247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/categories?post=6247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/tags?post=6247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}