{"id":33,"count":14,"description":"","link":"https:\/\/www.pmpf.rs.gov.br\/educacao\/category\/cidades-educadoras\/","name":"Cidades Educadoras","slug":"cidades-educadoras","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivos Cidades Educadoras - Secretaria de Educa\u00e7\u00e3o<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/educacao\/category\/cidades-educadoras\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivos Cidades Educadoras - Secretaria de Educa\u00e7\u00e3o\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/educacao\/category\/cidades-educadoras\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Educa\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/category\/cidades-educadoras\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/category\/cidades-educadoras\/\",\"name\":\"Arquivos Cidades Educadoras - Secretaria de Educa\u00e7\u00e3o\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/\",\"name\":\"Secretaria de Educa\u00e7\u00e3o\",\"description\":\"Secretaria de Educa\u00e7\u00e3o da cidade de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/educacao\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivos Cidades Educadoras - Secretaria de Educa\u00e7\u00e3o","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/educacao\/category\/cidades-educadoras\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivos Cidades Educadoras - Secretaria de Educa\u00e7\u00e3o","og_url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/category\/cidades-educadoras\/","og_site_name":"Secretaria de Educa\u00e7\u00e3o","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/category\/cidades-educadoras\/","url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/category\/cidades-educadoras\/","name":"Arquivos Cidades Educadoras - Secretaria de Educa\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website"},"inLanguage":"pt-BR"},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/educacao\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/educacao\/","name":"Secretaria de Educa\u00e7\u00e3o","description":"Secretaria de Educa\u00e7\u00e3o da cidade de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/educacao\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/categories\/33"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.pmpf.rs.gov.br\/educacao\/wp-json\/wp\/v2\/posts?categories=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}