{"id":2223,"date":"2017-04-19T18:37:08","date_gmt":"2017-04-19T21:37:08","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/secretaria-de-cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/"},"modified":"2017-04-19T18:37:08","modified_gmt":"2017-04-19T21:37:08","slug":"prefeitura-apresenta-programacao-dos-160-anos","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/","title":{"rendered":"Prefeitura apresenta programa\u00e7\u00e3o dos 160 anos"},"content":{"rendered":"<p>Em 2017 Passo Fundo completa 160 anos. S\u00e3o hist\u00f3rias constru\u00eddas por muitas pessoas ao longo dos anos. Por isso, as comemora\u00e7\u00f5es est\u00e3o sendo planejadas desde o in\u00edcio do ano para seguir em todos os meses. Nessa quarta-feira (19) a Prefeitura de Passo Fundo apresentou os principais destaques da programa\u00e7\u00e3o do anivers\u00e1rio de 160 anos do munic\u00edpio e o aplicativo Viva Passo Fundo, ferramenta que ser\u00e1 usada para divulgar toda a programa\u00e7\u00e3o.<\/p>\n<p>Na presen\u00e7a dos profissionais dos ve\u00edculos de comunica\u00e7\u00e3o da cidade, o secret\u00e1rio de Cultura, Pedro Almeida, falou sobre a ideia. \u201cComo este \u00e9 um anivers\u00e1rio especial da cidade, pensamos numa abordagem diferente. O Viva Passo Fundo foi criado ainda no ano passado para reunir todas as informa\u00e7\u00f5es da cidade numa plataforma \u00fanica. Tanto visitantes ou turistas quanto a popula\u00e7\u00e3o podem consult\u00e1-lo para saber mais sobre Passo Fundo. \u00c9 um guia que traz informa\u00e7\u00f5es variadas, al\u00e9m de servir como agenda para a movimenta\u00e7\u00e3o cultural e de eventos que temos\u201d, explicou ele.<\/p>\n<p>Para o vice-prefeito Jo\u00e3o Pedro Nunes, a participa\u00e7\u00e3o da comunidade \u00e9 importante. \u201cA cidade foi constru\u00edda por muitos e por isso as pessoas devem tomar os espa\u00e7os e aproveitar o que ser\u00e1 oferecido. Essa programa\u00e7\u00e3o vem sendo constru\u00eddas com carinho e desde o in\u00edcio do ano\u201d, afirmou.<\/p>\n<p><b>O aplicativo<\/b><br \/>O Viva Passo Fundo surgiu, inicialmente, para proporcionar uma ferramenta atualizada com informa\u00e7\u00f5es do munic\u00edpio aos visitantes que aqui chegam. As informa\u00e7\u00f5es s\u00e3o de diversas \u00e1reas: tur\u00edstica, cultural, hist\u00f3rica, hotelaria, eventos, gastron\u00f4mica e utilidade p\u00fablica. Com a ferramenta pronta, a abordagem tamb\u00e9m passou a ser pensada para as pessoas que vivem em Passo Fundo, com\u00a0 divulga\u00e7\u00e3o de eventos, not\u00edcias sobre as a\u00e7\u00f5es da Prefeitura, link para o site das bicicletas compartilhadas, por exemplo. \u201cNo fim, todas as informa\u00e7\u00f5es disponibilizadas interessam n\u00e3o apenas quem n\u00e3o \u00e9 daqui, mas tamb\u00e9m os passo-fundenses que nasceram ou escolheram morar aqui e querem manter um di\u00e1logo mais pr\u00f3ximo com a cidade\u201d, ressaltou o secret\u00e1rio Pedro.<\/p>\n<p>Cabe destacar que o aplicativo conta com um canal de comunica\u00e7\u00e3o em que as pessoas podem enviar sugest\u00f5es e empresas podem entrar em contato para incluir seu conte\u00fado, como rede de hotel ou alimenta\u00e7\u00e3o e organiza\u00e7\u00e3o de eventos.<\/p>\n<p><b>As se\u00e7\u00f5es do aplicativo s\u00e3o:<\/b><br \/>Especial Programa\u00e7\u00e3o 160 anos: todos os eventos oficiais dos 160 anos estar\u00e3o cadastrados na se\u00e7\u00e3o.<br \/>A Cidade: informa\u00e7\u00f5es gerais sobre a Capital do Planalto M\u00e9dio e a Capital Nacional da Literatura com hist\u00f3ria e localiza\u00e7\u00e3o.<br \/>Agenda: todos os eventos que acontecem na cidade ser\u00e3o disponibilizados. <br \/>Pontos Tur\u00edsticos: localiza\u00e7\u00e3o com informa\u00e7\u00f5es e pontos pr\u00f3ximos.<br \/>Informa\u00e7\u00f5es \u00fateis: indica\u00e7\u00f5es de onde ficar, onde comer, comercial e telefones \u00fateis.<br \/>Not\u00edcias: s\u00e3o reproduzidas as not\u00edcias do site da Prefeitura de Passo Fundo com informa\u00e7\u00f5es institucionais e a\u00e7\u00f5es feitas em toda a cidade.<br \/>Bicicletas compartilhadas: link para o site do sistema.<br \/>Sobre: canal de comunica\u00e7\u00e3o.<\/p>\n<p>O aplicativo foi criado pela Prefeitura de Passo Fundo, atrav\u00e9s da Funda\u00e7\u00e3o Passo Fundo de Turismo (Passotur). O Viva Passo Fundo est\u00e1 dispon\u00edvel para IOS e Android.<\/p>\n<p><b>A programa\u00e7\u00e3o<\/b><br \/>Foram apresentados alguns dos principais eventos que ir\u00e3o acontecer neste ano, em comemora\u00e7\u00e3o aos 160 anos de Passo Fundo. <\/p>\n<p><b>Confira alguns dos eventos que ser\u00e3o realizados:<\/b><br \/>&#8211; Inaugura\u00e7\u00e3o da Arena do Instituto Hist\u00f3rico de Passo Fundo \u2013 IHPF (maio)<br \/>O IHPF passa a integrar o Espa\u00e7o Cultural Roseli Doleski Pretto. A arena ao ar livre est\u00e1 localizada dentro do p\u00e1trio interno do complexo.<br \/>&#8211; Concurso de Fotografia CLICK 160 (segundo semestre)<br \/>Com parceria com o Grupo da Foto, profissionais e amadores poder\u00e3o participar.<br \/>&#8211; Festival de M\u00fasica do Passo \u2013 Tema: Passo Fundo (julho)<br \/>Mais uma edi\u00e7\u00e3o do festival ir\u00e1 acontecer. Voltado para m\u00fasicos e compositores passo-fundenses.<br \/>&#8211; Semana de Passo Fundo em Porto Alegre (agosto)<br \/>Ser\u00e3o diversos eventos com o objetivo de mostrar as potencialidades de Passo Fundo para o Estado. Shows, exposi\u00e7\u00e3o na Assembleia Legislativa, teatro de rua, encontro dos passo-fundenses que moram na capital, jogo de v\u00f4lei especial, palestra, evento da Jornada em Porto Alegre, s\u00e3o alguns dos destaques.<br \/>&#8211; Mostra de Cinema: exibi\u00e7\u00e3o do filme Maverick (agosto)<br \/>O filme internacional que teve parte gravado em Passo Fundo serpa exibido para a comunidade em diferentes datas.<br \/>&#8211; Projeto Document\u00e1rios 160 anos (agosto)<br \/>Em parceia com o curso de Hist\u00f3ria e a UPF\/TV, ser\u00e1 realizada uma s\u00e9rie de document\u00e1rios que tratar\u00e3o do patrim\u00f4nio humano, da identidade e da mem\u00f3ria do munic\u00edpio.<br \/>&#8211; Primeira edi\u00e7\u00e3o do Pr\u00eamio Escritor Passo-Fundense (novembro)<br \/>Em ano de Jornada Nacional de Literatura, ser\u00e1 lan\u00e7ada a primeira edi\u00e7\u00e3o com premia\u00e7\u00e3o de 12 escritores em 4 categorias. O pr\u00eamio serpa bianual.<br \/>&#8211; Concurso para cria\u00e7\u00e3o do Hino Oficial do Munic\u00edpio de Passo Fundo (novembro)<br \/>A a\u00e7\u00e3o tem o objetivo de oficializar a cria\u00e7\u00e3o de um hino da cidade.<\/p>\n<p><b>Outros eventos:<br \/><\/b><br \/>F\u00f3rum dos Institutos Hist\u00f3ricos do Rio Grande do Sul (maio);<br \/>Reculuta Farroupilha (maio);<br \/>Edital das Artes Visuais \u2013 oito exposi\u00e7\u00f5es v\u00e3o circular em diferentes espa\u00e7os da cidade;<br \/>Funcultura \u2013 3\u00aa edi\u00e7\u00e3o;<br \/>Mostra da Cultura Ga\u00facha \u2013 Especial 160 anos;<br \/>Festival Canto Galponeiro (outubro);<br \/>Jornada Nacional de Literatura (02 a 06 de outubro);<br \/>Feira do Livro de Passo Fundo (novembro);<br \/>Encontro de Bandoneon (novembro);<br \/>Encontro dos Apaixonados por Vinil (novembro);<br \/>Festival de Corais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tamb\u00e9m foi apresentado o aplicativo Viva Passo Fundo, onde est\u00e3o todas as informa\u00e7\u00f5es<\/p>\n","protected":false},"author":1,"featured_media":2224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-2223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prefeitura apresenta programa\u00e7\u00e3o dos 160 anos - Secretaria de Cultura<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prefeitura apresenta programa\u00e7\u00e3o dos 160 anos - Secretaria de Cultura\" \/>\n<meta property=\"og:description\" content=\"Tamb\u00e9m foi apresentado o aplicativo Viva Passo Fundo, onde est\u00e3o todas as informa\u00e7\u00f5es\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/\" \/>\n<meta property=\"og:site_name\" content=\"Secretaria de Cultura\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-19T21:37:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-content\/uploads\/sites\/25\/2021\/12\/I2017-04-19_164707_385109.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1469\" \/>\n\t<meta property=\"og:image:height\" content=\"1005\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/\",\"name\":\"Prefeitura apresenta programa\u00e7\u00e3o dos 160 anos - Secretaria de Cultura\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/cultura\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-content\/uploads\/sites\/25\/2021\/12\/I2017-04-19_164707_385109.jpg\",\"datePublished\":\"2017-04-19T21:37:08+00:00\",\"dateModified\":\"2017-04-19T21:37:08+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/cultura\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/#primaryimage\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-content\/uploads\/sites\/25\/2021\/12\/I2017-04-19_164707_385109.jpg\",\"contentUrl\":\"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-content\/uploads\/sites\/25\/2021\/12\/I2017-04-19_164707_385109.jpg\",\"width\":1469,\"height\":1005},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/cultura\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/cultura\/\",\"name\":\"Secretaria de Cultura\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/cultura\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/cultura\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/cultura\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/cultura\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prefeitura apresenta programa\u00e7\u00e3o dos 160 anos - Secretaria de Cultura","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/","og_locale":"pt_BR","og_type":"article","og_title":"Prefeitura apresenta programa\u00e7\u00e3o dos 160 anos - Secretaria de Cultura","og_description":"Tamb\u00e9m foi apresentado o aplicativo Viva Passo Fundo, onde est\u00e3o todas as informa\u00e7\u00f5es","og_url":"https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/","og_site_name":"Secretaria de Cultura","article_published_time":"2017-04-19T21:37:08+00:00","og_image":[{"width":1469,"height":1005,"url":"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-content\/uploads\/sites\/25\/2021\/12\/I2017-04-19_164707_385109.jpg","type":"image\/jpeg"}],"author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/","url":"https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/","name":"Prefeitura apresenta programa\u00e7\u00e3o dos 160 anos - Secretaria de Cultura","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/cultura\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/#primaryimage"},"image":{"@id":"https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-content\/uploads\/sites\/25\/2021\/12\/I2017-04-19_164707_385109.jpg","datePublished":"2017-04-19T21:37:08+00:00","dateModified":"2017-04-19T21:37:08+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/cultura\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/cultura\/2017\/04\/19\/prefeitura-apresenta-programacao-dos-160-anos\/#primaryimage","url":"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-content\/uploads\/sites\/25\/2021\/12\/I2017-04-19_164707_385109.jpg","contentUrl":"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-content\/uploads\/sites\/25\/2021\/12\/I2017-04-19_164707_385109.jpg","width":1469,"height":1005},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/cultura\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/cultura\/","name":"Secretaria de Cultura","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/cultura\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/cultura\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/cultura\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/cultura\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-json\/wp\/v2\/posts\/2223"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-json\/wp\/v2\/comments?post=2223"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-json\/wp\/v2\/posts\/2223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-json\/wp\/v2\/media\/2224"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-json\/wp\/v2\/media?parent=2223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-json\/wp\/v2\/categories?post=2223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/cultura\/wp-json\/wp\/v2\/tags?post=2223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}