{"id":467,"date":"2010-05-28T03:00:00","date_gmt":"2010-05-28T06:00:00","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2010\/05\/28\/conselho-do-meio-ambiente-reune-se-extraordinariamente\/"},"modified":"2010-05-28T03:00:00","modified_gmt":"2010-05-28T06:00:00","slug":"conselho-do-meio-ambiente-reune-se-extraordinariamente","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2010\/05\/28\/conselho-do-meio-ambiente-reune-se-extraordinariamente\/","title":{"rendered":"Conselho do Meio Ambiente re\u00fane-se extraordinariamente"},"content":{"rendered":"<p><span style=\"\"><\/span><span style=\"\">Dois projetos foram aprovados por unanimidade, no Conselho do Meio Ambiente, em reuni\u00e3o extraordin\u00e1ria, realizada nesta quinta-feira. Conforme o presidente da entidade e secret\u00e1rio de Meio Ambiente, Cl\u00f3vis Alves, o primeiro projeto discutido abordou um conv\u00eanio entre a Associa\u00e7\u00e3o Recibela (Associa\u00e7\u00e3o de Recicladores do Parque Bela Vista) e a C\u00e1ritas Diocesana, para a opera\u00e7\u00e3o da esteira de triagem do aterro municipal. O conv\u00eanio visa repassar as atividades de triagem do lixo encaminhado ao aterro para uma associa\u00e7\u00e3o sem fins lucrativos.<\/span><br style=\"\" \/><span style=\"\">O objetivo, afirmou, \u00e9 otimizar o uso da c\u00e9lula do aterro a fim de n\u00e3o satur\u00e1-la. Visando a preserva\u00e7\u00e3o ambiental e contemplando a quest\u00e3o social, pois estar\u00e3o envolvidos neste projeto cinq\u00fcenta oper\u00e1rios que ir\u00e3o fazer a triagem.<\/span><br style=\"\" \/><span style=\"\">Os oper\u00e1rios,\u00a0 at\u00e9 ent\u00e3o trabalhavam nas ruas de forma aut\u00f4noma. Com a aprova\u00e7\u00e3o do conv\u00eanio, passam a trabalhar em local fechado uniformizados, com equipamento de prote\u00e7\u00e3o individual. Tamb\u00e9m ser\u00e3o treinados. Entende o secret\u00e1rio que os oper\u00e1rios ganhar\u00e3o al\u00e9m de dignidade no seu trabalho, o valor agregado ao material que ser\u00e1 vendido e dividido entre os trabalhadores.<\/span><br style=\"\" \/><span style=\"\">O segundo item da pauta foi apresenta\u00e7\u00e3o e aprova\u00e7\u00e3o de um documento de apoio a cria\u00e7\u00e3o e reconhecimento da Reserva Particular do Patrim\u00f4nio Natural da Escola Redentorista Menino Deus (RPPNM).<\/span><br style=\"\" \/><span style=\"\">O reconhecimento da \u00e1rea como RPPN municipal depende de um decreto a ser assinado pelo Prefeito Airton Dipp.<\/span><br style=\"\" \/><span style=\"\">\u00a0Explica Alves, que a Lei 4.561 de 16-01-2009 habilita os munic\u00edpios a reconhecerem as RPPNs. A\u00a0 documenta\u00e7\u00e3o est\u00e1 pronta, para que a de Passo Fundo tenha o status de ser a primeira reserva a ser reconhecida pelo munic\u00edpio no Rio Grande do Sul.\u00a0 Outras 25 reservas existentes no Estado foram reconhecidas pelo Instituto Chico Mendes \u2013 do Ibama.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conselho do Meio Ambiente re\u00fane-se extraordinariamente<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-467","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conselho do Meio Ambiente re\u00fane-se extraordinariamente - Conselhos Municipais de Passo Fundo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2010\/05\/28\/conselho-do-meio-ambiente-reune-se-extraordinariamente\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conselho do Meio Ambiente re\u00fane-se extraordinariamente - Conselhos Municipais de Passo Fundo\" \/>\n<meta property=\"og:description\" content=\"Conselho do Meio Ambiente re\u00fane-se extraordinariamente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2010\/05\/28\/conselho-do-meio-ambiente-reune-se-extraordinariamente\/\" \/>\n<meta property=\"og:site_name\" content=\"Conselhos Municipais de Passo Fundo\" \/>\n<meta property=\"article:published_time\" content=\"2010-05-28T06:00:00+00:00\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2010\/05\/28\/conselho-do-meio-ambiente-reune-se-extraordinariamente\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2010\/05\/28\/conselho-do-meio-ambiente-reune-se-extraordinariamente\/\",\"name\":\"Conselho do Meio Ambiente re\u00fane-se extraordinariamente - Conselhos Municipais de Passo Fundo\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#website\"},\"datePublished\":\"2010-05-28T06:00:00+00:00\",\"dateModified\":\"2010-05-28T06:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2010\/05\/28\/conselho-do-meio-ambiente-reune-se-extraordinariamente\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/\",\"name\":\"Conselhos Municipais de Passo Fundo\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conselho do Meio Ambiente re\u00fane-se extraordinariamente - Conselhos Municipais de Passo Fundo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2010\/05\/28\/conselho-do-meio-ambiente-reune-se-extraordinariamente\/","og_locale":"pt_BR","og_type":"article","og_title":"Conselho do Meio Ambiente re\u00fane-se extraordinariamente - Conselhos Municipais de Passo Fundo","og_description":"Conselho do Meio Ambiente re\u00fane-se extraordinariamente","og_url":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2010\/05\/28\/conselho-do-meio-ambiente-reune-se-extraordinariamente\/","og_site_name":"Conselhos Municipais de Passo Fundo","article_published_time":"2010-05-28T06:00:00+00:00","author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2010\/05\/28\/conselho-do-meio-ambiente-reune-se-extraordinariamente\/","url":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2010\/05\/28\/conselho-do-meio-ambiente-reune-se-extraordinariamente\/","name":"Conselho do Meio Ambiente re\u00fane-se extraordinariamente - Conselhos Municipais de Passo Fundo","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#website"},"datePublished":"2010-05-28T06:00:00+00:00","dateModified":"2010-05-28T06:00:00+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2010\/05\/28\/conselho-do-meio-ambiente-reune-se-extraordinariamente\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/","name":"Conselhos Municipais de Passo Fundo","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/posts\/467"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/comments?post=467"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/posts\/467\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/media?parent=467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/categories?post=467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/tags?post=467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}