{"id":444,"date":"2015-04-16T03:00:00","date_gmt":"2015-04-16T06:00:00","guid":{"rendered":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2015\/04\/16\/conselhao-discutira-utilizacao-do-parque-da-efrica\/"},"modified":"2015-04-16T03:00:00","modified_gmt":"2015-04-16T06:00:00","slug":"conselhao-discutira-utilizacao-do-parque-da-efrica","status":"publish","type":"post","link":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2015\/04\/16\/conselhao-discutira-utilizacao-do-parque-da-efrica\/","title":{"rendered":"Conselh\u00e3o discutir\u00e1 utiliza\u00e7\u00e3o do Parque da EFRICA"},"content":{"rendered":"<div align=\"justify\"><span style=\"font-variant: normal;\"><span style=\"font-style: normal;\"><span style=\"font-weight: normal;\">O Conselho de Desenvolvimento Econ\u00f4mico e Social de Passo Fundo (CDES-PF), o Conselh\u00e3o, formado por conselheiros governamentais e n\u00e3o-governamentais, se reunir\u00e1 n<\/span><\/span><\/span><span style=\"font-variant: normal;\"><span style=\"font-style: normal;\"><span style=\"font-weight: normal;\">este s\u00e1bado (18), <\/span><\/span><\/span><span style=\"font-variant: normal;\"><span style=\"font-style: normal;\"><span style=\"font-weight: normal;\">\u00e0s 8h30min, no Anfiteatro da Faculdade de Medicina da Universidade de Passo Fundo (UPF) \u2013 Campus II, para definir a forma de utiliza\u00e7\u00e3o do Parque de Exposi\u00e7\u00f5es Wolmar Salton (EFRICA).<\/span><\/span><\/span> <\/div>\n<p align=\"justify\" style=\"font-variant: normal; font-style: normal; font-weight: normal;\"> O assunto j\u00e1 foi debatido pelo Conselho Municipal de Administra\u00e7\u00e3o do Parque, composto pelo Sindicato Rural de Passo Fundo, ACISA e Prefeitura, onde foi apresentada a possibilidade da utiliza\u00e7\u00e3o pela administra\u00e7\u00e3o municipal ou o seguimento do mesmo processo realizado com o Gin\u00e1sio Teixeirinha, que foi concedido para a iniciativa privada, por meio de edital de concess\u00e3o e explora\u00e7\u00e3o de uso de vinte anos ao Sport Clube Ga\u00facho.<\/p>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"font-variant: normal; font-style: normal; font-weight: normal;\"> A C\u00e2mara tem\u00e1tica abordar\u00e1 o tema \u201cA busca de uma solu\u00e7\u00e3o para a situa\u00e7\u00e3o do Parque Wolmar Salton\u201d. Os conselheiros tentar\u00e3o colaborar coletivamente para apontar o caminho para o Executivo na resolu\u00e7\u00e3o desta quest\u00e3o\u201d, disse o secret\u00e1rio-executivo da CDES-PF, Ginez Leopoldo de Campos.<\/p>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"font-variant: normal; font-style: normal; font-weight: normal;\"> Conforme Ginez, os membros do Conselh\u00e3o e do Conselho Municipal de Administra\u00e7\u00e3o do Parque Wolmar Salton dever\u00e3o definir uma data para realizar uma visita t\u00e9cnica ao parque, a fim de verificar as atuais condi\u00e7\u00f5es de estrutura do espa\u00e7o, os poss\u00edveis investimento para recupera\u00e7\u00e3o e, ap\u00f3s definir em assembleia, o destino do local.<\/p>\n<div align=\"justify\"> <\/div>\n<p align=\"justify\" style=\"font-variant: normal; font-style: normal; font-weight: normal;\">\n<div align=\"justify\"> <\/div>\n<p align=\"justify\">\n","protected":false},"excerpt":{"rendered":"<p>Conselh\u00e3o discutir\u00e1 utiliza\u00e7\u00e3o do Parque da EFRICA<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[],"tags":[],"class_list":["post-444","post","type-post","status-publish","format-standard","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conselh\u00e3o discutir\u00e1 utiliza\u00e7\u00e3o do Parque da EFRICA - Conselhos Municipais de Passo Fundo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2015\/04\/16\/conselhao-discutira-utilizacao-do-parque-da-efrica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conselh\u00e3o discutir\u00e1 utiliza\u00e7\u00e3o do Parque da EFRICA - Conselhos Municipais de Passo Fundo\" \/>\n<meta property=\"og:description\" content=\"Conselh\u00e3o discutir\u00e1 utiliza\u00e7\u00e3o do Parque da EFRICA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2015\/04\/16\/conselhao-discutira-utilizacao-do-parque-da-efrica\/\" \/>\n<meta property=\"og:site_name\" content=\"Conselhos Municipais de Passo Fundo\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-16T06:00:00+00:00\" \/>\n<meta name=\"author\" content=\"mosite\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mosite\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2015\/04\/16\/conselhao-discutira-utilizacao-do-parque-da-efrica\/\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2015\/04\/16\/conselhao-discutira-utilizacao-do-parque-da-efrica\/\",\"name\":\"Conselh\u00e3o discutir\u00e1 utiliza\u00e7\u00e3o do Parque da EFRICA - Conselhos Municipais de Passo Fundo\",\"isPartOf\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#website\"},\"datePublished\":\"2015-04-16T06:00:00+00:00\",\"dateModified\":\"2015-04-16T06:00:00+00:00\",\"author\":{\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2015\/04\/16\/conselhao-discutira-utilizacao-do-parque-da-efrica\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#website\",\"url\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/\",\"name\":\"Conselhos Municipais de Passo Fundo\",\"description\":\"S\u00f3 mais um site Prefeitura de Passo Fundo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7\",\"name\":\"mosite\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g\",\"caption\":\"mosite\"},\"sameAs\":[\"http:\/\/example.com\"],\"url\":\"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/author\/mosite\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conselh\u00e3o discutir\u00e1 utiliza\u00e7\u00e3o do Parque da EFRICA - Conselhos Municipais de Passo Fundo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2015\/04\/16\/conselhao-discutira-utilizacao-do-parque-da-efrica\/","og_locale":"pt_BR","og_type":"article","og_title":"Conselh\u00e3o discutir\u00e1 utiliza\u00e7\u00e3o do Parque da EFRICA - Conselhos Municipais de Passo Fundo","og_description":"Conselh\u00e3o discutir\u00e1 utiliza\u00e7\u00e3o do Parque da EFRICA","og_url":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2015\/04\/16\/conselhao-discutira-utilizacao-do-parque-da-efrica\/","og_site_name":"Conselhos Municipais de Passo Fundo","article_published_time":"2015-04-16T06:00:00+00:00","author":"mosite","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mosite","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2015\/04\/16\/conselhao-discutira-utilizacao-do-parque-da-efrica\/","url":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2015\/04\/16\/conselhao-discutira-utilizacao-do-parque-da-efrica\/","name":"Conselh\u00e3o discutir\u00e1 utiliza\u00e7\u00e3o do Parque da EFRICA - Conselhos Municipais de Passo Fundo","isPartOf":{"@id":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#website"},"datePublished":"2015-04-16T06:00:00+00:00","dateModified":"2015-04-16T06:00:00+00:00","author":{"@id":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/2015\/04\/16\/conselhao-discutira-utilizacao-do-parque-da-efrica\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#website","url":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/","name":"Conselhos Municipais de Passo Fundo","description":"S\u00f3 mais um site Prefeitura de Passo Fundo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#\/schema\/person\/0c355b0fa68a7aa986c8594f7a60a2d7","name":"mosite","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63d72595d6cecfe12bd8a94829d5a26c?s=96&d=mm&r=g","caption":"mosite"},"sameAs":["http:\/\/example.com"],"url":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/author\/mosite\/"}]}},"_links":{"self":[{"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/posts\/444"}],"collection":[{"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/comments?post=444"}],"version-history":[{"count":0,"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/posts\/444\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/media?parent=444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/categories?post=444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pmpf.rs.gov.br\/conselhos-municipais-de-passo-fundo\/wp-json\/wp\/v2\/tags?post=444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}